{"id":2723,"date":"2024-03-29T14:55:33","date_gmt":"2024-03-29T07:55:33","guid":{"rendered":"https:\/\/www.dmr.go.th\/Fossil_Management_Fund\/?p=2723"},"modified":"2024-03-29T14:55:35","modified_gmt":"2024-03-29T07:55:35","slug":"%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b8%8a%e0%b8%b8%e0%b8%a1%e0%b8%84%e0%b8%93%e0%b8%b0%e0%b8%81%e0%b8%a3%e0%b8%a3%e0%b8%a1%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%9a%e0%b8%a3%e0%b8%b4%e0%b8%ab%e0%b8%b2%e0%b8%a3%e0%b8%81%e0%b8%ad%e0%b8%87%e0%b8%97%e0%b8%b8%e0%b8%99%e0%b8%88%e0%b8%b1%e0%b8%94%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%8b%e0%b8%b2%e0%b8%81%e0%b8%94%e0%b8%b6%e0%b8%81%e0%b8%94%e0%b8%b3%e0%b8%9a%e0%b8%a3%e0%b8%a3%e0%b8%9e%e0%b9%8c-%e0%b8%84%e0%b8%a3%e0%b8%b1%e0%b9%89%e0%b8%87%e0%b8%97%e0%b8%b5%e0%b9%88-2-2567","status":"publish","type":"post","link":"https:\/\/www.dmr.go.th\/Fossil_Management_Fund\/2024\/03\/29\/%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b8%8a%e0%b8%b8%e0%b8%a1%e0%b8%84%e0%b8%93%e0%b8%b0%e0%b8%81%e0%b8%a3%e0%b8%a3%e0%b8%a1%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%9a%e0%b8%a3%e0%b8%b4%e0%b8%ab%e0%b8%b2%e0%b8%a3%e0%b8%81%e0%b8%ad%e0%b8%87%e0%b8%97%e0%b8%b8%e0%b8%99%e0%b8%88%e0%b8%b1%e0%b8%94%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%8b%e0%b8%b2%e0%b8%81%e0%b8%94%e0%b8%b6%e0%b8%81%e0%b8%94%e0%b8%b3%e0%b8%9a%e0%b8%a3%e0%b8%a3%e0%b8%9e%e0%b9%8c-%e0%b8%84%e0%b8%a3%e0%b8%b1%e0%b9%89%e0%b8%87%e0%b8%97%e0%b8%b5%e0%b9%88-2-2567\/","title":{"rendered":"\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e04\u0e13\u0e30\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e01\u0e2d\u0e07\u0e17\u0e38\u0e19\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e0b\u0e32\u0e01\u0e14\u0e36\u0e01\u0e14\u0e33\u0e1a\u0e23\u0e23\u0e1e\u0e4c \u0e04\u0e23\u0e31\u0e49\u0e07\u0e17\u0e35\u0e48 2\/2567"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":4,"featured_media":2722,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[35],"tags":[],"class_list":["post-2723","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-one-page"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v20.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e04\u0e13\u0e30\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e01\u0e2d\u0e07\u0e17\u0e38\u0e19\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e0b\u0e32\u0e01\u0e14\u0e36\u0e01\u0e14\u0e33\u0e1a\u0e23\u0e23\u0e1e\u0e4c \u0e04\u0e23\u0e31\u0e49\u0e07\u0e17\u0e35\u0e48 2\/2567 - \u0e01\u0e2d\u0e07\u0e17\u0e38\u0e19\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e0b\u0e32\u0e01\u0e14\u0e36\u0e01\u0e14\u0e33\u0e1a\u0e23\u0e23\u0e1e\u0e4c<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.dmr.go.th\/Fossil_Management_Fund\/2024\/03\/29\/\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e04\u0e13\u0e30\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e01\u0e2d\u0e07\u0e17\u0e38\u0e19\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e0b\u0e32\u0e01\u0e14\u0e36\u0e01\u0e14\u0e33\u0e1a\u0e23\u0e23\u0e1e\u0e4c-\u0e04\u0e23\u0e31\u0e49\u0e07\u0e17\u0e35\u0e48-2-2567\/\" \/>\n<meta property=\"og:locale\" content=\"th_TH\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e04\u0e13\u0e30\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e01\u0e2d\u0e07\u0e17\u0e38\u0e19\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e0b\u0e32\u0e01\u0e14\u0e36\u0e01\u0e14\u0e33\u0e1a\u0e23\u0e23\u0e1e\u0e4c \u0e04\u0e23\u0e31\u0e49\u0e07\u0e17\u0e35\u0e48 2\/2567 - \u0e01\u0e2d\u0e07\u0e17\u0e38\u0e19\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e0b\u0e32\u0e01\u0e14\u0e36\u0e01\u0e14\u0e33\u0e1a\u0e23\u0e23\u0e1e\u0e4c\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.dmr.go.th\/Fossil_Management_Fund\/2024\/03\/29\/\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e04\u0e13\u0e30\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e01\u0e2d\u0e07\u0e17\u0e38\u0e19\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e0b\u0e32\u0e01\u0e14\u0e36\u0e01\u0e14\u0e33\u0e1a\u0e23\u0e23\u0e1e\u0e4c-\u0e04\u0e23\u0e31\u0e49\u0e07\u0e17\u0e35\u0e48-2-2567\/\" \/>\n<meta property=\"og:site_name\" content=\"\u0e01\u0e2d\u0e07\u0e17\u0e38\u0e19\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e0b\u0e32\u0e01\u0e14\u0e36\u0e01\u0e14\u0e33\u0e1a\u0e23\u0e23\u0e1e\u0e4c\" \/>\n<meta property=\"article:published_time\" content=\"2024-03-29T07:55:33+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-03-29T07:55:35+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.dmr.go.th\/Fossil_Management_Fund\/wp-content\/uploads\/2024\/03\/one-page.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"724\" \/>\n\t<meta property=\"og:image:height\" content=\"1024\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"\u0e01\u0e2d\u0e07\u0e17\u0e38\u0e19\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e0b\u0e32\u0e01\u0e14\u0e36\u0e01\u0e14\u0e33\u0e1a\u0e23\u0e23\u0e1e\u0e4c2\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"\u0e01\u0e2d\u0e07\u0e17\u0e38\u0e19\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e0b\u0e32\u0e01\u0e14\u0e36\u0e01\u0e14\u0e33\u0e1a\u0e23\u0e23\u0e1e\u0e4c2\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.dmr.go.th\/Fossil_Management_Fund\/2024\/03\/29\/%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b8%8a%e0%b8%b8%e0%b8%a1%e0%b8%84%e0%b8%93%e0%b8%b0%e0%b8%81%e0%b8%a3%e0%b8%a3%e0%b8%a1%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%9a%e0%b8%a3%e0%b8%b4%e0%b8%ab%e0%b8%b2%e0%b8%a3%e0%b8%81%e0%b8%ad%e0%b8%87%e0%b8%97%e0%b8%b8%e0%b8%99%e0%b8%88%e0%b8%b1%e0%b8%94%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%8b%e0%b8%b2%e0%b8%81%e0%b8%94%e0%b8%b6%e0%b8%81%e0%b8%94%e0%b8%b3%e0%b8%9a%e0%b8%a3%e0%b8%a3%e0%b8%9e%e0%b9%8c-%e0%b8%84%e0%b8%a3%e0%b8%b1%e0%b9%89%e0%b8%87%e0%b8%97%e0%b8%b5%e0%b9%88-2-2567\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.dmr.go.th\/Fossil_Management_Fund\/2024\/03\/29\/%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b8%8a%e0%b8%b8%e0%b8%a1%e0%b8%84%e0%b8%93%e0%b8%b0%e0%b8%81%e0%b8%a3%e0%b8%a3%e0%b8%a1%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%9a%e0%b8%a3%e0%b8%b4%e0%b8%ab%e0%b8%b2%e0%b8%a3%e0%b8%81%e0%b8%ad%e0%b8%87%e0%b8%97%e0%b8%b8%e0%b8%99%e0%b8%88%e0%b8%b1%e0%b8%94%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%8b%e0%b8%b2%e0%b8%81%e0%b8%94%e0%b8%b6%e0%b8%81%e0%b8%94%e0%b8%b3%e0%b8%9a%e0%b8%a3%e0%b8%a3%e0%b8%9e%e0%b9%8c-%e0%b8%84%e0%b8%a3%e0%b8%b1%e0%b9%89%e0%b8%87%e0%b8%97%e0%b8%b5%e0%b9%88-2-2567\/\"},\"author\":{\"name\":\"\u0e01\u0e2d\u0e07\u0e17\u0e38\u0e19\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e0b\u0e32\u0e01\u0e14\u0e36\u0e01\u0e14\u0e33\u0e1a\u0e23\u0e23\u0e1e\u0e4c2\",\"@id\":\"https:\/\/www.dmr.go.th\/Fossil_Management_Fund\/#\/schema\/person\/dd92d597814b0847d736458be9549f3f\"},\"headline\":\"\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e04\u0e13\u0e30\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e01\u0e2d\u0e07\u0e17\u0e38\u0e19\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e0b\u0e32\u0e01\u0e14\u0e36\u0e01\u0e14\u0e33\u0e1a\u0e23\u0e23\u0e1e\u0e4c \u0e04\u0e23\u0e31\u0e49\u0e07\u0e17\u0e35\u0e48 2\/2567\",\"datePublished\":\"2024-03-29T07:55:33+00:00\",\"dateModified\":\"2024-03-29T07:55:35+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.dmr.go.th\/Fossil_Management_Fund\/2024\/03\/29\/%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b8%8a%e0%b8%b8%e0%b8%a1%e0%b8%84%e0%b8%93%e0%b8%b0%e0%b8%81%e0%b8%a3%e0%b8%a3%e0%b8%a1%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%9a%e0%b8%a3%e0%b8%b4%e0%b8%ab%e0%b8%b2%e0%b8%a3%e0%b8%81%e0%b8%ad%e0%b8%87%e0%b8%97%e0%b8%b8%e0%b8%99%e0%b8%88%e0%b8%b1%e0%b8%94%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%8b%e0%b8%b2%e0%b8%81%e0%b8%94%e0%b8%b6%e0%b8%81%e0%b8%94%e0%b8%b3%e0%b8%9a%e0%b8%a3%e0%b8%a3%e0%b8%9e%e0%b9%8c-%e0%b8%84%e0%b8%a3%e0%b8%b1%e0%b9%89%e0%b8%87%e0%b8%97%e0%b8%b5%e0%b9%88-2-2567\/\"},\"wordCount\":0,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.dmr.go.th\/Fossil_Management_Fund\/#organization\"},\"articleSection\":[\"One Page\"],\"inLanguage\":\"th\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.dmr.go.th\/Fossil_Management_Fund\/2024\/03\/29\/%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b8%8a%e0%b8%b8%e0%b8%a1%e0%b8%84%e0%b8%93%e0%b8%b0%e0%b8%81%e0%b8%a3%e0%b8%a3%e0%b8%a1%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%9a%e0%b8%a3%e0%b8%b4%e0%b8%ab%e0%b8%b2%e0%b8%a3%e0%b8%81%e0%b8%ad%e0%b8%87%e0%b8%97%e0%b8%b8%e0%b8%99%e0%b8%88%e0%b8%b1%e0%b8%94%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%8b%e0%b8%b2%e0%b8%81%e0%b8%94%e0%b8%b6%e0%b8%81%e0%b8%94%e0%b8%b3%e0%b8%9a%e0%b8%a3%e0%b8%a3%e0%b8%9e%e0%b9%8c-%e0%b8%84%e0%b8%a3%e0%b8%b1%e0%b9%89%e0%b8%87%e0%b8%97%e0%b8%b5%e0%b9%88-2-2567\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.dmr.go.th\/Fossil_Management_Fund\/2024\/03\/29\/%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b8%8a%e0%b8%b8%e0%b8%a1%e0%b8%84%e0%b8%93%e0%b8%b0%e0%b8%81%e0%b8%a3%e0%b8%a3%e0%b8%a1%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%9a%e0%b8%a3%e0%b8%b4%e0%b8%ab%e0%b8%b2%e0%b8%a3%e0%b8%81%e0%b8%ad%e0%b8%87%e0%b8%97%e0%b8%b8%e0%b8%99%e0%b8%88%e0%b8%b1%e0%b8%94%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%8b%e0%b8%b2%e0%b8%81%e0%b8%94%e0%b8%b6%e0%b8%81%e0%b8%94%e0%b8%b3%e0%b8%9a%e0%b8%a3%e0%b8%a3%e0%b8%9e%e0%b9%8c-%e0%b8%84%e0%b8%a3%e0%b8%b1%e0%b9%89%e0%b8%87%e0%b8%97%e0%b8%b5%e0%b9%88-2-2567\/\",\"url\":\"https:\/\/www.dmr.go.th\/Fossil_Management_Fund\/2024\/03\/29\/%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b8%8a%e0%b8%b8%e0%b8%a1%e0%b8%84%e0%b8%93%e0%b8%b0%e0%b8%81%e0%b8%a3%e0%b8%a3%e0%b8%a1%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%9a%e0%b8%a3%e0%b8%b4%e0%b8%ab%e0%b8%b2%e0%b8%a3%e0%b8%81%e0%b8%ad%e0%b8%87%e0%b8%97%e0%b8%b8%e0%b8%99%e0%b8%88%e0%b8%b1%e0%b8%94%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%8b%e0%b8%b2%e0%b8%81%e0%b8%94%e0%b8%b6%e0%b8%81%e0%b8%94%e0%b8%b3%e0%b8%9a%e0%b8%a3%e0%b8%a3%e0%b8%9e%e0%b9%8c-%e0%b8%84%e0%b8%a3%e0%b8%b1%e0%b9%89%e0%b8%87%e0%b8%97%e0%b8%b5%e0%b9%88-2-2567\/\",\"name\":\"\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e04\u0e13\u0e30\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e01\u0e2d\u0e07\u0e17\u0e38\u0e19\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e0b\u0e32\u0e01\u0e14\u0e36\u0e01\u0e14\u0e33\u0e1a\u0e23\u0e23\u0e1e\u0e4c \u0e04\u0e23\u0e31\u0e49\u0e07\u0e17\u0e35\u0e48 2\/2567 - \u0e01\u0e2d\u0e07\u0e17\u0e38\u0e19\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e0b\u0e32\u0e01\u0e14\u0e36\u0e01\u0e14\u0e33\u0e1a\u0e23\u0e23\u0e1e\u0e4c\",\"isPartOf\":{\"@id\":\"https:\/\/www.dmr.go.th\/Fossil_Management_Fund\/#website\"},\"datePublished\":\"2024-03-29T07:55:33+00:00\",\"dateModified\":\"2024-03-29T07:55:35+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.dmr.go.th\/Fossil_Management_Fund\/2024\/03\/29\/%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b8%8a%e0%b8%b8%e0%b8%a1%e0%b8%84%e0%b8%93%e0%b8%b0%e0%b8%81%e0%b8%a3%e0%b8%a3%e0%b8%a1%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%9a%e0%b8%a3%e0%b8%b4%e0%b8%ab%e0%b8%b2%e0%b8%a3%e0%b8%81%e0%b8%ad%e0%b8%87%e0%b8%97%e0%b8%b8%e0%b8%99%e0%b8%88%e0%b8%b1%e0%b8%94%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%8b%e0%b8%b2%e0%b8%81%e0%b8%94%e0%b8%b6%e0%b8%81%e0%b8%94%e0%b8%b3%e0%b8%9a%e0%b8%a3%e0%b8%a3%e0%b8%9e%e0%b9%8c-%e0%b8%84%e0%b8%a3%e0%b8%b1%e0%b9%89%e0%b8%87%e0%b8%97%e0%b8%b5%e0%b9%88-2-2567\/#breadcrumb\"},\"inLanguage\":\"th\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.dmr.go.th\/Fossil_Management_Fund\/2024\/03\/29\/%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b8%8a%e0%b8%b8%e0%b8%a1%e0%b8%84%e0%b8%93%e0%b8%b0%e0%b8%81%e0%b8%a3%e0%b8%a3%e0%b8%a1%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%9a%e0%b8%a3%e0%b8%b4%e0%b8%ab%e0%b8%b2%e0%b8%a3%e0%b8%81%e0%b8%ad%e0%b8%87%e0%b8%97%e0%b8%b8%e0%b8%99%e0%b8%88%e0%b8%b1%e0%b8%94%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%8b%e0%b8%b2%e0%b8%81%e0%b8%94%e0%b8%b6%e0%b8%81%e0%b8%94%e0%b8%b3%e0%b8%9a%e0%b8%a3%e0%b8%a3%e0%b8%9e%e0%b9%8c-%e0%b8%84%e0%b8%a3%e0%b8%b1%e0%b9%89%e0%b8%87%e0%b8%97%e0%b8%b5%e0%b9%88-2-2567\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.dmr.go.th\/Fossil_Management_Fund\/2024\/03\/29\/%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b8%8a%e0%b8%b8%e0%b8%a1%e0%b8%84%e0%b8%93%e0%b8%b0%e0%b8%81%e0%b8%a3%e0%b8%a3%e0%b8%a1%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%9a%e0%b8%a3%e0%b8%b4%e0%b8%ab%e0%b8%b2%e0%b8%a3%e0%b8%81%e0%b8%ad%e0%b8%87%e0%b8%97%e0%b8%b8%e0%b8%99%e0%b8%88%e0%b8%b1%e0%b8%94%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%8b%e0%b8%b2%e0%b8%81%e0%b8%94%e0%b8%b6%e0%b8%81%e0%b8%94%e0%b8%b3%e0%b8%9a%e0%b8%a3%e0%b8%a3%e0%b8%9e%e0%b9%8c-%e0%b8%84%e0%b8%a3%e0%b8%b1%e0%b9%89%e0%b8%87%e0%b8%97%e0%b8%b5%e0%b9%88-2-2567\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.dmr.go.th\/Fossil_Management_Fund\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e04\u0e13\u0e30\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e01\u0e2d\u0e07\u0e17\u0e38\u0e19\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e0b\u0e32\u0e01\u0e14\u0e36\u0e01\u0e14\u0e33\u0e1a\u0e23\u0e23\u0e1e\u0e4c \u0e04\u0e23\u0e31\u0e49\u0e07\u0e17\u0e35\u0e48 2\/2567\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.dmr.go.th\/Fossil_Management_Fund\/#website\",\"url\":\"https:\/\/www.dmr.go.th\/Fossil_Management_Fund\/\",\"name\":\"\u0e01\u0e2d\u0e07\u0e17\u0e38\u0e19\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e0b\u0e32\u0e01\u0e14\u0e36\u0e01\u0e14\u0e33\u0e1a\u0e23\u0e23\u0e1e\u0e4c\",\"description\":\"\u0e01\u0e2d\u0e07\u0e17\u0e38\u0e19\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e0b\u0e32\u0e01\u0e14\u0e36\u0e01\u0e14\u0e33\u0e1a\u0e23\u0e23\u0e1e\u0e4c\",\"publisher\":{\"@id\":\"https:\/\/www.dmr.go.th\/Fossil_Management_Fund\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.dmr.go.th\/Fossil_Management_Fund\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"th\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.dmr.go.th\/Fossil_Management_Fund\/#organization\",\"name\":\"\u0e01\u0e2d\u0e07\u0e17\u0e38\u0e19\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e0b\u0e32\u0e01\u0e14\u0e36\u0e01\u0e14\u0e33\u0e1a\u0e23\u0e23\u0e1e\u0e4c\",\"url\":\"https:\/\/www.dmr.go.th\/Fossil_Management_Fund\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"th\",\"@id\":\"https:\/\/www.dmr.go.th\/Fossil_Management_Fund\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.dmr.go.th\/Fossil_Management_Fund\/wp-content\/uploads\/2022\/12\/logo-PhotoRoom-1.png\",\"contentUrl\":\"https:\/\/www.dmr.go.th\/Fossil_Management_Fund\/wp-content\/uploads\/2022\/12\/logo-PhotoRoom-1.png\",\"width\":373,\"height\":373,\"caption\":\"\u0e01\u0e2d\u0e07\u0e17\u0e38\u0e19\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e0b\u0e32\u0e01\u0e14\u0e36\u0e01\u0e14\u0e33\u0e1a\u0e23\u0e23\u0e1e\u0e4c\"},\"image\":{\"@id\":\"https:\/\/www.dmr.go.th\/Fossil_Management_Fund\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.dmr.go.th\/Fossil_Management_Fund\/#\/schema\/person\/dd92d597814b0847d736458be9549f3f\",\"name\":\"\u0e01\u0e2d\u0e07\u0e17\u0e38\u0e19\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e0b\u0e32\u0e01\u0e14\u0e36\u0e01\u0e14\u0e33\u0e1a\u0e23\u0e23\u0e1e\u0e4c2\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"th\",\"@id\":\"https:\/\/www.dmr.go.th\/Fossil_Management_Fund\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/714bdb8637eb5704058efecbc3e49f852fb656e6066bc6014cff6a158890a999?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/714bdb8637eb5704058efecbc3e49f852fb656e6066bc6014cff6a158890a999?s=96&d=mm&r=g\",\"caption\":\"\u0e01\u0e2d\u0e07\u0e17\u0e38\u0e19\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e0b\u0e32\u0e01\u0e14\u0e36\u0e01\u0e14\u0e33\u0e1a\u0e23\u0e23\u0e1e\u0e4c2\"},\"url\":\"https:\/\/www.dmr.go.th\/Fossil_Management_Fund\/author\/fmf2\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e04\u0e13\u0e30\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e01\u0e2d\u0e07\u0e17\u0e38\u0e19\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e0b\u0e32\u0e01\u0e14\u0e36\u0e01\u0e14\u0e33\u0e1a\u0e23\u0e23\u0e1e\u0e4c \u0e04\u0e23\u0e31\u0e49\u0e07\u0e17\u0e35\u0e48 2\/2567 - \u0e01\u0e2d\u0e07\u0e17\u0e38\u0e19\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e0b\u0e32\u0e01\u0e14\u0e36\u0e01\u0e14\u0e33\u0e1a\u0e23\u0e23\u0e1e\u0e4c","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.dmr.go.th\/Fossil_Management_Fund\/2024\/03\/29\/\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e04\u0e13\u0e30\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e01\u0e2d\u0e07\u0e17\u0e38\u0e19\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e0b\u0e32\u0e01\u0e14\u0e36\u0e01\u0e14\u0e33\u0e1a\u0e23\u0e23\u0e1e\u0e4c-\u0e04\u0e23\u0e31\u0e49\u0e07\u0e17\u0e35\u0e48-2-2567\/","og_locale":"th_TH","og_type":"article","og_title":"\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e04\u0e13\u0e30\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e01\u0e2d\u0e07\u0e17\u0e38\u0e19\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e0b\u0e32\u0e01\u0e14\u0e36\u0e01\u0e14\u0e33\u0e1a\u0e23\u0e23\u0e1e\u0e4c \u0e04\u0e23\u0e31\u0e49\u0e07\u0e17\u0e35\u0e48 2\/2567 - \u0e01\u0e2d\u0e07\u0e17\u0e38\u0e19\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e0b\u0e32\u0e01\u0e14\u0e36\u0e01\u0e14\u0e33\u0e1a\u0e23\u0e23\u0e1e\u0e4c","og_url":"https:\/\/www.dmr.go.th\/Fossil_Management_Fund\/2024\/03\/29\/\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e04\u0e13\u0e30\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e01\u0e2d\u0e07\u0e17\u0e38\u0e19\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e0b\u0e32\u0e01\u0e14\u0e36\u0e01\u0e14\u0e33\u0e1a\u0e23\u0e23\u0e1e\u0e4c-\u0e04\u0e23\u0e31\u0e49\u0e07\u0e17\u0e35\u0e48-2-2567\/","og_site_name":"\u0e01\u0e2d\u0e07\u0e17\u0e38\u0e19\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e0b\u0e32\u0e01\u0e14\u0e36\u0e01\u0e14\u0e33\u0e1a\u0e23\u0e23\u0e1e\u0e4c","article_published_time":"2024-03-29T07:55:33+00:00","article_modified_time":"2024-03-29T07:55:35+00:00","og_image":[{"url":"https:\/\/www.dmr.go.th\/Fossil_Management_Fund\/wp-content\/uploads\/2024\/03\/one-page.jpg","width":724,"height":1024,"type":"image\/jpeg"}],"author":"\u0e01\u0e2d\u0e07\u0e17\u0e38\u0e19\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e0b\u0e32\u0e01\u0e14\u0e36\u0e01\u0e14\u0e33\u0e1a\u0e23\u0e23\u0e1e\u0e4c2","twitter_card":"summary_large_image","twitter_misc":{"Written by":"\u0e01\u0e2d\u0e07\u0e17\u0e38\u0e19\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e0b\u0e32\u0e01\u0e14\u0e36\u0e01\u0e14\u0e33\u0e1a\u0e23\u0e23\u0e1e\u0e4c2"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.dmr.go.th\/Fossil_Management_Fund\/2024\/03\/29\/%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b8%8a%e0%b8%b8%e0%b8%a1%e0%b8%84%e0%b8%93%e0%b8%b0%e0%b8%81%e0%b8%a3%e0%b8%a3%e0%b8%a1%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%9a%e0%b8%a3%e0%b8%b4%e0%b8%ab%e0%b8%b2%e0%b8%a3%e0%b8%81%e0%b8%ad%e0%b8%87%e0%b8%97%e0%b8%b8%e0%b8%99%e0%b8%88%e0%b8%b1%e0%b8%94%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%8b%e0%b8%b2%e0%b8%81%e0%b8%94%e0%b8%b6%e0%b8%81%e0%b8%94%e0%b8%b3%e0%b8%9a%e0%b8%a3%e0%b8%a3%e0%b8%9e%e0%b9%8c-%e0%b8%84%e0%b8%a3%e0%b8%b1%e0%b9%89%e0%b8%87%e0%b8%97%e0%b8%b5%e0%b9%88-2-2567\/#article","isPartOf":{"@id":"https:\/\/www.dmr.go.th\/Fossil_Management_Fund\/2024\/03\/29\/%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b8%8a%e0%b8%b8%e0%b8%a1%e0%b8%84%e0%b8%93%e0%b8%b0%e0%b8%81%e0%b8%a3%e0%b8%a3%e0%b8%a1%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%9a%e0%b8%a3%e0%b8%b4%e0%b8%ab%e0%b8%b2%e0%b8%a3%e0%b8%81%e0%b8%ad%e0%b8%87%e0%b8%97%e0%b8%b8%e0%b8%99%e0%b8%88%e0%b8%b1%e0%b8%94%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%8b%e0%b8%b2%e0%b8%81%e0%b8%94%e0%b8%b6%e0%b8%81%e0%b8%94%e0%b8%b3%e0%b8%9a%e0%b8%a3%e0%b8%a3%e0%b8%9e%e0%b9%8c-%e0%b8%84%e0%b8%a3%e0%b8%b1%e0%b9%89%e0%b8%87%e0%b8%97%e0%b8%b5%e0%b9%88-2-2567\/"},"author":{"name":"\u0e01\u0e2d\u0e07\u0e17\u0e38\u0e19\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e0b\u0e32\u0e01\u0e14\u0e36\u0e01\u0e14\u0e33\u0e1a\u0e23\u0e23\u0e1e\u0e4c2","@id":"https:\/\/www.dmr.go.th\/Fossil_Management_Fund\/#\/schema\/person\/dd92d597814b0847d736458be9549f3f"},"headline":"\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e04\u0e13\u0e30\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e01\u0e2d\u0e07\u0e17\u0e38\u0e19\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e0b\u0e32\u0e01\u0e14\u0e36\u0e01\u0e14\u0e33\u0e1a\u0e23\u0e23\u0e1e\u0e4c \u0e04\u0e23\u0e31\u0e49\u0e07\u0e17\u0e35\u0e48 2\/2567","datePublished":"2024-03-29T07:55:33+00:00","dateModified":"2024-03-29T07:55:35+00:00","mainEntityOfPage":{"@id":"https:\/\/www.dmr.go.th\/Fossil_Management_Fund\/2024\/03\/29\/%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b8%8a%e0%b8%b8%e0%b8%a1%e0%b8%84%e0%b8%93%e0%b8%b0%e0%b8%81%e0%b8%a3%e0%b8%a3%e0%b8%a1%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%9a%e0%b8%a3%e0%b8%b4%e0%b8%ab%e0%b8%b2%e0%b8%a3%e0%b8%81%e0%b8%ad%e0%b8%87%e0%b8%97%e0%b8%b8%e0%b8%99%e0%b8%88%e0%b8%b1%e0%b8%94%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%8b%e0%b8%b2%e0%b8%81%e0%b8%94%e0%b8%b6%e0%b8%81%e0%b8%94%e0%b8%b3%e0%b8%9a%e0%b8%a3%e0%b8%a3%e0%b8%9e%e0%b9%8c-%e0%b8%84%e0%b8%a3%e0%b8%b1%e0%b9%89%e0%b8%87%e0%b8%97%e0%b8%b5%e0%b9%88-2-2567\/"},"wordCount":0,"commentCount":0,"publisher":{"@id":"https:\/\/www.dmr.go.th\/Fossil_Management_Fund\/#organization"},"articleSection":["One Page"],"inLanguage":"th","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.dmr.go.th\/Fossil_Management_Fund\/2024\/03\/29\/%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b8%8a%e0%b8%b8%e0%b8%a1%e0%b8%84%e0%b8%93%e0%b8%b0%e0%b8%81%e0%b8%a3%e0%b8%a3%e0%b8%a1%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%9a%e0%b8%a3%e0%b8%b4%e0%b8%ab%e0%b8%b2%e0%b8%a3%e0%b8%81%e0%b8%ad%e0%b8%87%e0%b8%97%e0%b8%b8%e0%b8%99%e0%b8%88%e0%b8%b1%e0%b8%94%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%8b%e0%b8%b2%e0%b8%81%e0%b8%94%e0%b8%b6%e0%b8%81%e0%b8%94%e0%b8%b3%e0%b8%9a%e0%b8%a3%e0%b8%a3%e0%b8%9e%e0%b9%8c-%e0%b8%84%e0%b8%a3%e0%b8%b1%e0%b9%89%e0%b8%87%e0%b8%97%e0%b8%b5%e0%b9%88-2-2567\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.dmr.go.th\/Fossil_Management_Fund\/2024\/03\/29\/%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b8%8a%e0%b8%b8%e0%b8%a1%e0%b8%84%e0%b8%93%e0%b8%b0%e0%b8%81%e0%b8%a3%e0%b8%a3%e0%b8%a1%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%9a%e0%b8%a3%e0%b8%b4%e0%b8%ab%e0%b8%b2%e0%b8%a3%e0%b8%81%e0%b8%ad%e0%b8%87%e0%b8%97%e0%b8%b8%e0%b8%99%e0%b8%88%e0%b8%b1%e0%b8%94%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%8b%e0%b8%b2%e0%b8%81%e0%b8%94%e0%b8%b6%e0%b8%81%e0%b8%94%e0%b8%b3%e0%b8%9a%e0%b8%a3%e0%b8%a3%e0%b8%9e%e0%b9%8c-%e0%b8%84%e0%b8%a3%e0%b8%b1%e0%b9%89%e0%b8%87%e0%b8%97%e0%b8%b5%e0%b9%88-2-2567\/","url":"https:\/\/www.dmr.go.th\/Fossil_Management_Fund\/2024\/03\/29\/%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b8%8a%e0%b8%b8%e0%b8%a1%e0%b8%84%e0%b8%93%e0%b8%b0%e0%b8%81%e0%b8%a3%e0%b8%a3%e0%b8%a1%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%9a%e0%b8%a3%e0%b8%b4%e0%b8%ab%e0%b8%b2%e0%b8%a3%e0%b8%81%e0%b8%ad%e0%b8%87%e0%b8%97%e0%b8%b8%e0%b8%99%e0%b8%88%e0%b8%b1%e0%b8%94%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%8b%e0%b8%b2%e0%b8%81%e0%b8%94%e0%b8%b6%e0%b8%81%e0%b8%94%e0%b8%b3%e0%b8%9a%e0%b8%a3%e0%b8%a3%e0%b8%9e%e0%b9%8c-%e0%b8%84%e0%b8%a3%e0%b8%b1%e0%b9%89%e0%b8%87%e0%b8%97%e0%b8%b5%e0%b9%88-2-2567\/","name":"\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e04\u0e13\u0e30\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e01\u0e2d\u0e07\u0e17\u0e38\u0e19\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e0b\u0e32\u0e01\u0e14\u0e36\u0e01\u0e14\u0e33\u0e1a\u0e23\u0e23\u0e1e\u0e4c \u0e04\u0e23\u0e31\u0e49\u0e07\u0e17\u0e35\u0e48 2\/2567 - \u0e01\u0e2d\u0e07\u0e17\u0e38\u0e19\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e0b\u0e32\u0e01\u0e14\u0e36\u0e01\u0e14\u0e33\u0e1a\u0e23\u0e23\u0e1e\u0e4c","isPartOf":{"@id":"https:\/\/www.dmr.go.th\/Fossil_Management_Fund\/#website"},"datePublished":"2024-03-29T07:55:33+00:00","dateModified":"2024-03-29T07:55:35+00:00","breadcrumb":{"@id":"https:\/\/www.dmr.go.th\/Fossil_Management_Fund\/2024\/03\/29\/%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b8%8a%e0%b8%b8%e0%b8%a1%e0%b8%84%e0%b8%93%e0%b8%b0%e0%b8%81%e0%b8%a3%e0%b8%a3%e0%b8%a1%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%9a%e0%b8%a3%e0%b8%b4%e0%b8%ab%e0%b8%b2%e0%b8%a3%e0%b8%81%e0%b8%ad%e0%b8%87%e0%b8%97%e0%b8%b8%e0%b8%99%e0%b8%88%e0%b8%b1%e0%b8%94%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%8b%e0%b8%b2%e0%b8%81%e0%b8%94%e0%b8%b6%e0%b8%81%e0%b8%94%e0%b8%b3%e0%b8%9a%e0%b8%a3%e0%b8%a3%e0%b8%9e%e0%b9%8c-%e0%b8%84%e0%b8%a3%e0%b8%b1%e0%b9%89%e0%b8%87%e0%b8%97%e0%b8%b5%e0%b9%88-2-2567\/#breadcrumb"},"inLanguage":"th","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.dmr.go.th\/Fossil_Management_Fund\/2024\/03\/29\/%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b8%8a%e0%b8%b8%e0%b8%a1%e0%b8%84%e0%b8%93%e0%b8%b0%e0%b8%81%e0%b8%a3%e0%b8%a3%e0%b8%a1%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%9a%e0%b8%a3%e0%b8%b4%e0%b8%ab%e0%b8%b2%e0%b8%a3%e0%b8%81%e0%b8%ad%e0%b8%87%e0%b8%97%e0%b8%b8%e0%b8%99%e0%b8%88%e0%b8%b1%e0%b8%94%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%8b%e0%b8%b2%e0%b8%81%e0%b8%94%e0%b8%b6%e0%b8%81%e0%b8%94%e0%b8%b3%e0%b8%9a%e0%b8%a3%e0%b8%a3%e0%b8%9e%e0%b9%8c-%e0%b8%84%e0%b8%a3%e0%b8%b1%e0%b9%89%e0%b8%87%e0%b8%97%e0%b8%b5%e0%b9%88-2-2567\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.dmr.go.th\/Fossil_Management_Fund\/2024\/03\/29\/%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b8%8a%e0%b8%b8%e0%b8%a1%e0%b8%84%e0%b8%93%e0%b8%b0%e0%b8%81%e0%b8%a3%e0%b8%a3%e0%b8%a1%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%9a%e0%b8%a3%e0%b8%b4%e0%b8%ab%e0%b8%b2%e0%b8%a3%e0%b8%81%e0%b8%ad%e0%b8%87%e0%b8%97%e0%b8%b8%e0%b8%99%e0%b8%88%e0%b8%b1%e0%b8%94%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%8b%e0%b8%b2%e0%b8%81%e0%b8%94%e0%b8%b6%e0%b8%81%e0%b8%94%e0%b8%b3%e0%b8%9a%e0%b8%a3%e0%b8%a3%e0%b8%9e%e0%b9%8c-%e0%b8%84%e0%b8%a3%e0%b8%b1%e0%b9%89%e0%b8%87%e0%b8%97%e0%b8%b5%e0%b9%88-2-2567\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.dmr.go.th\/Fossil_Management_Fund\/"},{"@type":"ListItem","position":2,"name":"\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e04\u0e13\u0e30\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e01\u0e2d\u0e07\u0e17\u0e38\u0e19\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e0b\u0e32\u0e01\u0e14\u0e36\u0e01\u0e14\u0e33\u0e1a\u0e23\u0e23\u0e1e\u0e4c \u0e04\u0e23\u0e31\u0e49\u0e07\u0e17\u0e35\u0e48 2\/2567"}]},{"@type":"WebSite","@id":"https:\/\/www.dmr.go.th\/Fossil_Management_Fund\/#website","url":"https:\/\/www.dmr.go.th\/Fossil_Management_Fund\/","name":"\u0e01\u0e2d\u0e07\u0e17\u0e38\u0e19\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e0b\u0e32\u0e01\u0e14\u0e36\u0e01\u0e14\u0e33\u0e1a\u0e23\u0e23\u0e1e\u0e4c","description":"\u0e01\u0e2d\u0e07\u0e17\u0e38\u0e19\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e0b\u0e32\u0e01\u0e14\u0e36\u0e01\u0e14\u0e33\u0e1a\u0e23\u0e23\u0e1e\u0e4c","publisher":{"@id":"https:\/\/www.dmr.go.th\/Fossil_Management_Fund\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.dmr.go.th\/Fossil_Management_Fund\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"th"},{"@type":"Organization","@id":"https:\/\/www.dmr.go.th\/Fossil_Management_Fund\/#organization","name":"\u0e01\u0e2d\u0e07\u0e17\u0e38\u0e19\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e0b\u0e32\u0e01\u0e14\u0e36\u0e01\u0e14\u0e33\u0e1a\u0e23\u0e23\u0e1e\u0e4c","url":"https:\/\/www.dmr.go.th\/Fossil_Management_Fund\/","logo":{"@type":"ImageObject","inLanguage":"th","@id":"https:\/\/www.dmr.go.th\/Fossil_Management_Fund\/#\/schema\/logo\/image\/","url":"https:\/\/www.dmr.go.th\/Fossil_Management_Fund\/wp-content\/uploads\/2022\/12\/logo-PhotoRoom-1.png","contentUrl":"https:\/\/www.dmr.go.th\/Fossil_Management_Fund\/wp-content\/uploads\/2022\/12\/logo-PhotoRoom-1.png","width":373,"height":373,"caption":"\u0e01\u0e2d\u0e07\u0e17\u0e38\u0e19\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e0b\u0e32\u0e01\u0e14\u0e36\u0e01\u0e14\u0e33\u0e1a\u0e23\u0e23\u0e1e\u0e4c"},"image":{"@id":"https:\/\/www.dmr.go.th\/Fossil_Management_Fund\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.dmr.go.th\/Fossil_Management_Fund\/#\/schema\/person\/dd92d597814b0847d736458be9549f3f","name":"\u0e01\u0e2d\u0e07\u0e17\u0e38\u0e19\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e0b\u0e32\u0e01\u0e14\u0e36\u0e01\u0e14\u0e33\u0e1a\u0e23\u0e23\u0e1e\u0e4c2","image":{"@type":"ImageObject","inLanguage":"th","@id":"https:\/\/www.dmr.go.th\/Fossil_Management_Fund\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/714bdb8637eb5704058efecbc3e49f852fb656e6066bc6014cff6a158890a999?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/714bdb8637eb5704058efecbc3e49f852fb656e6066bc6014cff6a158890a999?s=96&d=mm&r=g","caption":"\u0e01\u0e2d\u0e07\u0e17\u0e38\u0e19\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e0b\u0e32\u0e01\u0e14\u0e36\u0e01\u0e14\u0e33\u0e1a\u0e23\u0e23\u0e1e\u0e4c2"},"url":"https:\/\/www.dmr.go.th\/Fossil_Management_Fund\/author\/fmf2\/"}]}},"_links":{"self":[{"href":"https:\/\/www.dmr.go.th\/Fossil_Management_Fund\/wp-json\/wp\/v2\/posts\/2723","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.dmr.go.th\/Fossil_Management_Fund\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.dmr.go.th\/Fossil_Management_Fund\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.dmr.go.th\/Fossil_Management_Fund\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.dmr.go.th\/Fossil_Management_Fund\/wp-json\/wp\/v2\/comments?post=2723"}],"version-history":[{"count":2,"href":"https:\/\/www.dmr.go.th\/Fossil_Management_Fund\/wp-json\/wp\/v2\/posts\/2723\/revisions"}],"predecessor-version":[{"id":2725,"href":"https:\/\/www.dmr.go.th\/Fossil_Management_Fund\/wp-json\/wp\/v2\/posts\/2723\/revisions\/2725"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.dmr.go.th\/Fossil_Management_Fund\/wp-json\/wp\/v2\/media\/2722"}],"wp:attachment":[{"href":"https:\/\/www.dmr.go.th\/Fossil_Management_Fund\/wp-json\/wp\/v2\/media?parent=2723"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.dmr.go.th\/Fossil_Management_Fund\/wp-json\/wp\/v2\/categories?post=2723"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.dmr.go.th\/Fossil_Management_Fund\/wp-json\/wp\/v2\/tags?post=2723"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}