{"id":156624,"date":"2011-02-13T11:08:00","date_gmt":"2011-02-13T04:08:00","guid":{"rendered":""},"modified":"2011-02-13T11:08:00","modified_gmt":"2011-02-13T04:08:00","slug":"%e0%b8%a3%e0%b8%b2%e0%b8%a2%e0%b8%87%e0%b8%b2%e0%b8%99%e0%b8%aa%e0%b8%96%e0%b8%b2%e0%b8%99%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%93%e0%b9%8c%e0%b8%98%e0%b8%a3%e0%b8%93%e0%b8%b5%e0%b8%9e%e0%b8%b4%e0%b8%9a%e0%b8%b1%e0%b8%95%e0%b8%b4%e0%b8%a0%e0%b8%b1%e0%b8%a2-%e0%b8%aa%e0%b8%a0%e0%b8%b2%e0%b8%9e%e0%b8%ad%e0%b8%b2%e0%b8%81%e0%b8%b2%e0%b8%a8-%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b8%88%e0%b8%b3%e0%b8%a7%e0%b8%b1%e0%b8%99%e0%b8%ad%e0%b8%b2%e0%b8%97%e0%b8%b4%e0%b8%95%e0%b8%a2%e0%b9%8c%e0%b8%97%e0%b8%b5%e0%b9%88-%e0%b9%91%e0%b9%93-%e0%b8%81%e0%b8%b8%e0%b8%a1%e0%b8%a0%e0%b8%b2%e0%b8%9e%e0%b8%b1%e0%b8%99%e0%b8%98%e0%b9%8c-%e0%b9%92%e0%b9%95%e0%b9%95%e0%b9%94","status":"publish","type":"post","link":"https:\/\/www.dmr.go.th\/en\/%e0%b8%a3%e0%b8%b2%e0%b8%a2%e0%b8%87%e0%b8%b2%e0%b8%99%e0%b8%aa%e0%b8%96%e0%b8%b2%e0%b8%99%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%93%e0%b9%8c%e0%b8%98%e0%b8%a3%e0%b8%93%e0%b8%b5%e0%b8%9e%e0%b8%b4%e0%b8%9a%e0%b8%b1%e0%b8%95%e0%b8%b4%e0%b8%a0%e0%b8%b1%e0%b8%a2-%e0%b8%aa%e0%b8%a0%e0%b8%b2%e0%b8%9e%e0%b8%ad%e0%b8%b2%e0%b8%81%e0%b8%b2%e0%b8%a8-%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b8%88%e0%b8%b3%e0%b8%a7%e0%b8%b1%e0%b8%99%e0%b8%ad%e0%b8%b2%e0%b8%97%e0%b8%b4%e0%b8%95%e0%b8%a2%e0%b9%8c%e0%b8%97%e0%b8%b5%e0%b9%88-%e0%b9%91%e0%b9%93-%e0%b8%81%e0%b8%b8%e0%b8%a1%e0%b8%a0%e0%b8%b2%e0%b8%9e%e0%b8%b1%e0%b8%99%e0%b8%98%e0%b9%8c-%e0%b9%92%e0%b9%95%e0%b9%95%e0%b9%94\/","title":{"rendered":"\u0e23\u0e32\u0e22\u0e07\u0e32\u0e19\u0e2a\u0e16\u0e32\u0e19\u0e01\u0e32\u0e23\u0e13\u0e4c\u0e18\u0e23\u0e13\u0e35\u0e1e\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e20\u0e31\u0e22 \u0e2a\u0e20\u0e32\u0e1e\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e1b\u0e23\u0e30\u0e08\u0e33\u0e27\u0e31\u0e19\u0e2d\u0e32\u0e17\u0e34\u0e15\u0e22\u0e4c\u0e17\u0e35\u0e48 \u0e51\u0e53 \u0e01\u0e38\u0e21\u0e20\u0e32\u0e1e\u0e31\u0e19\u0e18\u0e4c \u0e52\u0e55\u0e55\u0e54"},"content":{"rendered":"<p>\u0e23\u0e32\u0e22\u0e07\u0e32\u0e19\u0e2a\u0e16\u0e32\u0e19\u0e01\u0e32\u0e23\u0e13\u0e4c\u0e18\u0e23\u0e13\u0e35\u0e1e\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e20\u0e31\u0e22 \u0e2a\u0e20\u0e32\u0e1e\u0e2d\u0e32\u0e01\u0e32\u0e28<br \/>\n\u0e27\u0e31\u0e19\u0e2d\u0e32\u0e17\u0e34\u0e15\u0e22\u0e4c \u0e17\u0e35\u0e48 \u0e51\u0e53 \u0e01\u0e38\u0e21\u0e20\u0e32\u0e1e\u0e31\u0e19\u0e18\u0e4c \u0e1e.\u0e28. \u0e52\u0e55\u0e55\u0e54  \u0e40\u0e27\u0e25\u0e32 \u0e51\u0e50.\u0e50\u0e50 \u0e19.<br \/>\n\u0e51. \u0e18\u0e23\u0e13\u0e35\u0e1e\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e20\u0e31\u0e22<br \/>\n\u0e51.\u0e51 \u0e14\u0e34\u0e19\u0e44\u0e2b\u0e25 \u0e2b\u0e34\u0e19\u0e16\u0e25\u0e48\u0e21 \u0e23\u0e2d\u0e22\u0e41\u0e22\u0e01 \u0e2b\u0e25\u0e38\u0e21\u0e22\u0e38\u0e1a<br \/>\n&#8211; \u0e44\u0e21\u0e48\u0e21\u0e35<br \/>\n\u0e51.\u0e52 \u0e41\u0e1c\u0e48\u0e19\u0e14\u0e34\u0e19\u0e44\u0e2b\u0e27<br \/>\n            \u0e41\u0e1c\u0e48\u0e19\u0e14\u0e34\u0e19\u0e44\u0e2b\u0e27\u0e43\u0e19\u0e23\u0e2d\u0e1a \u0e52\u0e54  \u0e0a\u0e31\u0e48\u0e27\u0e42\u0e21\u0e07\u0e17\u0e35\u0e48\u0e1c\u0e48\u0e32\u0e19\u0e21\u0e32 (\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 \u0e51\u0e52 \u0e01.\u0e1e. \u0e55\u0e54 \u0e40\u0e27\u0e25\u0e32 \u0e50\u0e59.\u0e50\u0e50 \u0e19. &#8211; \u0e51\u0e53 \u0e01.\u0e1e. \u0e55\u0e54 \u0e40\u0e27\u0e25\u0e32 \u0e50\u0e59.\u0e50\u0e50 \u0e19.)<br \/>\n\u0e0a\u0e48\u0e27\u0e07\u0e02\u0e19\u0e32\u0e14\u0e41\u0e1c\u0e48\u0e19\u0e14\u0e34\u0e19\u0e44\u0e2b\u0e27 (\u0e23\u0e34\u0e01\u0e40\u0e15\u0e2d\u0e23\u0e4c)<br \/>\n\u0e08\u0e33\u0e19\u0e27\u0e19 (\u0e04\u0e23\u0e31\u0e49\u0e07)<br \/>\n\u0e53.\u0e50 \u2013 \u0e54.\u0e50 (\u0e40\u0e25\u0e47\u0e01)<br \/>\n\u0e58<br \/>\n\u0e54.\u0e51-\u0e55.\u0e50 (\u0e04\u0e48\u0e2d\u0e19\u0e02\u0e49\u0e32\u0e07\u0e40\u0e25\u0e47\u0e01)<br \/>\n\u0e57<br \/>\n\u0e55.\u0e51-\u0e56.\u0e50 (\u0e1b\u0e32\u0e19\u0e01\u0e25\u0e32\u0e07)<br \/>\n\u0e54<br \/>\n\u0e56.\u0e51 \u0e02\u0e36\u0e49\u0e19\u0e44\u0e1b (\u0e04\u0e48\u0e2d\u0e19\u0e02\u0e49\u0e32\u0e07\u0e43\u0e2b\u0e0d\u0e48)<br \/>\n\u0e52<br \/>\n\u0e41\u0e1c\u0e48\u0e19\u0e14\u0e34\u0e19\u0e44\u0e2b\u0e27\u0e25\u0e48\u0e32\u0e2a\u0e38\u0e14\u0e21\u0e35\u0e02\u0e19\u0e32\u0e14 \u0e55.\u0e57 \u0e23\u0e34\u0e01\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e43\u0e19\u0e17\u0e30\u0e40\u0e25 \u0e17\u0e35\u0e48\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e04\u0e27\u0e32\u0e21\u0e25\u0e36\u0e01 \u0e53\u0e55.\u0e54 \u0e01\u0e34\u0e42\u0e25\u0e40\u0e21\u0e15\u0e23\u0e08\u0e32\u0e01\u0e1c\u0e34\u0e27\u0e42\u0e25\u0e01 \u0e40\u0e21\u0e37\u0e48\u0e2d\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 \u0e51\u0e53 \u0e01\u0e38\u0e21\u0e20\u0e32\u0e1e\u0e31\u0e19\u0e18\u0e4c \u0e52\u0e55\u0e55\u0e54 \u0e40\u0e27\u0e25\u0e32 \u0e50\u0e57.\u0e51\u0e52 \u0e19. \u0e15\u0e32\u0e21\u0e40\u0e27\u0e25\u0e32\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22 ANDAMAN ISLANDS, INDIA REGION (\u0e17\u0e35\u0e48\u0e21\u0e32: USGS)<br \/>\n\u0e52. \u0e2a\u0e20\u0e32\u0e1e\u0e2d\u0e32\u0e01\u0e32\u0e28<br \/>\n&#8211; \u0e1a\u0e23\u0e34\u0e40\u0e27\u0e13\u0e04\u0e27\u0e32\u0e21\u0e01\u0e14\u0e2d\u0e32\u0e01\u0e32\u0e28\u0e2a\u0e39\u0e07\u0e2b\u0e23\u0e37\u0e2d\u0e21\u0e27\u0e25\u0e2d\u0e32\u0e01\u0e32\u0e28\u0e40\u0e22\u0e47\u0e19\u0e01\u0e33\u0e25\u0e31\u0e07\u0e04\u0e48\u0e2d\u0e19\u0e02\u0e49\u0e32\u0e07\u0e41\u0e23\u0e07\u0e08\u0e32\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e08\u0e35\u0e19\u0e44\u0e14\u0e49\u0e41\u0e1c\u0e48\u0e25\u0e07\u0e21\u0e32\u0e1b\u0e01\u0e04\u0e25\u0e38\u0e21\u0e20\u0e32\u0e04\u0e15\u0e30\u0e27\u0e31\u0e19\u0e2d\u0e2d\u0e01\u0e40\u0e09\u0e35\u0e22\u0e07\u0e40\u0e2b\u0e19\u0e37\u0e2d\u0e02\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22\u0e41\u0e25\u0e49\u0e27 \u0e17\u0e33\u0e43\u0e2b\u0e49\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22\u0e15\u0e2d\u0e19\u0e1a\u0e19\u0e21\u0e35\u0e1e\u0e32\u0e22\u0e38\u0e1d\u0e19\u0e1f\u0e49\u0e32\u0e04\u0e30\u0e19\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e25\u0e21\u0e01\u0e23\u0e30\u0e42\u0e0a\u0e01\u0e41\u0e23\u0e07\u0e40\u0e01\u0e34\u0e14\u0e02\u0e36\u0e49\u0e19\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e13\u0e2b\u0e20\u0e39\u0e21\u0e34\u0e08\u0e30\u0e25\u0e14\u0e25\u0e07 \u0e54-\u0e56 \u0e2d\u0e07\u0e28\u0e32 \u0e08\u0e36\u0e07\u0e02\u0e2d\u0e43\u0e2b\u0e49\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e0a\u0e19\u0e23\u0e30\u0e21\u0e31\u0e14\u0e23\u0e30\u0e27\u0e31\u0e07\u0e2d\u0e31\u0e19\u0e15\u0e23\u0e32\u0e22\u0e08\u0e32\u0e01\u0e1e\u0e32\u0e22\u0e38\u0e1d\u0e19\u0e1f\u0e49\u0e32\u0e04\u0e30\u0e19\u0e2d\u0e07\u0e41\u0e25\u0e30\u0e25\u0e21\u0e01\u0e23\u0e30\u0e42\u0e0a\u0e01\u0e41\u0e23\u0e07\u0e43\u0e19\u0e23\u0e30\u0e22\u0e30\u0e19\u0e35\u0e49 \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e21\u0e23\u0e2a\u0e38\u0e21\u0e15\u0e30\u0e27\u0e31\u0e19\u0e2d\u0e2d\u0e01\u0e40\u0e09\u0e35\u0e22\u0e07\u0e40\u0e2b\u0e19\u0e37\u0e2d\u0e21\u0e35\u0e01\u0e33\u0e25\u0e31\u0e07\u0e41\u0e23\u0e07\u0e02\u0e36\u0e49\u0e19\u0e41\u0e25\u0e30\u0e40\u0e02\u0e49\u0e32\u0e21\u0e32\u0e1b\u0e01\u0e04\u0e25\u0e38\u0e21\u0e20\u0e32\u0e04\u0e43\u0e15\u0e49\u0e41\u0e25\u0e30\u0e2d\u0e48\u0e32\u0e27\u0e44\u0e17\u0e22 \u0e43\u0e19\u0e0a\u0e48\u0e27\u0e07\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 \u0e51\u0e53-\u0e51\u0e56 \u0e01\u0e38\u0e21\u0e20\u0e32\u0e1e\u0e31\u0e19\u0e18\u0e4c \u0e52\u0e55\u0e55\u0e54 \u0e17\u0e33\u0e43\u0e2b\u0e49\u0e20\u0e32\u0e04\u0e43\u0e15\u0e49\u0e21\u0e35\u0e1d\u0e19\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e21\u0e32\u0e01\u0e02\u0e36\u0e49\u0e19\u0e41\u0e25\u0e30\u0e21\u0e35\u0e1d\u0e19\u0e15\u0e01\u0e2b\u0e19\u0e31\u0e01\u0e1a\u0e32\u0e07\u0e41\u0e2b\u0e48\u0e07 (\u0e01\u0e23\u0e21\u0e2d\u0e38\u0e15\u0e38\u0e19\u0e34\u0e22\u0e21\u0e27\u0e34\u0e17\u0e22\u0e32)<br \/>\n&#8211; \u0e1b\u0e23\u0e34\u0e21\u0e32\u0e13\u0e19\u0e49\u0e33\u0e1d\u0e19\u0e2a\u0e39\u0e07\u0e2a\u0e38\u0e14\u0e27\u0e31\u0e14\u0e44\u0e14\u0e49\u0e17\u0e35\u0e48\u0e2d\u0e33\u0e40\u0e20\u0e2d\u0e42\u0e19\u0e19\u0e2a\u0e30\u0e2d\u0e32\u0e14 \u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e2d\u0e38\u0e14\u0e23\u0e18\u0e32\u0e19\u0e35 \u0e1b\u0e23\u0e34\u0e21\u0e32\u0e13 \u0e53\u0e52.\u0e55 \u0e21\u0e21.(\u0e01\u0e23\u0e21\u0e2d\u0e38\u0e15\u0e38\u0e19\u0e34\u0e22\u0e21\u0e27\u0e34\u0e17\u0e22\u0e32)<br \/>\n\u0e53. \u0e40\u0e04\u0e23\u0e37\u0e2d\u0e02\u0e48\u0e32\u0e22\u0e01\u0e23\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e32\u0e01\u0e23\u0e18\u0e23\u0e13\u0e35 \u0e40\u0e21\u0e37\u0e48\u0e2d\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 \u0e51\u0e53 \u0e01\u0e38\u0e21\u0e20\u0e32\u0e1e\u0e31\u0e19\u0e18\u0e4c \u0e52\u0e55\u0e55\u0e54<br \/>\n          -\u0e1a\u0e49\u0e32\u0e19\u0e04\u0e25\u0e2d\u0e07\u0e44\u0e17\u0e23 \u0e15\u0e33\u0e1a\u0e25\u0e41\u0e21\u0e48\u0e40\u0e25\u0e22\u0e4c \u0e2d\u0e33\u0e40\u0e20\u0e2d\u0e41\u0e21\u0e48\u0e27\u0e07\u0e01\u0e4c \u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e19\u0e04\u0e23\u0e2a\u0e27\u0e23\u0e23\u0e04\u0e4c \u0e27\u0e31\u0e14\u0e19\u0e49\u0e33\u0e1d\u0e19\u0e44\u0e14\u0e49 \u0e52\u0e50 \u0e21\u0e21. (\u0e19\u0e32\u0e07\u0e01\u0e31\u0e19\u0e17\u0e34\u0e21\u0e32 \u0e2d\u0e34\u0e19\u0e17\u0e23\u0e4c\u0e2b\u0e2d\u0e21)<br \/>\n          -\u0e1a\u0e49\u0e32\u0e19\u0e2a\u0e31\u0e01\u0e07\u0e32\u0e21 \u0e15\u0e33\u0e1a\u0e25\u0e2a\u0e31\u0e01\u0e07\u0e32\u0e21 \u0e2d\u0e33\u0e40\u0e20\u0e2d\u0e04\u0e25\u0e2d\u0e07\u0e25\u0e32\u0e19 \u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e01\u0e33\u0e41\u0e1e\u0e07\u0e40\u0e1e\u0e0a\u0e23 \u0e27\u0e31\u0e14\u0e19\u0e49\u0e33\u0e1d\u0e19\u0e44\u0e14\u0e49 \u0e51\u0e50 \u0e21\u0e21. (\u0e19\u0e32\u0e07\u0e27\u0e31\u0e19\u0e40\u0e1e\u0e47\u0e0d \u0e2a\u0e34\u0e07\u0e2b\u0e4c\u0e2a\u0e23\u0e2d\u0e22)<br \/>\n          -\u0e1a\u0e49\u0e32\u0e19\u0e42\u0e19\u0e19\u0e40\u0e15\u0e32\u0e40\u0e2b\u0e25\u0e47\u0e01 \u0e15\u0e33\u0e1a\u0e25\u0e27\u0e31\u0e07\u0e2a\u0e27\u0e32\u0e1a \u0e2d\u0e33\u0e40\u0e20\u0e2d\u0e20\u0e39\u0e1c\u0e32\u0e21\u0e48\u0e32\u0e19 \u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19 \u0e27\u0e31\u0e14\u0e19\u0e49\u0e33\u0e1d\u0e19\u0e44\u0e14\u0e49 \u0e51\u0e50 \u0e21\u0e21. (\u0e19\u0e32\u0e22\u0e17\u0e2d\u0e07\u0e2a\u0e38\u0e02 \u0e41\u0e1e\u0e07\u0e17\u0e2d\u0e07)<br \/>\n          -\u0e1a\u0e49\u0e32\u0e19\u0e2b\u0e21\u0e37\u0e48\u0e19\u0e14\u0e48\u0e32\u0e19 \u0e15\u0e33\u0e1a\u0e25\u0e1a\u0e48\u0e2d\u0e1e\u0e25\u0e2d\u0e22 \u0e2d\u0e33\u0e40\u0e20\u0e2d\u0e1a\u0e48\u0e2d\u0e44\u0e23\u0e48 \u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e15\u0e23\u0e32\u0e14 \u0e17\u0e49\u0e2d\u0e07\u0e1f\u0e49\u0e32\u0e21\u0e37\u0e14\u0e04\u0e23\u0e36\u0e49\u0e21 \u0e44\u0e21\u0e48\u0e21\u0e35\u0e1d\u0e19 (\u0e19\u0e32\u0e07\u0e25\u0e33\u0e14\u0e27\u0e19 \u0e08\u0e33\u0e1b\u0e32\u0e14\u0e35)<br \/>\n          -\u0e1a\u0e49\u0e32\u0e19\u0e2a\u0e27\u0e19\u0e1b\u0e48\u0e32 \u0e15\u0e33\u0e1a\u0e25\u0e41\u0e21\u0e48\u0e40\u0e1b\u0e34\u0e19 \u0e2d\u0e33\u0e40\u0e20\u0e2d\u0e41\u0e21\u0e48\u0e40\u0e1b\u0e34\u0e19 \u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e19\u0e04\u0e23\u0e2a\u0e27\u0e23\u0e23\u0e04\u0e4c \u0e17\u0e49\u0e2d\u0e07\u0e1f\u0e49\u0e32\u0e21\u0e37\u0e14\u0e04\u0e23\u0e36\u0e49\u0e21 \u0e44\u0e21\u0e48\u0e21\u0e35\u0e1d\u0e19 (\u0e19\u0e32\u0e22\u0e1a\u0e38\u0e0d\u0e0a\u0e39 \u0e42\u0e0a\u0e15\u0e34\u0e1e\u0e23\u0e21)<br \/>\n          -\u0e1a\u0e49\u0e32\u0e19\u0e40\u0e19\u0e34\u0e19\u0e2a\u0e27\u0e48\u0e32\u0e07 \u0e15\u0e33\u0e1a\u0e25\u0e19\u0e32\u0e1a\u0e48\u0e2d\u0e04\u0e33 \u0e2d\u0e33\u0e40\u0e20\u0e2d\u0e40\u0e21\u0e37\u0e2d\u0e07 \u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e01\u0e33\u0e41\u0e1e\u0e07\u0e40\u0e1e\u0e0a\u0e23 \u0e17\u0e49\u0e2d\u0e07\u0e1f\u0e49\u0e32\u0e41\u0e08\u0e48\u0e21\u0e43\u0e2a \u0e44\u0e21\u0e48\u0e21\u0e35\u0e1d\u0e19 (\u0e19\u0e32\u0e07\u0e43\u0e2b\u0e21\u0e48 \u0e01\u0e32\u0e40\u0e2b\u0e27\u0e48\u0e32)<br \/>\n\u0e54. \u0e41\u0e1c\u0e48\u0e19\u0e14\u0e34\u0e19\u0e44\u0e2b\u0e27\u0e0a\u0e34\u0e25\u0e35<br \/>\n          &#8211; \u0e40\u0e01\u0e34\u0e14\u0e40\u0e2b\u0e15\u0e38\u0e41\u0e1c\u0e48\u0e19\u0e14\u0e34\u0e19\u0e44\u0e2b\u0e27\u0e02\u0e19\u0e32\u0e14 \u0e56.\u0e58 \u0e23\u0e34\u0e04\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e21\u0e35\u0e08\u0e38\u0e14\u0e28\u0e39\u0e19\u0e22\u0e4c\u0e01\u0e25\u0e32\u0e07\u0e2d\u0e22\u0e39\u0e48\u0e19\u0e2d\u0e01\u0e0a\u0e32\u0e22\u0e1d\u0e31\u0e48\u0e07\u0e17\u0e32\u0e07\u0e40\u0e2b\u0e19\u0e37\u0e2d\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e04\u0e2d\u0e19\u0e40\u0e0b\u0e1b\u0e0b\u0e34\u0e2d\u0e2d\u0e19 \u0e54\u0e55 \u0e01\u0e34\u0e42\u0e25\u0e40\u0e21\u0e15\u0e23\u0e2d\u0e22\u0e39\u0e48\u0e25\u0e36\u0e01\u0e25\u0e07\u0e44\u0e1b\u0e43\u0e15\u0e49\u0e17\u0e30\u0e40\u0e25 \u0e51\u0e58.\u0e54 \u0e01\u0e34\u0e42\u0e25\u0e40\u0e21\u0e15\u0e23 \u0e2a\u0e23\u0e49\u0e32\u0e07\u0e04\u0e27\u0e32\u0e21\u0e41\u0e15\u0e01\u0e15\u0e37\u0e48\u0e19\u0e43\u0e2b\u0e49\u0e01\u0e31\u0e1a\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e0a\u0e19\u0e40\u0e1b\u0e47\u0e19\u0e08\u0e33\u0e19\u0e27\u0e19\u0e21\u0e32\u0e01 \u0e40\u0e1e\u0e23\u0e32\u0e30\u0e08\u0e38\u0e14\u0e17\u0e35\u0e48\u0e40\u0e01\u0e34\u0e14\u0e41\u0e1c\u0e48\u0e19\u0e14\u0e34\u0e19\u0e44\u0e2b\u0e27\u0e40\u0e1b\u0e47\u0e19\u0e08\u0e38\u0e14\u0e40\u0e14\u0e35\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e17\u0e35\u0e48\u0e40\u0e01\u0e34\u0e14\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e1b\u0e35\u0e17\u0e35\u0e48\u0e41\u0e25\u0e49\u0e27\u0e17\u0e35\u0e48\u0e17\u0e33\u0e43\u0e2b\u0e49\u0e21\u0e35\u0e1c\u0e39\u0e49\u0e40\u0e2a\u0e35\u0e22\u0e0a\u0e35\u0e27\u0e34\u0e15\u0e44\u0e1b\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e19\u0e49\u0e2d\u0e22 \u0e55\u0e52\u0e51 \u0e04\u0e19 \u0e2d\u0e22\u0e48\u0e32\u0e07\u0e44\u0e23\u0e01\u0e47\u0e15\u0e32\u0e21\u0e41\u0e1c\u0e48\u0e19\u0e14\u0e34\u0e19\u0e44\u0e2b\u0e27\u0e17\u0e35\u0e48\u0e40\u0e01\u0e34\u0e14\u0e02\u0e36\u0e49\u0e19\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e27\u0e32\u0e19\u0e19\u0e35\u0e49\u0e44\u0e21\u0e48\u0e21\u0e35\u0e23\u0e32\u0e22\u0e07\u0e32\u0e19\u0e1c\u0e39\u0e49\u0e1a\u0e32\u0e14\u0e40\u0e08\u0e47\u0e1a \u0e2b\u0e23\u0e37\u0e2d\u0e40\u0e2a\u0e35\u0e22\u0e0a\u0e35\u0e27\u0e34\u0e15 \u0e41\u0e15\u0e48\u0e01\u0e47\u0e17\u0e33\u0e43\u0e2b\u0e49\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e41\u0e25\u0e30\u0e42\u0e17\u0e23\u0e28\u0e31\u0e1e\u0e17\u0e4c\u0e16\u0e39\u0e01\u0e15\u0e31\u0e14\u0e02\u0e32\u0e14 \u0e17\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49\u0e21\u0e35\u0e23\u0e32\u0e22\u0e07\u0e32\u0e19\u0e27\u0e48\u0e32 \u0e44\u0e14\u0e49\u0e40\u0e01\u0e34\u0e14\u0e2d\u0e32\u0e1f\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e0a\u0e47\u0e2d\u0e04 \u0e2b\u0e23\u0e37\u0e2d\u0e41\u0e23\u0e07\u0e2a\u0e31\u0e48\u0e19\u0e2a\u0e30\u0e40\u0e17\u0e37\u0e2d\u0e19\u0e15\u0e32\u0e21\u0e32\u0e27\u0e31\u0e14\u0e44\u0e14\u0e49\u0e15\u0e31\u0e49\u0e07\u0e41\u0e15\u0e48 \u0e54.\u0e57 \u0e44\u0e1b\u0e08\u0e19\u0e16\u0e36\u0e07 \u0e56.\u0e51 \u0e23\u0e34\u0e04\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e02\u0e13\u0e30\u0e17\u0e35\u0e48\u0e2d\u0e32\u0e04\u0e32\u0e23\u0e43\u0e19\u0e01\u0e23\u0e38\u0e07\u0e0b\u0e32\u0e19\u0e15\u0e34\u0e2d\u0e32\u0e42\u0e01\u0e49 \u0e01\u0e47\u0e22\u0e31\u0e07\u0e2a\u0e31\u0e48\u0e19\u0e44\u0e2b\u0e27\u0e44\u0e1b\u0e14\u0e49\u0e27\u0e22 (\u0e17\u0e35\u0e48\u0e21\u0e32: \u0e1c\u0e39\u0e49\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u0e23\u0e32\u0e22\u0e07\u0e32\u0e19\u0e2a\u0e16\u0e32\u0e19\u0e01\u0e32\u0e23\u0e13\u0e4c\u0e18\u0e23\u0e13\u0e35\u0e1e\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e20\u0e31\u0e22 \u0e2a\u0e20\u0e32\u0e1e\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e27\u0e31\u0e19\u0e2d\u0e32\u0e17\u0e34\u0e15\u0e22\u0e4c \u0e17\u0e35\u0e48 \u0e51\u0e53 \u0e01\u0e38\u0e21\u0e20\u0e32\u0e1e\u0e31\u0e19\u0e18\u0e4c \u0e1e.\u0e28. \u0e52\u0e55\u0e55\u0e54 \u0e40\u0e27\u0e25\u0e32 \u0e51\u0e50.\u0e50\u0e50 \u0e19. \u0e51. \u0e18\u0e23\u0e13\u0e35\u0e1e\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e20\u0e31\u0e22 \u0e51.\u0e51 \u0e14\u0e34\u0e19\u0e44\u0e2b\u0e25 \u0e2b\u0e34\u0e19\u0e16\u0e25\u0e48\u0e21 \u0e23\u0e2d\u0e22\u0e41\u0e22\u0e01 \u0e2b\u0e25\u0e38\u0e21\u0e22\u0e38\u0e1a &#8211; \u0e44\u0e21\u0e48\u0e21\u0e35 \u0e51.\u0e52 \u0e41\u0e1c\u0e48\u0e19\u0e14\u0e34\u0e19\u0e44\u0e2b\u0e27 \u0e41\u0e1c\u0e48\u0e19\u0e14\u0e34\u0e19\u0e44\u0e2b\u0e27\u0e43\u0e19\u0e23\u0e2d\u0e1a \u0e52\u0e54 \u0e0a\u0e31\u0e48\u0e27\u0e42\u0e21\u0e07\u0e17\u0e35\u0e48\u0e1c\u0e48\u0e32\u0e19\u0e21\u0e32 (\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 \u0e51\u0e52 \u0e01.\u0e1e. \u0e55\u0e54 \u0e40\u0e27\u0e25\u0e32 \u0e50\u0e59.\u0e50\u0e50 \u0e19. &#8211; \u0e51\u0e53 \u0e01.\u0e1e. \u0e55\u0e54 \u0e40\u0e27\u0e25\u0e32 \u0e50\u0e59.\u0e50\u0e50 \u0e19.) \u0e0a\u0e48\u0e27\u0e07\u0e02\u0e19\u0e32\u0e14\u0e41\u0e1c\u0e48\u0e19\u0e14\u0e34\u0e19\u0e44\u0e2b\u0e27 (\u0e23\u0e34\u0e01\u0e40\u0e15\u0e2d\u0e23\u0e4c) \u0e08\u0e33\u0e19\u0e27\u0e19 (\u0e04\u0e23\u0e31\u0e49\u0e07) \u0e53.\u0e50 \u2013 \u0e54.\u0e50 (\u0e40\u0e25\u0e47\u0e01) \u0e58 \u0e54.\u0e51-\u0e55.\u0e50 (\u0e04\u0e48\u0e2d\u0e19\u0e02\u0e49\u0e32\u0e07\u0e40\u0e25\u0e47\u0e01) \u0e57 \u0e55.\u0e51-\u0e56.\u0e50 (\u0e1b\u0e32\u0e19\u0e01\u0e25\u0e32\u0e07) \u0e54 \u0e56.\u0e51 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":151535,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[41],"tags":[],"class_list":["post-156624","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-geohazard_daily_report"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u0e23\u0e32\u0e22\u0e07\u0e32\u0e19\u0e2a\u0e16\u0e32\u0e19\u0e01\u0e32\u0e23\u0e13\u0e4c\u0e18\u0e23\u0e13\u0e35\u0e1e\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e20\u0e31\u0e22 \u0e2a\u0e20\u0e32\u0e1e\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e1b\u0e23\u0e30\u0e08\u0e33\u0e27\u0e31\u0e19\u0e2d\u0e32\u0e17\u0e34\u0e15\u0e22\u0e4c\u0e17\u0e35\u0e48 \u0e51\u0e53 \u0e01\u0e38\u0e21\u0e20\u0e32\u0e1e\u0e31\u0e19\u0e18\u0e4c \u0e52\u0e55\u0e55\u0e54 - \u0e01\u0e23\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e32\u0e01\u0e23\u0e18\u0e23\u0e13\u0e35<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.dmr.go.th\/\u0e23\u0e32\u0e22\u0e07\u0e32\u0e19\u0e2a\u0e16\u0e32\u0e19\u0e01\u0e32\u0e23\u0e13\u0e4c\u0e18\u0e23\u0e13\u0e35\u0e1e\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e20\u0e31\u0e22-\u0e2a\u0e20\u0e32\u0e1e\u0e2d\u0e32\u0e01\u0e32\u0e28-\u0e1b\u0e23\u0e30\u0e08\u0e33\u0e27\u0e31\u0e19\u0e2d\u0e32\u0e17\u0e34\u0e15\u0e22\u0e4c\u0e17\u0e35\u0e48-\u0e51\u0e53-\u0e01\u0e38\u0e21\u0e20\u0e32\u0e1e\u0e31\u0e19\u0e18\u0e4c-\u0e52\u0e55\u0e55\u0e54\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u0e23\u0e32\u0e22\u0e07\u0e32\u0e19\u0e2a\u0e16\u0e32\u0e19\u0e01\u0e32\u0e23\u0e13\u0e4c\u0e18\u0e23\u0e13\u0e35\u0e1e\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e20\u0e31\u0e22 \u0e2a\u0e20\u0e32\u0e1e\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e1b\u0e23\u0e30\u0e08\u0e33\u0e27\u0e31\u0e19\u0e2d\u0e32\u0e17\u0e34\u0e15\u0e22\u0e4c\u0e17\u0e35\u0e48 \u0e51\u0e53 \u0e01\u0e38\u0e21\u0e20\u0e32\u0e1e\u0e31\u0e19\u0e18\u0e4c \u0e52\u0e55\u0e55\u0e54 - \u0e01\u0e23\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e32\u0e01\u0e23\u0e18\u0e23\u0e13\u0e35\" \/>\n<meta property=\"og:description\" content=\"\u0e23\u0e32\u0e22\u0e07\u0e32\u0e19\u0e2a\u0e16\u0e32\u0e19\u0e01\u0e32\u0e23\u0e13\u0e4c\u0e18\u0e23\u0e13\u0e35\u0e1e\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e20\u0e31\u0e22 \u0e2a\u0e20\u0e32\u0e1e\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e27\u0e31\u0e19\u0e2d\u0e32\u0e17\u0e34\u0e15\u0e22\u0e4c \u0e17\u0e35\u0e48 \u0e51\u0e53 \u0e01\u0e38\u0e21\u0e20\u0e32\u0e1e\u0e31\u0e19\u0e18\u0e4c \u0e1e.\u0e28. \u0e52\u0e55\u0e55\u0e54 \u0e40\u0e27\u0e25\u0e32 \u0e51\u0e50.\u0e50\u0e50 \u0e19. \u0e51. \u0e18\u0e23\u0e13\u0e35\u0e1e\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e20\u0e31\u0e22 \u0e51.\u0e51 \u0e14\u0e34\u0e19\u0e44\u0e2b\u0e25 \u0e2b\u0e34\u0e19\u0e16\u0e25\u0e48\u0e21 \u0e23\u0e2d\u0e22\u0e41\u0e22\u0e01 \u0e2b\u0e25\u0e38\u0e21\u0e22\u0e38\u0e1a &#8211; \u0e44\u0e21\u0e48\u0e21\u0e35 \u0e51.\u0e52 \u0e41\u0e1c\u0e48\u0e19\u0e14\u0e34\u0e19\u0e44\u0e2b\u0e27 \u0e41\u0e1c\u0e48\u0e19\u0e14\u0e34\u0e19\u0e44\u0e2b\u0e27\u0e43\u0e19\u0e23\u0e2d\u0e1a \u0e52\u0e54 \u0e0a\u0e31\u0e48\u0e27\u0e42\u0e21\u0e07\u0e17\u0e35\u0e48\u0e1c\u0e48\u0e32\u0e19\u0e21\u0e32 (\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 \u0e51\u0e52 \u0e01.\u0e1e. \u0e55\u0e54 \u0e40\u0e27\u0e25\u0e32 \u0e50\u0e59.\u0e50\u0e50 \u0e19. &#8211; \u0e51\u0e53 \u0e01.\u0e1e. \u0e55\u0e54 \u0e40\u0e27\u0e25\u0e32 \u0e50\u0e59.\u0e50\u0e50 \u0e19.) \u0e0a\u0e48\u0e27\u0e07\u0e02\u0e19\u0e32\u0e14\u0e41\u0e1c\u0e48\u0e19\u0e14\u0e34\u0e19\u0e44\u0e2b\u0e27 (\u0e23\u0e34\u0e01\u0e40\u0e15\u0e2d\u0e23\u0e4c) \u0e08\u0e33\u0e19\u0e27\u0e19 (\u0e04\u0e23\u0e31\u0e49\u0e07) \u0e53.\u0e50 \u2013 \u0e54.\u0e50 (\u0e40\u0e25\u0e47\u0e01) \u0e58 \u0e54.\u0e51-\u0e55.\u0e50 (\u0e04\u0e48\u0e2d\u0e19\u0e02\u0e49\u0e32\u0e07\u0e40\u0e25\u0e47\u0e01) \u0e57 \u0e55.\u0e51-\u0e56.\u0e50 (\u0e1b\u0e32\u0e19\u0e01\u0e25\u0e32\u0e07) \u0e54 \u0e56.\u0e51 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.dmr.go.th\/\u0e23\u0e32\u0e22\u0e07\u0e32\u0e19\u0e2a\u0e16\u0e32\u0e19\u0e01\u0e32\u0e23\u0e13\u0e4c\u0e18\u0e23\u0e13\u0e35\u0e1e\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e20\u0e31\u0e22-\u0e2a\u0e20\u0e32\u0e1e\u0e2d\u0e32\u0e01\u0e32\u0e28-\u0e1b\u0e23\u0e30\u0e08\u0e33\u0e27\u0e31\u0e19\u0e2d\u0e32\u0e17\u0e34\u0e15\u0e22\u0e4c\u0e17\u0e35\u0e48-\u0e51\u0e53-\u0e01\u0e38\u0e21\u0e20\u0e32\u0e1e\u0e31\u0e19\u0e18\u0e4c-\u0e52\u0e55\u0e55\u0e54\/\" \/>\n<meta property=\"og:site_name\" content=\"\u0e01\u0e23\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e32\u0e01\u0e23\u0e18\u0e23\u0e13\u0e35\" \/>\n<meta property=\"article:published_time\" content=\"2011-02-13T04:08:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.dmr.go.th\/wp-content\/uploads\/2022\/10\/default_img-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"768\" \/>\n\t<meta property=\"og:image:height\" content=\"1109\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e18\u0e23\u0e13\u0e35\u0e27\u0e34\u0e17\u0e22\u0e32\u0e2a\u0e34\u0e48\u0e07\u0e41\u0e27\u0e14\u0e25\u0e49\u0e2d\u0e21\u0e41\u0e25\u0e30\u0e18\u0e23\u0e13\u0e35\u0e1e\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e20\u0e31\u0e22\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e18\u0e23\u0e13\u0e35\u0e27\u0e34\u0e17\u0e22\u0e32\u0e2a\u0e34\u0e48\u0e07\u0e41\u0e27\u0e14\u0e25\u0e49\u0e2d\u0e21\u0e41\u0e25\u0e30\u0e18\u0e23\u0e13\u0e35\u0e1e\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e20\u0e31\u0e22\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.dmr.go.th\/%e0%b8%a3%e0%b8%b2%e0%b8%a2%e0%b8%87%e0%b8%b2%e0%b8%99%e0%b8%aa%e0%b8%96%e0%b8%b2%e0%b8%99%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%93%e0%b9%8c%e0%b8%98%e0%b8%a3%e0%b8%93%e0%b8%b5%e0%b8%9e%e0%b8%b4%e0%b8%9a%e0%b8%b1%e0%b8%95%e0%b8%b4%e0%b8%a0%e0%b8%b1%e0%b8%a2-%e0%b8%aa%e0%b8%a0%e0%b8%b2%e0%b8%9e%e0%b8%ad%e0%b8%b2%e0%b8%81%e0%b8%b2%e0%b8%a8-%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b8%88%e0%b8%b3%e0%b8%a7%e0%b8%b1%e0%b8%99%e0%b8%ad%e0%b8%b2%e0%b8%97%e0%b8%b4%e0%b8%95%e0%b8%a2%e0%b9%8c%e0%b8%97%e0%b8%b5%e0%b9%88-%e0%b9%91%e0%b9%93-%e0%b8%81%e0%b8%b8%e0%b8%a1%e0%b8%a0%e0%b8%b2%e0%b8%9e%e0%b8%b1%e0%b8%99%e0%b8%98%e0%b9%8c-%e0%b9%92%e0%b9%95%e0%b9%95%e0%b9%94\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.dmr.go.th\/%e0%b8%a3%e0%b8%b2%e0%b8%a2%e0%b8%87%e0%b8%b2%e0%b8%99%e0%b8%aa%e0%b8%96%e0%b8%b2%e0%b8%99%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%93%e0%b9%8c%e0%b8%98%e0%b8%a3%e0%b8%93%e0%b8%b5%e0%b8%9e%e0%b8%b4%e0%b8%9a%e0%b8%b1%e0%b8%95%e0%b8%b4%e0%b8%a0%e0%b8%b1%e0%b8%a2-%e0%b8%aa%e0%b8%a0%e0%b8%b2%e0%b8%9e%e0%b8%ad%e0%b8%b2%e0%b8%81%e0%b8%b2%e0%b8%a8-%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b8%88%e0%b8%b3%e0%b8%a7%e0%b8%b1%e0%b8%99%e0%b8%ad%e0%b8%b2%e0%b8%97%e0%b8%b4%e0%b8%95%e0%b8%a2%e0%b9%8c%e0%b8%97%e0%b8%b5%e0%b9%88-%e0%b9%91%e0%b9%93-%e0%b8%81%e0%b8%b8%e0%b8%a1%e0%b8%a0%e0%b8%b2%e0%b8%9e%e0%b8%b1%e0%b8%99%e0%b8%98%e0%b9%8c-%e0%b9%92%e0%b9%95%e0%b9%95%e0%b9%94\/\"},\"author\":{\"name\":\"\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e18\u0e23\u0e13\u0e35\u0e27\u0e34\u0e17\u0e22\u0e32\u0e2a\u0e34\u0e48\u0e07\u0e41\u0e27\u0e14\u0e25\u0e49\u0e2d\u0e21\u0e41\u0e25\u0e30\u0e18\u0e23\u0e13\u0e35\u0e1e\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e20\u0e31\u0e22\",\"@id\":\"https:\/\/www.dmr.go.th\/#\/schema\/person\/f4bc4dd56ee9041de4a03c606749e2bc\"},\"headline\":\"\u0e23\u0e32\u0e22\u0e07\u0e32\u0e19\u0e2a\u0e16\u0e32\u0e19\u0e01\u0e32\u0e23\u0e13\u0e4c\u0e18\u0e23\u0e13\u0e35\u0e1e\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e20\u0e31\u0e22 \u0e2a\u0e20\u0e32\u0e1e\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e1b\u0e23\u0e30\u0e08\u0e33\u0e27\u0e31\u0e19\u0e2d\u0e32\u0e17\u0e34\u0e15\u0e22\u0e4c\u0e17\u0e35\u0e48 \u0e51\u0e53 \u0e01\u0e38\u0e21\u0e20\u0e32\u0e1e\u0e31\u0e19\u0e18\u0e4c \u0e52\u0e55\u0e55\u0e54\",\"datePublished\":\"2011-02-13T04:08:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.dmr.go.th\/%e0%b8%a3%e0%b8%b2%e0%b8%a2%e0%b8%87%e0%b8%b2%e0%b8%99%e0%b8%aa%e0%b8%96%e0%b8%b2%e0%b8%99%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%93%e0%b9%8c%e0%b8%98%e0%b8%a3%e0%b8%93%e0%b8%b5%e0%b8%9e%e0%b8%b4%e0%b8%9a%e0%b8%b1%e0%b8%95%e0%b8%b4%e0%b8%a0%e0%b8%b1%e0%b8%a2-%e0%b8%aa%e0%b8%a0%e0%b8%b2%e0%b8%9e%e0%b8%ad%e0%b8%b2%e0%b8%81%e0%b8%b2%e0%b8%a8-%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b8%88%e0%b8%b3%e0%b8%a7%e0%b8%b1%e0%b8%99%e0%b8%ad%e0%b8%b2%e0%b8%97%e0%b8%b4%e0%b8%95%e0%b8%a2%e0%b9%8c%e0%b8%97%e0%b8%b5%e0%b9%88-%e0%b9%91%e0%b9%93-%e0%b8%81%e0%b8%b8%e0%b8%a1%e0%b8%a0%e0%b8%b2%e0%b8%9e%e0%b8%b1%e0%b8%99%e0%b8%98%e0%b9%8c-%e0%b9%92%e0%b9%95%e0%b9%95%e0%b9%94\/\"},\"wordCount\":20,\"publisher\":{\"@id\":\"https:\/\/www.dmr.go.th\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.dmr.go.th\/%e0%b8%a3%e0%b8%b2%e0%b8%a2%e0%b8%87%e0%b8%b2%e0%b8%99%e0%b8%aa%e0%b8%96%e0%b8%b2%e0%b8%99%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%93%e0%b9%8c%e0%b8%98%e0%b8%a3%e0%b8%93%e0%b8%b5%e0%b8%9e%e0%b8%b4%e0%b8%9a%e0%b8%b1%e0%b8%95%e0%b8%b4%e0%b8%a0%e0%b8%b1%e0%b8%a2-%e0%b8%aa%e0%b8%a0%e0%b8%b2%e0%b8%9e%e0%b8%ad%e0%b8%b2%e0%b8%81%e0%b8%b2%e0%b8%a8-%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b8%88%e0%b8%b3%e0%b8%a7%e0%b8%b1%e0%b8%99%e0%b8%ad%e0%b8%b2%e0%b8%97%e0%b8%b4%e0%b8%95%e0%b8%a2%e0%b9%8c%e0%b8%97%e0%b8%b5%e0%b9%88-%e0%b9%91%e0%b9%93-%e0%b8%81%e0%b8%b8%e0%b8%a1%e0%b8%a0%e0%b8%b2%e0%b8%9e%e0%b8%b1%e0%b8%99%e0%b8%98%e0%b9%8c-%e0%b9%92%e0%b9%95%e0%b9%95%e0%b9%94\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.dmr.go.th\/wp-content\/uploads\/2022\/10\/default_img-1.jpg\",\"articleSection\":[\"\u0e23\u0e32\u0e22\u0e07\u0e32\u0e19\u0e2a\u0e16\u0e32\u0e19\u0e01\u0e32\u0e23\u0e13\u0e4c\u0e18\u0e23\u0e13\u0e35\u0e1e\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e20\u0e31\u0e22\u0e1b\u0e23\u0e30\u0e08\u0e33\u0e27\u0e31\u0e19\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.dmr.go.th\/%e0%b8%a3%e0%b8%b2%e0%b8%a2%e0%b8%87%e0%b8%b2%e0%b8%99%e0%b8%aa%e0%b8%96%e0%b8%b2%e0%b8%99%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%93%e0%b9%8c%e0%b8%98%e0%b8%a3%e0%b8%93%e0%b8%b5%e0%b8%9e%e0%b8%b4%e0%b8%9a%e0%b8%b1%e0%b8%95%e0%b8%b4%e0%b8%a0%e0%b8%b1%e0%b8%a2-%e0%b8%aa%e0%b8%a0%e0%b8%b2%e0%b8%9e%e0%b8%ad%e0%b8%b2%e0%b8%81%e0%b8%b2%e0%b8%a8-%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b8%88%e0%b8%b3%e0%b8%a7%e0%b8%b1%e0%b8%99%e0%b8%ad%e0%b8%b2%e0%b8%97%e0%b8%b4%e0%b8%95%e0%b8%a2%e0%b9%8c%e0%b8%97%e0%b8%b5%e0%b9%88-%e0%b9%91%e0%b9%93-%e0%b8%81%e0%b8%b8%e0%b8%a1%e0%b8%a0%e0%b8%b2%e0%b8%9e%e0%b8%b1%e0%b8%99%e0%b8%98%e0%b9%8c-%e0%b9%92%e0%b9%95%e0%b9%95%e0%b9%94\/\",\"url\":\"https:\/\/www.dmr.go.th\/%e0%b8%a3%e0%b8%b2%e0%b8%a2%e0%b8%87%e0%b8%b2%e0%b8%99%e0%b8%aa%e0%b8%96%e0%b8%b2%e0%b8%99%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%93%e0%b9%8c%e0%b8%98%e0%b8%a3%e0%b8%93%e0%b8%b5%e0%b8%9e%e0%b8%b4%e0%b8%9a%e0%b8%b1%e0%b8%95%e0%b8%b4%e0%b8%a0%e0%b8%b1%e0%b8%a2-%e0%b8%aa%e0%b8%a0%e0%b8%b2%e0%b8%9e%e0%b8%ad%e0%b8%b2%e0%b8%81%e0%b8%b2%e0%b8%a8-%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b8%88%e0%b8%b3%e0%b8%a7%e0%b8%b1%e0%b8%99%e0%b8%ad%e0%b8%b2%e0%b8%97%e0%b8%b4%e0%b8%95%e0%b8%a2%e0%b9%8c%e0%b8%97%e0%b8%b5%e0%b9%88-%e0%b9%91%e0%b9%93-%e0%b8%81%e0%b8%b8%e0%b8%a1%e0%b8%a0%e0%b8%b2%e0%b8%9e%e0%b8%b1%e0%b8%99%e0%b8%98%e0%b9%8c-%e0%b9%92%e0%b9%95%e0%b9%95%e0%b9%94\/\",\"name\":\"\u0e23\u0e32\u0e22\u0e07\u0e32\u0e19\u0e2a\u0e16\u0e32\u0e19\u0e01\u0e32\u0e23\u0e13\u0e4c\u0e18\u0e23\u0e13\u0e35\u0e1e\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e20\u0e31\u0e22 \u0e2a\u0e20\u0e32\u0e1e\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e1b\u0e23\u0e30\u0e08\u0e33\u0e27\u0e31\u0e19\u0e2d\u0e32\u0e17\u0e34\u0e15\u0e22\u0e4c\u0e17\u0e35\u0e48 \u0e51\u0e53 \u0e01\u0e38\u0e21\u0e20\u0e32\u0e1e\u0e31\u0e19\u0e18\u0e4c \u0e52\u0e55\u0e55\u0e54 - \u0e01\u0e23\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e32\u0e01\u0e23\u0e18\u0e23\u0e13\u0e35\",\"isPartOf\":{\"@id\":\"https:\/\/www.dmr.go.th\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.dmr.go.th\/%e0%b8%a3%e0%b8%b2%e0%b8%a2%e0%b8%87%e0%b8%b2%e0%b8%99%e0%b8%aa%e0%b8%96%e0%b8%b2%e0%b8%99%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%93%e0%b9%8c%e0%b8%98%e0%b8%a3%e0%b8%93%e0%b8%b5%e0%b8%9e%e0%b8%b4%e0%b8%9a%e0%b8%b1%e0%b8%95%e0%b8%b4%e0%b8%a0%e0%b8%b1%e0%b8%a2-%e0%b8%aa%e0%b8%a0%e0%b8%b2%e0%b8%9e%e0%b8%ad%e0%b8%b2%e0%b8%81%e0%b8%b2%e0%b8%a8-%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b8%88%e0%b8%b3%e0%b8%a7%e0%b8%b1%e0%b8%99%e0%b8%ad%e0%b8%b2%e0%b8%97%e0%b8%b4%e0%b8%95%e0%b8%a2%e0%b9%8c%e0%b8%97%e0%b8%b5%e0%b9%88-%e0%b9%91%e0%b9%93-%e0%b8%81%e0%b8%b8%e0%b8%a1%e0%b8%a0%e0%b8%b2%e0%b8%9e%e0%b8%b1%e0%b8%99%e0%b8%98%e0%b9%8c-%e0%b9%92%e0%b9%95%e0%b9%95%e0%b9%94\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.dmr.go.th\/%e0%b8%a3%e0%b8%b2%e0%b8%a2%e0%b8%87%e0%b8%b2%e0%b8%99%e0%b8%aa%e0%b8%96%e0%b8%b2%e0%b8%99%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%93%e0%b9%8c%e0%b8%98%e0%b8%a3%e0%b8%93%e0%b8%b5%e0%b8%9e%e0%b8%b4%e0%b8%9a%e0%b8%b1%e0%b8%95%e0%b8%b4%e0%b8%a0%e0%b8%b1%e0%b8%a2-%e0%b8%aa%e0%b8%a0%e0%b8%b2%e0%b8%9e%e0%b8%ad%e0%b8%b2%e0%b8%81%e0%b8%b2%e0%b8%a8-%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b8%88%e0%b8%b3%e0%b8%a7%e0%b8%b1%e0%b8%99%e0%b8%ad%e0%b8%b2%e0%b8%97%e0%b8%b4%e0%b8%95%e0%b8%a2%e0%b9%8c%e0%b8%97%e0%b8%b5%e0%b9%88-%e0%b9%91%e0%b9%93-%e0%b8%81%e0%b8%b8%e0%b8%a1%e0%b8%a0%e0%b8%b2%e0%b8%9e%e0%b8%b1%e0%b8%99%e0%b8%98%e0%b9%8c-%e0%b9%92%e0%b9%95%e0%b9%95%e0%b9%94\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.dmr.go.th\/wp-content\/uploads\/2022\/10\/default_img-1.jpg\",\"datePublished\":\"2011-02-13T04:08:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.dmr.go.th\/%e0%b8%a3%e0%b8%b2%e0%b8%a2%e0%b8%87%e0%b8%b2%e0%b8%99%e0%b8%aa%e0%b8%96%e0%b8%b2%e0%b8%99%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%93%e0%b9%8c%e0%b8%98%e0%b8%a3%e0%b8%93%e0%b8%b5%e0%b8%9e%e0%b8%b4%e0%b8%9a%e0%b8%b1%e0%b8%95%e0%b8%b4%e0%b8%a0%e0%b8%b1%e0%b8%a2-%e0%b8%aa%e0%b8%a0%e0%b8%b2%e0%b8%9e%e0%b8%ad%e0%b8%b2%e0%b8%81%e0%b8%b2%e0%b8%a8-%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b8%88%e0%b8%b3%e0%b8%a7%e0%b8%b1%e0%b8%99%e0%b8%ad%e0%b8%b2%e0%b8%97%e0%b8%b4%e0%b8%95%e0%b8%a2%e0%b9%8c%e0%b8%97%e0%b8%b5%e0%b9%88-%e0%b9%91%e0%b9%93-%e0%b8%81%e0%b8%b8%e0%b8%a1%e0%b8%a0%e0%b8%b2%e0%b8%9e%e0%b8%b1%e0%b8%99%e0%b8%98%e0%b9%8c-%e0%b9%92%e0%b9%95%e0%b9%95%e0%b9%94\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.dmr.go.th\/%e0%b8%a3%e0%b8%b2%e0%b8%a2%e0%b8%87%e0%b8%b2%e0%b8%99%e0%b8%aa%e0%b8%96%e0%b8%b2%e0%b8%99%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%93%e0%b9%8c%e0%b8%98%e0%b8%a3%e0%b8%93%e0%b8%b5%e0%b8%9e%e0%b8%b4%e0%b8%9a%e0%b8%b1%e0%b8%95%e0%b8%b4%e0%b8%a0%e0%b8%b1%e0%b8%a2-%e0%b8%aa%e0%b8%a0%e0%b8%b2%e0%b8%9e%e0%b8%ad%e0%b8%b2%e0%b8%81%e0%b8%b2%e0%b8%a8-%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b8%88%e0%b8%b3%e0%b8%a7%e0%b8%b1%e0%b8%99%e0%b8%ad%e0%b8%b2%e0%b8%97%e0%b8%b4%e0%b8%95%e0%b8%a2%e0%b9%8c%e0%b8%97%e0%b8%b5%e0%b9%88-%e0%b9%91%e0%b9%93-%e0%b8%81%e0%b8%b8%e0%b8%a1%e0%b8%a0%e0%b8%b2%e0%b8%9e%e0%b8%b1%e0%b8%99%e0%b8%98%e0%b9%8c-%e0%b9%92%e0%b9%95%e0%b9%95%e0%b9%94\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.dmr.go.th\/%e0%b8%a3%e0%b8%b2%e0%b8%a2%e0%b8%87%e0%b8%b2%e0%b8%99%e0%b8%aa%e0%b8%96%e0%b8%b2%e0%b8%99%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%93%e0%b9%8c%e0%b8%98%e0%b8%a3%e0%b8%93%e0%b8%b5%e0%b8%9e%e0%b8%b4%e0%b8%9a%e0%b8%b1%e0%b8%95%e0%b8%b4%e0%b8%a0%e0%b8%b1%e0%b8%a2-%e0%b8%aa%e0%b8%a0%e0%b8%b2%e0%b8%9e%e0%b8%ad%e0%b8%b2%e0%b8%81%e0%b8%b2%e0%b8%a8-%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b8%88%e0%b8%b3%e0%b8%a7%e0%b8%b1%e0%b8%99%e0%b8%ad%e0%b8%b2%e0%b8%97%e0%b8%b4%e0%b8%95%e0%b8%a2%e0%b9%8c%e0%b8%97%e0%b8%b5%e0%b9%88-%e0%b9%91%e0%b9%93-%e0%b8%81%e0%b8%b8%e0%b8%a1%e0%b8%a0%e0%b8%b2%e0%b8%9e%e0%b8%b1%e0%b8%99%e0%b8%98%e0%b9%8c-%e0%b9%92%e0%b9%95%e0%b9%95%e0%b9%94\/#primaryimage\",\"url\":\"https:\/\/www.dmr.go.th\/wp-content\/uploads\/2022\/10\/default_img-1.jpg\",\"contentUrl\":\"https:\/\/www.dmr.go.th\/wp-content\/uploads\/2022\/10\/default_img-1.jpg\",\"width\":768,\"height\":1109,\"caption\":\"\u0e23\u0e39\u0e1b\u0e20\u0e32\u0e1e\u0e02\u0e2d\u0e07\u0e01\u0e23\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e32\u0e01\u0e23\u0e18\u0e23\u0e13\u0e35\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.dmr.go.th\/%e0%b8%a3%e0%b8%b2%e0%b8%a2%e0%b8%87%e0%b8%b2%e0%b8%99%e0%b8%aa%e0%b8%96%e0%b8%b2%e0%b8%99%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%93%e0%b9%8c%e0%b8%98%e0%b8%a3%e0%b8%93%e0%b8%b5%e0%b8%9e%e0%b8%b4%e0%b8%9a%e0%b8%b1%e0%b8%95%e0%b8%b4%e0%b8%a0%e0%b8%b1%e0%b8%a2-%e0%b8%aa%e0%b8%a0%e0%b8%b2%e0%b8%9e%e0%b8%ad%e0%b8%b2%e0%b8%81%e0%b8%b2%e0%b8%a8-%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b8%88%e0%b8%b3%e0%b8%a7%e0%b8%b1%e0%b8%99%e0%b8%ad%e0%b8%b2%e0%b8%97%e0%b8%b4%e0%b8%95%e0%b8%a2%e0%b9%8c%e0%b8%97%e0%b8%b5%e0%b9%88-%e0%b9%91%e0%b9%93-%e0%b8%81%e0%b8%b8%e0%b8%a1%e0%b8%a0%e0%b8%b2%e0%b8%9e%e0%b8%b1%e0%b8%99%e0%b8%98%e0%b9%8c-%e0%b9%92%e0%b9%95%e0%b9%95%e0%b9%94\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.dmr.go.th\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u0e23\u0e32\u0e22\u0e07\u0e32\u0e19\u0e2a\u0e16\u0e32\u0e19\u0e01\u0e32\u0e23\u0e13\u0e4c\u0e18\u0e23\u0e13\u0e35\u0e1e\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e20\u0e31\u0e22 \u0e2a\u0e20\u0e32\u0e1e\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e1b\u0e23\u0e30\u0e08\u0e33\u0e27\u0e31\u0e19\u0e2d\u0e32\u0e17\u0e34\u0e15\u0e22\u0e4c\u0e17\u0e35\u0e48 \u0e51\u0e53 \u0e01\u0e38\u0e21\u0e20\u0e32\u0e1e\u0e31\u0e19\u0e18\u0e4c \u0e52\u0e55\u0e55\u0e54\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.dmr.go.th\/#website\",\"url\":\"https:\/\/www.dmr.go.th\/\",\"name\":\"\u0e01\u0e23\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e32\u0e01\u0e23\u0e18\u0e23\u0e13\u0e35\",\"description\":\"\u0e01\u0e23\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e32\u0e01\u0e23\u0e18\u0e23\u0e13\u0e35\",\"publisher\":{\"@id\":\"https:\/\/www.dmr.go.th\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.dmr.go.th\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.dmr.go.th\/#organization\",\"name\":\"\u0e01\u0e23\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e32\u0e01\u0e23\u0e18\u0e23\u0e13\u0e35\",\"url\":\"https:\/\/www.dmr.go.th\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.dmr.go.th\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.dmr.go.th\/wp-content\/uploads\/2022\/08\/\u0e15\u0e23\u0e32\u0e01\u0e23\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e32\u0e01\u0e23\u0e18\u0e23\u0e13\u0e35-2.png\",\"contentUrl\":\"https:\/\/www.dmr.go.th\/wp-content\/uploads\/2022\/08\/\u0e15\u0e23\u0e32\u0e01\u0e23\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e32\u0e01\u0e23\u0e18\u0e23\u0e13\u0e35-2.png\",\"width\":400,\"height\":400,\"caption\":\"\u0e01\u0e23\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e32\u0e01\u0e23\u0e18\u0e23\u0e13\u0e35\"},\"image\":{\"@id\":\"https:\/\/www.dmr.go.th\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.dmr.go.th\/#\/schema\/person\/f4bc4dd56ee9041de4a03c606749e2bc\",\"name\":\"\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e18\u0e23\u0e13\u0e35\u0e27\u0e34\u0e17\u0e22\u0e32\u0e2a\u0e34\u0e48\u0e07\u0e41\u0e27\u0e14\u0e25\u0e49\u0e2d\u0e21\u0e41\u0e25\u0e30\u0e18\u0e23\u0e13\u0e35\u0e1e\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e20\u0e31\u0e22\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.dmr.go.th\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/16cd7e279959e64661a4e273e93548cbadc539d0c3f9f0db93f4c4c1c30720c0?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/16cd7e279959e64661a4e273e93548cbadc539d0c3f9f0db93f4c4c1c30720c0?s=96&d=mm&r=g\",\"caption\":\"\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e18\u0e23\u0e13\u0e35\u0e27\u0e34\u0e17\u0e22\u0e32\u0e2a\u0e34\u0e48\u0e07\u0e41\u0e27\u0e14\u0e25\u0e49\u0e2d\u0e21\u0e41\u0e25\u0e30\u0e18\u0e23\u0e13\u0e35\u0e1e\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e20\u0e31\u0e22\"},\"sameAs\":[\"https:\/\/www.dmr.go.th\"],\"url\":\"https:\/\/www.dmr.go.th\/en\/author\/amika-bcipher-co-th\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u0e23\u0e32\u0e22\u0e07\u0e32\u0e19\u0e2a\u0e16\u0e32\u0e19\u0e01\u0e32\u0e23\u0e13\u0e4c\u0e18\u0e23\u0e13\u0e35\u0e1e\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e20\u0e31\u0e22 \u0e2a\u0e20\u0e32\u0e1e\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e1b\u0e23\u0e30\u0e08\u0e33\u0e27\u0e31\u0e19\u0e2d\u0e32\u0e17\u0e34\u0e15\u0e22\u0e4c\u0e17\u0e35\u0e48 \u0e51\u0e53 \u0e01\u0e38\u0e21\u0e20\u0e32\u0e1e\u0e31\u0e19\u0e18\u0e4c \u0e52\u0e55\u0e55\u0e54 - \u0e01\u0e23\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e32\u0e01\u0e23\u0e18\u0e23\u0e13\u0e35","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.dmr.go.th\/\u0e23\u0e32\u0e22\u0e07\u0e32\u0e19\u0e2a\u0e16\u0e32\u0e19\u0e01\u0e32\u0e23\u0e13\u0e4c\u0e18\u0e23\u0e13\u0e35\u0e1e\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e20\u0e31\u0e22-\u0e2a\u0e20\u0e32\u0e1e\u0e2d\u0e32\u0e01\u0e32\u0e28-\u0e1b\u0e23\u0e30\u0e08\u0e33\u0e27\u0e31\u0e19\u0e2d\u0e32\u0e17\u0e34\u0e15\u0e22\u0e4c\u0e17\u0e35\u0e48-\u0e51\u0e53-\u0e01\u0e38\u0e21\u0e20\u0e32\u0e1e\u0e31\u0e19\u0e18\u0e4c-\u0e52\u0e55\u0e55\u0e54\/","og_locale":"en_US","og_type":"article","og_title":"\u0e23\u0e32\u0e22\u0e07\u0e32\u0e19\u0e2a\u0e16\u0e32\u0e19\u0e01\u0e32\u0e23\u0e13\u0e4c\u0e18\u0e23\u0e13\u0e35\u0e1e\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e20\u0e31\u0e22 \u0e2a\u0e20\u0e32\u0e1e\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e1b\u0e23\u0e30\u0e08\u0e33\u0e27\u0e31\u0e19\u0e2d\u0e32\u0e17\u0e34\u0e15\u0e22\u0e4c\u0e17\u0e35\u0e48 \u0e51\u0e53 \u0e01\u0e38\u0e21\u0e20\u0e32\u0e1e\u0e31\u0e19\u0e18\u0e4c \u0e52\u0e55\u0e55\u0e54 - \u0e01\u0e23\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e32\u0e01\u0e23\u0e18\u0e23\u0e13\u0e35","og_description":"\u0e23\u0e32\u0e22\u0e07\u0e32\u0e19\u0e2a\u0e16\u0e32\u0e19\u0e01\u0e32\u0e23\u0e13\u0e4c\u0e18\u0e23\u0e13\u0e35\u0e1e\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e20\u0e31\u0e22 \u0e2a\u0e20\u0e32\u0e1e\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e27\u0e31\u0e19\u0e2d\u0e32\u0e17\u0e34\u0e15\u0e22\u0e4c \u0e17\u0e35\u0e48 \u0e51\u0e53 \u0e01\u0e38\u0e21\u0e20\u0e32\u0e1e\u0e31\u0e19\u0e18\u0e4c \u0e1e.\u0e28. \u0e52\u0e55\u0e55\u0e54 \u0e40\u0e27\u0e25\u0e32 \u0e51\u0e50.\u0e50\u0e50 \u0e19. \u0e51. \u0e18\u0e23\u0e13\u0e35\u0e1e\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e20\u0e31\u0e22 \u0e51.\u0e51 \u0e14\u0e34\u0e19\u0e44\u0e2b\u0e25 \u0e2b\u0e34\u0e19\u0e16\u0e25\u0e48\u0e21 \u0e23\u0e2d\u0e22\u0e41\u0e22\u0e01 \u0e2b\u0e25\u0e38\u0e21\u0e22\u0e38\u0e1a &#8211; \u0e44\u0e21\u0e48\u0e21\u0e35 \u0e51.\u0e52 \u0e41\u0e1c\u0e48\u0e19\u0e14\u0e34\u0e19\u0e44\u0e2b\u0e27 \u0e41\u0e1c\u0e48\u0e19\u0e14\u0e34\u0e19\u0e44\u0e2b\u0e27\u0e43\u0e19\u0e23\u0e2d\u0e1a \u0e52\u0e54 \u0e0a\u0e31\u0e48\u0e27\u0e42\u0e21\u0e07\u0e17\u0e35\u0e48\u0e1c\u0e48\u0e32\u0e19\u0e21\u0e32 (\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 \u0e51\u0e52 \u0e01.\u0e1e. \u0e55\u0e54 \u0e40\u0e27\u0e25\u0e32 \u0e50\u0e59.\u0e50\u0e50 \u0e19. &#8211; \u0e51\u0e53 \u0e01.\u0e1e. \u0e55\u0e54 \u0e40\u0e27\u0e25\u0e32 \u0e50\u0e59.\u0e50\u0e50 \u0e19.) \u0e0a\u0e48\u0e27\u0e07\u0e02\u0e19\u0e32\u0e14\u0e41\u0e1c\u0e48\u0e19\u0e14\u0e34\u0e19\u0e44\u0e2b\u0e27 (\u0e23\u0e34\u0e01\u0e40\u0e15\u0e2d\u0e23\u0e4c) \u0e08\u0e33\u0e19\u0e27\u0e19 (\u0e04\u0e23\u0e31\u0e49\u0e07) \u0e53.\u0e50 \u2013 \u0e54.\u0e50 (\u0e40\u0e25\u0e47\u0e01) \u0e58 \u0e54.\u0e51-\u0e55.\u0e50 (\u0e04\u0e48\u0e2d\u0e19\u0e02\u0e49\u0e32\u0e07\u0e40\u0e25\u0e47\u0e01) \u0e57 \u0e55.\u0e51-\u0e56.\u0e50 (\u0e1b\u0e32\u0e19\u0e01\u0e25\u0e32\u0e07) \u0e54 \u0e56.\u0e51 [&hellip;]","og_url":"https:\/\/www.dmr.go.th\/\u0e23\u0e32\u0e22\u0e07\u0e32\u0e19\u0e2a\u0e16\u0e32\u0e19\u0e01\u0e32\u0e23\u0e13\u0e4c\u0e18\u0e23\u0e13\u0e35\u0e1e\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e20\u0e31\u0e22-\u0e2a\u0e20\u0e32\u0e1e\u0e2d\u0e32\u0e01\u0e32\u0e28-\u0e1b\u0e23\u0e30\u0e08\u0e33\u0e27\u0e31\u0e19\u0e2d\u0e32\u0e17\u0e34\u0e15\u0e22\u0e4c\u0e17\u0e35\u0e48-\u0e51\u0e53-\u0e01\u0e38\u0e21\u0e20\u0e32\u0e1e\u0e31\u0e19\u0e18\u0e4c-\u0e52\u0e55\u0e55\u0e54\/","og_site_name":"\u0e01\u0e23\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e32\u0e01\u0e23\u0e18\u0e23\u0e13\u0e35","article_published_time":"2011-02-13T04:08:00+00:00","og_image":[{"width":768,"height":1109,"url":"https:\/\/www.dmr.go.th\/wp-content\/uploads\/2022\/10\/default_img-1.jpg","type":"image\/jpeg"}],"author":"\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e18\u0e23\u0e13\u0e35\u0e27\u0e34\u0e17\u0e22\u0e32\u0e2a\u0e34\u0e48\u0e07\u0e41\u0e27\u0e14\u0e25\u0e49\u0e2d\u0e21\u0e41\u0e25\u0e30\u0e18\u0e23\u0e13\u0e35\u0e1e\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e20\u0e31\u0e22","twitter_card":"summary_large_image","twitter_misc":{"Written by":"\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e18\u0e23\u0e13\u0e35\u0e27\u0e34\u0e17\u0e22\u0e32\u0e2a\u0e34\u0e48\u0e07\u0e41\u0e27\u0e14\u0e25\u0e49\u0e2d\u0e21\u0e41\u0e25\u0e30\u0e18\u0e23\u0e13\u0e35\u0e1e\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e20\u0e31\u0e22"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.dmr.go.th\/%e0%b8%a3%e0%b8%b2%e0%b8%a2%e0%b8%87%e0%b8%b2%e0%b8%99%e0%b8%aa%e0%b8%96%e0%b8%b2%e0%b8%99%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%93%e0%b9%8c%e0%b8%98%e0%b8%a3%e0%b8%93%e0%b8%b5%e0%b8%9e%e0%b8%b4%e0%b8%9a%e0%b8%b1%e0%b8%95%e0%b8%b4%e0%b8%a0%e0%b8%b1%e0%b8%a2-%e0%b8%aa%e0%b8%a0%e0%b8%b2%e0%b8%9e%e0%b8%ad%e0%b8%b2%e0%b8%81%e0%b8%b2%e0%b8%a8-%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b8%88%e0%b8%b3%e0%b8%a7%e0%b8%b1%e0%b8%99%e0%b8%ad%e0%b8%b2%e0%b8%97%e0%b8%b4%e0%b8%95%e0%b8%a2%e0%b9%8c%e0%b8%97%e0%b8%b5%e0%b9%88-%e0%b9%91%e0%b9%93-%e0%b8%81%e0%b8%b8%e0%b8%a1%e0%b8%a0%e0%b8%b2%e0%b8%9e%e0%b8%b1%e0%b8%99%e0%b8%98%e0%b9%8c-%e0%b9%92%e0%b9%95%e0%b9%95%e0%b9%94\/#article","isPartOf":{"@id":"https:\/\/www.dmr.go.th\/%e0%b8%a3%e0%b8%b2%e0%b8%a2%e0%b8%87%e0%b8%b2%e0%b8%99%e0%b8%aa%e0%b8%96%e0%b8%b2%e0%b8%99%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%93%e0%b9%8c%e0%b8%98%e0%b8%a3%e0%b8%93%e0%b8%b5%e0%b8%9e%e0%b8%b4%e0%b8%9a%e0%b8%b1%e0%b8%95%e0%b8%b4%e0%b8%a0%e0%b8%b1%e0%b8%a2-%e0%b8%aa%e0%b8%a0%e0%b8%b2%e0%b8%9e%e0%b8%ad%e0%b8%b2%e0%b8%81%e0%b8%b2%e0%b8%a8-%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b8%88%e0%b8%b3%e0%b8%a7%e0%b8%b1%e0%b8%99%e0%b8%ad%e0%b8%b2%e0%b8%97%e0%b8%b4%e0%b8%95%e0%b8%a2%e0%b9%8c%e0%b8%97%e0%b8%b5%e0%b9%88-%e0%b9%91%e0%b9%93-%e0%b8%81%e0%b8%b8%e0%b8%a1%e0%b8%a0%e0%b8%b2%e0%b8%9e%e0%b8%b1%e0%b8%99%e0%b8%98%e0%b9%8c-%e0%b9%92%e0%b9%95%e0%b9%95%e0%b9%94\/"},"author":{"name":"\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e18\u0e23\u0e13\u0e35\u0e27\u0e34\u0e17\u0e22\u0e32\u0e2a\u0e34\u0e48\u0e07\u0e41\u0e27\u0e14\u0e25\u0e49\u0e2d\u0e21\u0e41\u0e25\u0e30\u0e18\u0e23\u0e13\u0e35\u0e1e\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e20\u0e31\u0e22","@id":"https:\/\/www.dmr.go.th\/#\/schema\/person\/f4bc4dd56ee9041de4a03c606749e2bc"},"headline":"\u0e23\u0e32\u0e22\u0e07\u0e32\u0e19\u0e2a\u0e16\u0e32\u0e19\u0e01\u0e32\u0e23\u0e13\u0e4c\u0e18\u0e23\u0e13\u0e35\u0e1e\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e20\u0e31\u0e22 \u0e2a\u0e20\u0e32\u0e1e\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e1b\u0e23\u0e30\u0e08\u0e33\u0e27\u0e31\u0e19\u0e2d\u0e32\u0e17\u0e34\u0e15\u0e22\u0e4c\u0e17\u0e35\u0e48 \u0e51\u0e53 \u0e01\u0e38\u0e21\u0e20\u0e32\u0e1e\u0e31\u0e19\u0e18\u0e4c \u0e52\u0e55\u0e55\u0e54","datePublished":"2011-02-13T04:08:00+00:00","mainEntityOfPage":{"@id":"https:\/\/www.dmr.go.th\/%e0%b8%a3%e0%b8%b2%e0%b8%a2%e0%b8%87%e0%b8%b2%e0%b8%99%e0%b8%aa%e0%b8%96%e0%b8%b2%e0%b8%99%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%93%e0%b9%8c%e0%b8%98%e0%b8%a3%e0%b8%93%e0%b8%b5%e0%b8%9e%e0%b8%b4%e0%b8%9a%e0%b8%b1%e0%b8%95%e0%b8%b4%e0%b8%a0%e0%b8%b1%e0%b8%a2-%e0%b8%aa%e0%b8%a0%e0%b8%b2%e0%b8%9e%e0%b8%ad%e0%b8%b2%e0%b8%81%e0%b8%b2%e0%b8%a8-%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b8%88%e0%b8%b3%e0%b8%a7%e0%b8%b1%e0%b8%99%e0%b8%ad%e0%b8%b2%e0%b8%97%e0%b8%b4%e0%b8%95%e0%b8%a2%e0%b9%8c%e0%b8%97%e0%b8%b5%e0%b9%88-%e0%b9%91%e0%b9%93-%e0%b8%81%e0%b8%b8%e0%b8%a1%e0%b8%a0%e0%b8%b2%e0%b8%9e%e0%b8%b1%e0%b8%99%e0%b8%98%e0%b9%8c-%e0%b9%92%e0%b9%95%e0%b9%95%e0%b9%94\/"},"wordCount":20,"publisher":{"@id":"https:\/\/www.dmr.go.th\/#organization"},"image":{"@id":"https:\/\/www.dmr.go.th\/%e0%b8%a3%e0%b8%b2%e0%b8%a2%e0%b8%87%e0%b8%b2%e0%b8%99%e0%b8%aa%e0%b8%96%e0%b8%b2%e0%b8%99%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%93%e0%b9%8c%e0%b8%98%e0%b8%a3%e0%b8%93%e0%b8%b5%e0%b8%9e%e0%b8%b4%e0%b8%9a%e0%b8%b1%e0%b8%95%e0%b8%b4%e0%b8%a0%e0%b8%b1%e0%b8%a2-%e0%b8%aa%e0%b8%a0%e0%b8%b2%e0%b8%9e%e0%b8%ad%e0%b8%b2%e0%b8%81%e0%b8%b2%e0%b8%a8-%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b8%88%e0%b8%b3%e0%b8%a7%e0%b8%b1%e0%b8%99%e0%b8%ad%e0%b8%b2%e0%b8%97%e0%b8%b4%e0%b8%95%e0%b8%a2%e0%b9%8c%e0%b8%97%e0%b8%b5%e0%b9%88-%e0%b9%91%e0%b9%93-%e0%b8%81%e0%b8%b8%e0%b8%a1%e0%b8%a0%e0%b8%b2%e0%b8%9e%e0%b8%b1%e0%b8%99%e0%b8%98%e0%b9%8c-%e0%b9%92%e0%b9%95%e0%b9%95%e0%b9%94\/#primaryimage"},"thumbnailUrl":"https:\/\/www.dmr.go.th\/wp-content\/uploads\/2022\/10\/default_img-1.jpg","articleSection":["\u0e23\u0e32\u0e22\u0e07\u0e32\u0e19\u0e2a\u0e16\u0e32\u0e19\u0e01\u0e32\u0e23\u0e13\u0e4c\u0e18\u0e23\u0e13\u0e35\u0e1e\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e20\u0e31\u0e22\u0e1b\u0e23\u0e30\u0e08\u0e33\u0e27\u0e31\u0e19"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/www.dmr.go.th\/%e0%b8%a3%e0%b8%b2%e0%b8%a2%e0%b8%87%e0%b8%b2%e0%b8%99%e0%b8%aa%e0%b8%96%e0%b8%b2%e0%b8%99%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%93%e0%b9%8c%e0%b8%98%e0%b8%a3%e0%b8%93%e0%b8%b5%e0%b8%9e%e0%b8%b4%e0%b8%9a%e0%b8%b1%e0%b8%95%e0%b8%b4%e0%b8%a0%e0%b8%b1%e0%b8%a2-%e0%b8%aa%e0%b8%a0%e0%b8%b2%e0%b8%9e%e0%b8%ad%e0%b8%b2%e0%b8%81%e0%b8%b2%e0%b8%a8-%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b8%88%e0%b8%b3%e0%b8%a7%e0%b8%b1%e0%b8%99%e0%b8%ad%e0%b8%b2%e0%b8%97%e0%b8%b4%e0%b8%95%e0%b8%a2%e0%b9%8c%e0%b8%97%e0%b8%b5%e0%b9%88-%e0%b9%91%e0%b9%93-%e0%b8%81%e0%b8%b8%e0%b8%a1%e0%b8%a0%e0%b8%b2%e0%b8%9e%e0%b8%b1%e0%b8%99%e0%b8%98%e0%b9%8c-%e0%b9%92%e0%b9%95%e0%b9%95%e0%b9%94\/","url":"https:\/\/www.dmr.go.th\/%e0%b8%a3%e0%b8%b2%e0%b8%a2%e0%b8%87%e0%b8%b2%e0%b8%99%e0%b8%aa%e0%b8%96%e0%b8%b2%e0%b8%99%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%93%e0%b9%8c%e0%b8%98%e0%b8%a3%e0%b8%93%e0%b8%b5%e0%b8%9e%e0%b8%b4%e0%b8%9a%e0%b8%b1%e0%b8%95%e0%b8%b4%e0%b8%a0%e0%b8%b1%e0%b8%a2-%e0%b8%aa%e0%b8%a0%e0%b8%b2%e0%b8%9e%e0%b8%ad%e0%b8%b2%e0%b8%81%e0%b8%b2%e0%b8%a8-%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b8%88%e0%b8%b3%e0%b8%a7%e0%b8%b1%e0%b8%99%e0%b8%ad%e0%b8%b2%e0%b8%97%e0%b8%b4%e0%b8%95%e0%b8%a2%e0%b9%8c%e0%b8%97%e0%b8%b5%e0%b9%88-%e0%b9%91%e0%b9%93-%e0%b8%81%e0%b8%b8%e0%b8%a1%e0%b8%a0%e0%b8%b2%e0%b8%9e%e0%b8%b1%e0%b8%99%e0%b8%98%e0%b9%8c-%e0%b9%92%e0%b9%95%e0%b9%95%e0%b9%94\/","name":"\u0e23\u0e32\u0e22\u0e07\u0e32\u0e19\u0e2a\u0e16\u0e32\u0e19\u0e01\u0e32\u0e23\u0e13\u0e4c\u0e18\u0e23\u0e13\u0e35\u0e1e\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e20\u0e31\u0e22 \u0e2a\u0e20\u0e32\u0e1e\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e1b\u0e23\u0e30\u0e08\u0e33\u0e27\u0e31\u0e19\u0e2d\u0e32\u0e17\u0e34\u0e15\u0e22\u0e4c\u0e17\u0e35\u0e48 \u0e51\u0e53 \u0e01\u0e38\u0e21\u0e20\u0e32\u0e1e\u0e31\u0e19\u0e18\u0e4c \u0e52\u0e55\u0e55\u0e54 - \u0e01\u0e23\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e32\u0e01\u0e23\u0e18\u0e23\u0e13\u0e35","isPartOf":{"@id":"https:\/\/www.dmr.go.th\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.dmr.go.th\/%e0%b8%a3%e0%b8%b2%e0%b8%a2%e0%b8%87%e0%b8%b2%e0%b8%99%e0%b8%aa%e0%b8%96%e0%b8%b2%e0%b8%99%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%93%e0%b9%8c%e0%b8%98%e0%b8%a3%e0%b8%93%e0%b8%b5%e0%b8%9e%e0%b8%b4%e0%b8%9a%e0%b8%b1%e0%b8%95%e0%b8%b4%e0%b8%a0%e0%b8%b1%e0%b8%a2-%e0%b8%aa%e0%b8%a0%e0%b8%b2%e0%b8%9e%e0%b8%ad%e0%b8%b2%e0%b8%81%e0%b8%b2%e0%b8%a8-%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b8%88%e0%b8%b3%e0%b8%a7%e0%b8%b1%e0%b8%99%e0%b8%ad%e0%b8%b2%e0%b8%97%e0%b8%b4%e0%b8%95%e0%b8%a2%e0%b9%8c%e0%b8%97%e0%b8%b5%e0%b9%88-%e0%b9%91%e0%b9%93-%e0%b8%81%e0%b8%b8%e0%b8%a1%e0%b8%a0%e0%b8%b2%e0%b8%9e%e0%b8%b1%e0%b8%99%e0%b8%98%e0%b9%8c-%e0%b9%92%e0%b9%95%e0%b9%95%e0%b9%94\/#primaryimage"},"image":{"@id":"https:\/\/www.dmr.go.th\/%e0%b8%a3%e0%b8%b2%e0%b8%a2%e0%b8%87%e0%b8%b2%e0%b8%99%e0%b8%aa%e0%b8%96%e0%b8%b2%e0%b8%99%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%93%e0%b9%8c%e0%b8%98%e0%b8%a3%e0%b8%93%e0%b8%b5%e0%b8%9e%e0%b8%b4%e0%b8%9a%e0%b8%b1%e0%b8%95%e0%b8%b4%e0%b8%a0%e0%b8%b1%e0%b8%a2-%e0%b8%aa%e0%b8%a0%e0%b8%b2%e0%b8%9e%e0%b8%ad%e0%b8%b2%e0%b8%81%e0%b8%b2%e0%b8%a8-%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b8%88%e0%b8%b3%e0%b8%a7%e0%b8%b1%e0%b8%99%e0%b8%ad%e0%b8%b2%e0%b8%97%e0%b8%b4%e0%b8%95%e0%b8%a2%e0%b9%8c%e0%b8%97%e0%b8%b5%e0%b9%88-%e0%b9%91%e0%b9%93-%e0%b8%81%e0%b8%b8%e0%b8%a1%e0%b8%a0%e0%b8%b2%e0%b8%9e%e0%b8%b1%e0%b8%99%e0%b8%98%e0%b9%8c-%e0%b9%92%e0%b9%95%e0%b9%95%e0%b9%94\/#primaryimage"},"thumbnailUrl":"https:\/\/www.dmr.go.th\/wp-content\/uploads\/2022\/10\/default_img-1.jpg","datePublished":"2011-02-13T04:08:00+00:00","breadcrumb":{"@id":"https:\/\/www.dmr.go.th\/%e0%b8%a3%e0%b8%b2%e0%b8%a2%e0%b8%87%e0%b8%b2%e0%b8%99%e0%b8%aa%e0%b8%96%e0%b8%b2%e0%b8%99%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%93%e0%b9%8c%e0%b8%98%e0%b8%a3%e0%b8%93%e0%b8%b5%e0%b8%9e%e0%b8%b4%e0%b8%9a%e0%b8%b1%e0%b8%95%e0%b8%b4%e0%b8%a0%e0%b8%b1%e0%b8%a2-%e0%b8%aa%e0%b8%a0%e0%b8%b2%e0%b8%9e%e0%b8%ad%e0%b8%b2%e0%b8%81%e0%b8%b2%e0%b8%a8-%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b8%88%e0%b8%b3%e0%b8%a7%e0%b8%b1%e0%b8%99%e0%b8%ad%e0%b8%b2%e0%b8%97%e0%b8%b4%e0%b8%95%e0%b8%a2%e0%b9%8c%e0%b8%97%e0%b8%b5%e0%b9%88-%e0%b9%91%e0%b9%93-%e0%b8%81%e0%b8%b8%e0%b8%a1%e0%b8%a0%e0%b8%b2%e0%b8%9e%e0%b8%b1%e0%b8%99%e0%b8%98%e0%b9%8c-%e0%b9%92%e0%b9%95%e0%b9%95%e0%b9%94\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.dmr.go.th\/%e0%b8%a3%e0%b8%b2%e0%b8%a2%e0%b8%87%e0%b8%b2%e0%b8%99%e0%b8%aa%e0%b8%96%e0%b8%b2%e0%b8%99%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%93%e0%b9%8c%e0%b8%98%e0%b8%a3%e0%b8%93%e0%b8%b5%e0%b8%9e%e0%b8%b4%e0%b8%9a%e0%b8%b1%e0%b8%95%e0%b8%b4%e0%b8%a0%e0%b8%b1%e0%b8%a2-%e0%b8%aa%e0%b8%a0%e0%b8%b2%e0%b8%9e%e0%b8%ad%e0%b8%b2%e0%b8%81%e0%b8%b2%e0%b8%a8-%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b8%88%e0%b8%b3%e0%b8%a7%e0%b8%b1%e0%b8%99%e0%b8%ad%e0%b8%b2%e0%b8%97%e0%b8%b4%e0%b8%95%e0%b8%a2%e0%b9%8c%e0%b8%97%e0%b8%b5%e0%b9%88-%e0%b9%91%e0%b9%93-%e0%b8%81%e0%b8%b8%e0%b8%a1%e0%b8%a0%e0%b8%b2%e0%b8%9e%e0%b8%b1%e0%b8%99%e0%b8%98%e0%b9%8c-%e0%b9%92%e0%b9%95%e0%b9%95%e0%b9%94\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.dmr.go.th\/%e0%b8%a3%e0%b8%b2%e0%b8%a2%e0%b8%87%e0%b8%b2%e0%b8%99%e0%b8%aa%e0%b8%96%e0%b8%b2%e0%b8%99%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%93%e0%b9%8c%e0%b8%98%e0%b8%a3%e0%b8%93%e0%b8%b5%e0%b8%9e%e0%b8%b4%e0%b8%9a%e0%b8%b1%e0%b8%95%e0%b8%b4%e0%b8%a0%e0%b8%b1%e0%b8%a2-%e0%b8%aa%e0%b8%a0%e0%b8%b2%e0%b8%9e%e0%b8%ad%e0%b8%b2%e0%b8%81%e0%b8%b2%e0%b8%a8-%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b8%88%e0%b8%b3%e0%b8%a7%e0%b8%b1%e0%b8%99%e0%b8%ad%e0%b8%b2%e0%b8%97%e0%b8%b4%e0%b8%95%e0%b8%a2%e0%b9%8c%e0%b8%97%e0%b8%b5%e0%b9%88-%e0%b9%91%e0%b9%93-%e0%b8%81%e0%b8%b8%e0%b8%a1%e0%b8%a0%e0%b8%b2%e0%b8%9e%e0%b8%b1%e0%b8%99%e0%b8%98%e0%b9%8c-%e0%b9%92%e0%b9%95%e0%b9%95%e0%b9%94\/#primaryimage","url":"https:\/\/www.dmr.go.th\/wp-content\/uploads\/2022\/10\/default_img-1.jpg","contentUrl":"https:\/\/www.dmr.go.th\/wp-content\/uploads\/2022\/10\/default_img-1.jpg","width":768,"height":1109,"caption":"\u0e23\u0e39\u0e1b\u0e20\u0e32\u0e1e\u0e02\u0e2d\u0e07\u0e01\u0e23\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e32\u0e01\u0e23\u0e18\u0e23\u0e13\u0e35"},{"@type":"BreadcrumbList","@id":"https:\/\/www.dmr.go.th\/%e0%b8%a3%e0%b8%b2%e0%b8%a2%e0%b8%87%e0%b8%b2%e0%b8%99%e0%b8%aa%e0%b8%96%e0%b8%b2%e0%b8%99%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%93%e0%b9%8c%e0%b8%98%e0%b8%a3%e0%b8%93%e0%b8%b5%e0%b8%9e%e0%b8%b4%e0%b8%9a%e0%b8%b1%e0%b8%95%e0%b8%b4%e0%b8%a0%e0%b8%b1%e0%b8%a2-%e0%b8%aa%e0%b8%a0%e0%b8%b2%e0%b8%9e%e0%b8%ad%e0%b8%b2%e0%b8%81%e0%b8%b2%e0%b8%a8-%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b8%88%e0%b8%b3%e0%b8%a7%e0%b8%b1%e0%b8%99%e0%b8%ad%e0%b8%b2%e0%b8%97%e0%b8%b4%e0%b8%95%e0%b8%a2%e0%b9%8c%e0%b8%97%e0%b8%b5%e0%b9%88-%e0%b9%91%e0%b9%93-%e0%b8%81%e0%b8%b8%e0%b8%a1%e0%b8%a0%e0%b8%b2%e0%b8%9e%e0%b8%b1%e0%b8%99%e0%b8%98%e0%b9%8c-%e0%b9%92%e0%b9%95%e0%b9%95%e0%b9%94\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.dmr.go.th\/"},{"@type":"ListItem","position":2,"name":"\u0e23\u0e32\u0e22\u0e07\u0e32\u0e19\u0e2a\u0e16\u0e32\u0e19\u0e01\u0e32\u0e23\u0e13\u0e4c\u0e18\u0e23\u0e13\u0e35\u0e1e\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e20\u0e31\u0e22 \u0e2a\u0e20\u0e32\u0e1e\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e1b\u0e23\u0e30\u0e08\u0e33\u0e27\u0e31\u0e19\u0e2d\u0e32\u0e17\u0e34\u0e15\u0e22\u0e4c\u0e17\u0e35\u0e48 \u0e51\u0e53 \u0e01\u0e38\u0e21\u0e20\u0e32\u0e1e\u0e31\u0e19\u0e18\u0e4c \u0e52\u0e55\u0e55\u0e54"}]},{"@type":"WebSite","@id":"https:\/\/www.dmr.go.th\/#website","url":"https:\/\/www.dmr.go.th\/","name":"\u0e01\u0e23\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e32\u0e01\u0e23\u0e18\u0e23\u0e13\u0e35","description":"\u0e01\u0e23\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e32\u0e01\u0e23\u0e18\u0e23\u0e13\u0e35","publisher":{"@id":"https:\/\/www.dmr.go.th\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.dmr.go.th\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.dmr.go.th\/#organization","name":"\u0e01\u0e23\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e32\u0e01\u0e23\u0e18\u0e23\u0e13\u0e35","url":"https:\/\/www.dmr.go.th\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.dmr.go.th\/#\/schema\/logo\/image\/","url":"https:\/\/www.dmr.go.th\/wp-content\/uploads\/2022\/08\/\u0e15\u0e23\u0e32\u0e01\u0e23\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e32\u0e01\u0e23\u0e18\u0e23\u0e13\u0e35-2.png","contentUrl":"https:\/\/www.dmr.go.th\/wp-content\/uploads\/2022\/08\/\u0e15\u0e23\u0e32\u0e01\u0e23\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e32\u0e01\u0e23\u0e18\u0e23\u0e13\u0e35-2.png","width":400,"height":400,"caption":"\u0e01\u0e23\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e32\u0e01\u0e23\u0e18\u0e23\u0e13\u0e35"},"image":{"@id":"https:\/\/www.dmr.go.th\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.dmr.go.th\/#\/schema\/person\/f4bc4dd56ee9041de4a03c606749e2bc","name":"\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e18\u0e23\u0e13\u0e35\u0e27\u0e34\u0e17\u0e22\u0e32\u0e2a\u0e34\u0e48\u0e07\u0e41\u0e27\u0e14\u0e25\u0e49\u0e2d\u0e21\u0e41\u0e25\u0e30\u0e18\u0e23\u0e13\u0e35\u0e1e\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e20\u0e31\u0e22","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.dmr.go.th\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/16cd7e279959e64661a4e273e93548cbadc539d0c3f9f0db93f4c4c1c30720c0?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/16cd7e279959e64661a4e273e93548cbadc539d0c3f9f0db93f4c4c1c30720c0?s=96&d=mm&r=g","caption":"\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e18\u0e23\u0e13\u0e35\u0e27\u0e34\u0e17\u0e22\u0e32\u0e2a\u0e34\u0e48\u0e07\u0e41\u0e27\u0e14\u0e25\u0e49\u0e2d\u0e21\u0e41\u0e25\u0e30\u0e18\u0e23\u0e13\u0e35\u0e1e\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e20\u0e31\u0e22"},"sameAs":["https:\/\/www.dmr.go.th"],"url":"https:\/\/www.dmr.go.th\/en\/author\/amika-bcipher-co-th\/"}]}},"_links":{"self":[{"href":"https:\/\/www.dmr.go.th\/en\/wp-json\/wp\/v2\/posts\/156624","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.dmr.go.th\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.dmr.go.th\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.dmr.go.th\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.dmr.go.th\/en\/wp-json\/wp\/v2\/comments?post=156624"}],"version-history":[{"count":0,"href":"https:\/\/www.dmr.go.th\/en\/wp-json\/wp\/v2\/posts\/156624\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.dmr.go.th\/en\/wp-json\/wp\/v2\/media\/151535"}],"wp:attachment":[{"href":"https:\/\/www.dmr.go.th\/en\/wp-json\/wp\/v2\/media?parent=156624"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.dmr.go.th\/en\/wp-json\/wp\/v2\/categories?post=156624"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.dmr.go.th\/en\/wp-json\/wp\/v2\/tags?post=156624"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}