{"id":172299,"date":"2009-12-03T18:10:14","date_gmt":"2009-12-03T11:10:14","guid":{"rendered":""},"modified":"2009-12-03T18:10:14","modified_gmt":"2009-12-03T11:10:14","slug":"%e0%b8%98%e0%b8%a3%e0%b8%93%e0%b8%b5%e0%b8%a7%e0%b8%b4%e0%b8%97%e0%b8%a2%e0%b8%b2%e0%b8%81%e0%b8%b1%e0%b8%9a%e0%b8%87%e0%b8%b2%e0%b8%99%e0%b8%9f%e0%b8%b7%e0%b9%89%e0%b8%99%e0%b8%9f%e0%b8%b9%e0%b9%83%e0%b8%99%e0%b8%9e%e0%b8%b7%e0%b9%89%e0%b8%99%e0%b8%97%e0%b8%b5%e0%b9%88%e0%b9%84%e0%b8%94%e0%b9%89%e0%b8%a3%e0%b8%b1%e0%b8%9a%e0%b8%9c%e0%b8%a5%e0%b8%81%e0%b8%a3%e0%b8%b0%e0%b8%97%e0%b8%9a%e0%b8%98%e0%b8%a3%e0%b8%93%e0%b8%b5%e0%b8%9e%e0%b8%b4%e0%b8%9a%e0%b8%b1%e0%b8%95%e0%b8%b4%e0%b8%a0%e0%b8%b1%e0%b8%a2","status":"publish","type":"post","link":"https:\/\/www.dmr.go.th\/en\/%e0%b8%98%e0%b8%a3%e0%b8%93%e0%b8%b5%e0%b8%a7%e0%b8%b4%e0%b8%97%e0%b8%a2%e0%b8%b2%e0%b8%81%e0%b8%b1%e0%b8%9a%e0%b8%87%e0%b8%b2%e0%b8%99%e0%b8%9f%e0%b8%b7%e0%b9%89%e0%b8%99%e0%b8%9f%e0%b8%b9%e0%b9%83%e0%b8%99%e0%b8%9e%e0%b8%b7%e0%b9%89%e0%b8%99%e0%b8%97%e0%b8%b5%e0%b9%88%e0%b9%84%e0%b8%94%e0%b9%89%e0%b8%a3%e0%b8%b1%e0%b8%9a%e0%b8%9c%e0%b8%a5%e0%b8%81%e0%b8%a3%e0%b8%b0%e0%b8%97%e0%b8%9a%e0%b8%98%e0%b8%a3%e0%b8%93%e0%b8%b5%e0%b8%9e%e0%b8%b4%e0%b8%9a%e0%b8%b1%e0%b8%95%e0%b8%b4%e0%b8%a0%e0%b8%b1%e0%b8%a2\/","title":{"rendered":"\u0e18\u0e23\u0e13\u0e35\u0e27\u0e34\u0e17\u0e22\u0e32\u0e01\u0e31\u0e1a\u0e07\u0e32\u0e19\u0e1f\u0e37\u0e49\u0e19\u0e1f\u0e39\u0e43\u0e19\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e1c\u0e25\u0e01\u0e23\u0e30\u0e17\u0e1a\u0e18\u0e23\u0e13\u0e35\u0e1e\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e20\u0e31\u0e22"},"content":{"rendered":"<p>\u0e18\u0e23\u0e13\u0e35\u0e27\u0e34\u0e17\u0e22\u0e32\u0e01\u0e31\u0e1a\u0e07\u0e32\u0e19\u0e1f\u0e37\u0e49\u0e19\u0e1f\u0e39\u0e43\u0e19\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e1c\u0e25\u0e01\u0e23\u0e30\u0e17\u0e1a\u0e18\u0e23\u0e13\u0e35\u0e1e\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e20\u0e31\u0e22<br \/>\n\u0e19\u0e32\u0e22\u0e2d\u0e14\u0e34\u0e0a\u0e32\u0e15\u0e34 \u0e2a\u0e38\u0e23\u0e34\u0e19\u0e17\u0e23\u0e4c\u0e04\u0e33 \u0e1c\u0e39\u0e49\u0e2d\u0e33\u0e19\u0e27\u0e22\u0e01\u0e32\u0e23\u0e01\u0e2d\u0e07\u0e18\u0e23\u0e13\u0e35\u0e27\u0e34\u0e17\u0e22\u0e32\u0e2a\u0e34\u0e48\u0e07\u0e41\u0e27\u0e14\u0e25\u0e49\u0e2d\u0e21 \u0e19\u0e33\u0e2a\u0e37\u0e48\u0e2d\u0e21\u0e27\u0e25\u0e0a\u0e19\u0e25\u0e07\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e17\u0e35\u0e48\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e1c\u0e25\u0e01\u0e23\u0e30\u0e17\u0e1a\u0e08\u0e32\u0e01\u0e40\u0e2b\u0e15\u0e38\u0e18\u0e23\u0e13\u0e35\u0e1e\u0e34\u0e1a\u0e31\u0e15\u0e34 \u0e13 \u0e2d.\u0e1a\u0e48\u0e2d\u0e40\u0e01\u0e25\u0e37\u0e2d \u0e08.\u0e19\u0e48\u0e32\u0e19 \u0e16\u0e48\u0e32\u0e22\u0e17\u0e33\u0e2a\u0e01\u0e39\u0e4a\u0e1b\u0e02\u0e48\u0e32\u0e27\u0e07\u0e32\u0e19\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e41\u0e19\u0e27\u0e1b\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e19\u0e41\u0e25\u0e30\u0e1f\u0e37\u0e49\u0e19\u0e1f\u0e39\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e17\u0e35\u0e48\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e1c\u0e25\u0e01\u0e23\u0e30\u0e17\u0e1a\u0e08\u0e32\u0e01\u0e18\u0e23\u0e13\u0e35\u0e1e\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e20\u0e31\u0e22 \u0e01\u0e32\u0e23\u0e41\u0e01\u0e49\u0e44\u0e02\u0e1b\u0e31\u0e0d\u0e2b\u0e32\u0e08\u0e32\u0e01\u0e1c\u0e25\u0e01\u0e23\u0e30\u0e17\u0e1a\u0e14\u0e49\u0e32\u0e19\u0e18\u0e23\u0e13\u0e35\u0e27\u0e34\u0e17\u0e22\u0e32 \u0e41\u0e25\u0e30\u0e1b\u0e23\u0e30\u0e2a\u0e32\u0e19\u0e1b\u0e23\u0e30\u0e2a\u0e32\u0e19\u0e40\u0e04\u0e23\u0e37\u0e2d\u0e02\u0e48\u0e32\u0e22\u0e40\u0e1d\u0e49\u0e32\u0e23\u0e30\u0e27\u0e31\u0e07\u0e41\u0e08\u0e49\u0e07\u0e40\u0e2b\u0e15\u0e38\u0e18\u0e23\u0e13\u0e35\u0e1e\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e20\u0e31\u0e22 \u0e1c\u0e39\u0e49\u0e19\u0e33\u0e0a\u0e38\u0e21\u0e0a\u0e19 \u0e40\u0e0a\u0e48\u0e19 \u0e19\u0e32\u0e22\u0e01 \u0e2d\u0e1a\u0e15. \u0e2d\u0e1a\u0e15. \u0e1c\u0e39\u0e49\u0e43\u0e2b\u0e0d\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e1c\u0e39\u0e49\u0e0a\u0e48\u0e27\u0e22\u0e1c\u0e39\u0e49\u0e43\u0e2b\u0e0d\u0e48\u0e1a\u0e49\u0e32\u0e19  \u0e1c\u0e39\u0e49\u0e21\u0e35\u0e2a\u0e48\u0e27\u0e19\u0e44\u0e14\u0e49\u0e2a\u0e48\u0e27\u0e19\u0e40\u0e2a\u0e35\u0e22\u0e43\u0e19\u0e01\u0e32\u0e23\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e17\u0e33\u0e41\u0e19\u0e27\u0e01\u0e32\u0e23\u0e1b\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e19\u0e41\u0e25\u0e30\u0e1f\u0e37\u0e49\u0e19\u0e1f\u0e39\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e30\u0e2a\u0e1a\u0e20\u0e31\u0e22\u0e14\u0e34\u0e19\u0e16\u0e25\u0e48\u0e21 \u0e43\u0e19\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e20\u0e39\u0e1f\u0e49\u0e32 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e27\u0e32\u0e07\u0e41\u0e1c\u0e19\u0e43\u0e19\u0e01\u0e32\u0e23\u0e40\u0e02\u0e49\u0e32\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e01\u0e32\u0e23\u0e1b\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e19\u0e41\u0e25\u0e30\u0e1f\u0e37\u0e49\u0e19\u0e1f\u0e39\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e30\u0e2a\u0e1a\u0e20\u0e31\u0e22\u0e14\u0e34\u0e19\u0e16\u0e25\u0e48\u0e21 \u0e0b\u0e36\u0e48\u0e07\u0e2a\u0e01\u0e39\u0e4a\u0e1b\u0e02\u0e48\u0e32\u0e27 2 \u0e19\u0e32\u0e17\u0e35 \u0e21\u0e35\u0e17\u0e31\u0e49\u0e07\u0e2b\u0e21\u0e14 4 \u0e15\u0e2d\u0e19 \u0e0b\u0e36\u0e48\u0e07\u0e21\u0e35\u0e01\u0e33\u0e2b\u0e19\u0e14\u0e2d\u0e2d\u0e01\u0e2d\u0e32\u0e01\u0e32\u0e28\u0e17\u0e32\u0e07\u0e2a\u0e16\u0e32\u0e19\u0e35\u0e42\u0e17\u0e23\u0e17\u0e31\u0e28\u0e19\u0e4c\u0e42\u0e21\u0e40\u0e14\u0e34\u0e23\u0e4c\u0e19\u0e44\u0e19\u0e17\u0e4c\u0e17\u0e35\u0e27\u0e35 \u0e40\u0e27\u0e25\u0e32\u0e1b\u0e23\u0e30\u0e21\u0e32\u0e13 19.20-19.40 \u0e19. \u0e14\u0e31\u0e07\u0e19\u0e35\u0e49<br \/>\n1. \u0e27\u0e31\u0e19\u0e1e\u0e24\u0e2b\u0e31\u0e2a\u0e1a\u0e14\u0e35\u0e17\u0e35\u0e48 3 \u0e18\u0e31\u0e19\u0e27\u0e32\u0e04\u0e21 2552    \u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07 \u0e1a\u0e48\u0e2d\u0e40\u0e01\u0e25\u0e37\u0e2d\u0e1a\u0e19\u0e20\u0e39\u0e40\u0e02\u0e32<br \/>\n2. \u0e27\u0e31\u0e19\u0e2d\u0e31\u0e07\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48 8 \u0e18\u0e31\u0e19\u0e27\u0e32\u0e04\u0e21 2552          \u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07 \u0e1b\u0e38\u0e4b\u0e22\u0e2d\u0e34\u0e19\u0e17\u0e23\u0e35\u0e22\u0e4c\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e41\u0e01\u0e49\u0e1b\u0e31\u0e0d\u0e2b\u0e32\u0e14\u0e34\u0e19\u0e16\u0e25\u0e48\u0e21<br \/>\n3. \u0e27\u0e31\u0e19\u0e1e\u0e38\u0e18\u0e17\u0e35\u0e48 9 \u0e18\u0e31\u0e19\u0e27\u0e32\u0e04\u0e21 2552        \u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07 \u0e40\u0e22\u0e32\u0e27\u0e0a\u0e19\u0e23\u0e31\u0e01\u0e29\u0e4c\u0e20\u0e39\u0e1f\u0e49\u0e32\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e23\u0e31\u0e01\u0e29\u0e32\u0e2a\u0e34\u0e48\u0e07\u0e41\u0e27\u0e14\u0e25\u0e49\u0e2d\u0e21<br \/>\n4. \u0e27\u0e31\u0e19\u0e2d\u0e31\u0e07\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48 15 \u0e18\u0e31\u0e19\u0e27\u0e32\u0e04\u0e21 2552                      \u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07 \u0e15\u0e49\u0e19\u0e41\u0e1a\u0e1a\u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 (\u0e1f\u0e37\u0e49\u0e19\u0e1f\u0e39\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e30\u0e2a\u0e1a\u0e20\u0e31\u0e22\u0e14\u0e34\u0e19\u0e16\u0e25\u0e48\u0e21)<br \/>\n\u0e02\u0e2d\u0e40\u0e0a\u0e34\u0e0d\u0e02\u0e49\u0e32\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23 \u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48\u0e01\u0e23\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e32\u0e01\u0e23\u0e18\u0e23\u0e13\u0e35\u0e17\u0e38\u0e01\u0e17\u0e48\u0e32\u0e19\u0e15\u0e34\u0e14\u0e15\u0e32\u0e21\u0e0a\u0e21\u0e2a\u0e01\u0e39\u0e4a\u0e1b\u0e02\u0e48\u0e32\u0e27\u0e44\u0e14\u0e49\u0e15\u0e32\u0e21\u0e27\u0e31\u0e19\u0e40\u0e27\u0e25\u0e32\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u0e18\u0e23\u0e13\u0e35\u0e27\u0e34\u0e17\u0e22\u0e32\u0e01\u0e31\u0e1a\u0e07\u0e32\u0e19\u0e1f\u0e37\u0e49\u0e19\u0e1f\u0e39\u0e43\u0e19\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e1c\u0e25\u0e01\u0e23\u0e30\u0e17\u0e1a\u0e18\u0e23\u0e13\u0e35\u0e1e\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e20\u0e31\u0e22 \u0e19\u0e32\u0e22\u0e2d\u0e14\u0e34\u0e0a\u0e32\u0e15\u0e34 \u0e2a\u0e38\u0e23\u0e34\u0e19\u0e17\u0e23\u0e4c\u0e04\u0e33 \u0e1c\u0e39\u0e49\u0e2d\u0e33\u0e19\u0e27\u0e22\u0e01\u0e32\u0e23\u0e01\u0e2d\u0e07\u0e18\u0e23\u0e13\u0e35\u0e27\u0e34\u0e17\u0e22\u0e32\u0e2a\u0e34\u0e48\u0e07\u0e41\u0e27\u0e14\u0e25\u0e49\u0e2d\u0e21 \u0e19\u0e33\u0e2a\u0e37\u0e48\u0e2d\u0e21\u0e27\u0e25\u0e0a\u0e19\u0e25\u0e07\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e17\u0e35\u0e48\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e1c\u0e25\u0e01\u0e23\u0e30\u0e17\u0e1a\u0e08\u0e32\u0e01\u0e40\u0e2b\u0e15\u0e38\u0e18\u0e23\u0e13\u0e35\u0e1e\u0e34\u0e1a\u0e31\u0e15\u0e34 \u0e13 \u0e2d.\u0e1a\u0e48\u0e2d\u0e40\u0e01\u0e25\u0e37\u0e2d \u0e08.\u0e19\u0e48\u0e32\u0e19 \u0e16\u0e48\u0e32\u0e22\u0e17\u0e33\u0e2a\u0e01\u0e39\u0e4a\u0e1b\u0e02\u0e48\u0e32\u0e27\u0e07\u0e32\u0e19\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e41\u0e19\u0e27\u0e1b\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e19\u0e41\u0e25\u0e30\u0e1f\u0e37\u0e49\u0e19\u0e1f\u0e39\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e17\u0e35\u0e48\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e1c\u0e25\u0e01\u0e23\u0e30\u0e17\u0e1a\u0e08\u0e32\u0e01\u0e18\u0e23\u0e13\u0e35\u0e1e\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e20\u0e31\u0e22 \u0e01\u0e32\u0e23\u0e41\u0e01\u0e49\u0e44\u0e02\u0e1b\u0e31\u0e0d\u0e2b\u0e32\u0e08\u0e32\u0e01\u0e1c\u0e25\u0e01\u0e23\u0e30\u0e17\u0e1a\u0e14\u0e49\u0e32\u0e19\u0e18\u0e23\u0e13\u0e35\u0e27\u0e34\u0e17\u0e22\u0e32 \u0e41\u0e25\u0e30\u0e1b\u0e23\u0e30\u0e2a\u0e32\u0e19\u0e1b\u0e23\u0e30\u0e2a\u0e32\u0e19\u0e40\u0e04\u0e23\u0e37\u0e2d\u0e02\u0e48\u0e32\u0e22\u0e40\u0e1d\u0e49\u0e32\u0e23\u0e30\u0e27\u0e31\u0e07\u0e41\u0e08\u0e49\u0e07\u0e40\u0e2b\u0e15\u0e38\u0e18\u0e23\u0e13\u0e35\u0e1e\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e20\u0e31\u0e22 \u0e1c\u0e39\u0e49\u0e19\u0e33\u0e0a\u0e38\u0e21\u0e0a\u0e19 \u0e40\u0e0a\u0e48\u0e19 \u0e19\u0e32\u0e22\u0e01 \u0e2d\u0e1a\u0e15. \u0e2d\u0e1a\u0e15. \u0e1c\u0e39\u0e49\u0e43\u0e2b\u0e0d\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e1c\u0e39\u0e49\u0e0a\u0e48\u0e27\u0e22\u0e1c\u0e39\u0e49\u0e43\u0e2b\u0e0d\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e1c\u0e39\u0e49\u0e21\u0e35\u0e2a\u0e48\u0e27\u0e19\u0e44\u0e14\u0e49\u0e2a\u0e48\u0e27\u0e19\u0e40\u0e2a\u0e35\u0e22\u0e43\u0e19\u0e01\u0e32\u0e23\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e17\u0e33\u0e41\u0e19\u0e27\u0e01\u0e32\u0e23\u0e1b\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e19\u0e41\u0e25\u0e30\u0e1f\u0e37\u0e49\u0e19\u0e1f\u0e39\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e30\u0e2a\u0e1a\u0e20\u0e31\u0e22\u0e14\u0e34\u0e19\u0e16\u0e25\u0e48\u0e21 \u0e43\u0e19\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e20\u0e39\u0e1f\u0e49\u0e32 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e27\u0e32\u0e07\u0e41\u0e1c\u0e19\u0e43\u0e19\u0e01\u0e32\u0e23\u0e40\u0e02\u0e49\u0e32\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e01\u0e32\u0e23\u0e1b\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e19\u0e41\u0e25\u0e30\u0e1f\u0e37\u0e49\u0e19\u0e1f\u0e39\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e30\u0e2a\u0e1a\u0e20\u0e31\u0e22\u0e14\u0e34\u0e19\u0e16\u0e25\u0e48\u0e21 \u0e0b\u0e36\u0e48\u0e07\u0e2a\u0e01\u0e39\u0e4a\u0e1b\u0e02\u0e48\u0e32\u0e27 2 \u0e19\u0e32\u0e17\u0e35 \u0e21\u0e35\u0e17\u0e31\u0e49\u0e07\u0e2b\u0e21\u0e14 4 \u0e15\u0e2d\u0e19 \u0e0b\u0e36\u0e48\u0e07\u0e21\u0e35\u0e01\u0e33\u0e2b\u0e19\u0e14\u0e2d\u0e2d\u0e01\u0e2d\u0e32\u0e01\u0e32\u0e28\u0e17\u0e32\u0e07\u0e2a\u0e16\u0e32\u0e19\u0e35\u0e42\u0e17\u0e23\u0e17\u0e31\u0e28\u0e19\u0e4c\u0e42\u0e21\u0e40\u0e14\u0e34\u0e23\u0e4c\u0e19\u0e44\u0e19\u0e17\u0e4c\u0e17\u0e35\u0e27\u0e35 \u0e40\u0e27\u0e25\u0e32\u0e1b\u0e23\u0e30\u0e21\u0e32\u0e13 19.20-19.40 \u0e19. \u0e14\u0e31\u0e07\u0e19\u0e35\u0e49 1. \u0e27\u0e31\u0e19\u0e1e\u0e24\u0e2b\u0e31\u0e2a\u0e1a\u0e14\u0e35\u0e17\u0e35\u0e48 3 \u0e18\u0e31\u0e19\u0e27\u0e32\u0e04\u0e21 2552 \u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07 \u0e1a\u0e48\u0e2d\u0e40\u0e01\u0e25\u0e37\u0e2d\u0e1a\u0e19\u0e20\u0e39\u0e40\u0e02\u0e32 2. \u0e27\u0e31\u0e19\u0e2d\u0e31\u0e07\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48 8 \u0e18\u0e31\u0e19\u0e27\u0e32\u0e04\u0e21 2552 \u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07 \u0e1b\u0e38\u0e4b\u0e22\u0e2d\u0e34\u0e19\u0e17\u0e23\u0e35\u0e22\u0e4c\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e41\u0e01\u0e49\u0e1b\u0e31\u0e0d\u0e2b\u0e32\u0e14\u0e34\u0e19\u0e16\u0e25\u0e48\u0e21 3. \u0e27\u0e31\u0e19\u0e1e\u0e38\u0e18\u0e17\u0e35\u0e48 9 \u0e18\u0e31\u0e19\u0e27\u0e32\u0e04\u0e21 2552 \u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07 \u0e40\u0e22\u0e32\u0e27\u0e0a\u0e19\u0e23\u0e31\u0e01\u0e29\u0e4c\u0e20\u0e39\u0e1f\u0e49\u0e32\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e23\u0e31\u0e01\u0e29\u0e32\u0e2a\u0e34\u0e48\u0e07\u0e41\u0e27\u0e14\u0e25\u0e49\u0e2d\u0e21 4. \u0e27\u0e31\u0e19\u0e2d\u0e31\u0e07\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":165448,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[12],"tags":[],"class_list":["post-172299","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-12"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u0e18\u0e23\u0e13\u0e35\u0e27\u0e34\u0e17\u0e22\u0e32\u0e01\u0e31\u0e1a\u0e07\u0e32\u0e19\u0e1f\u0e37\u0e49\u0e19\u0e1f\u0e39\u0e43\u0e19\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e1c\u0e25\u0e01\u0e23\u0e30\u0e17\u0e1a\u0e18\u0e23\u0e13\u0e35\u0e1e\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e20\u0e31\u0e22 - \u0e01\u0e23\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e32\u0e01\u0e23\u0e18\u0e23\u0e13\u0e35<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.dmr.go.th\/\u0e18\u0e23\u0e13\u0e35\u0e27\u0e34\u0e17\u0e22\u0e32\u0e01\u0e31\u0e1a\u0e07\u0e32\u0e19\u0e1f\u0e37\u0e49\u0e19\u0e1f\u0e39\u0e43\u0e19\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e1c\u0e25\u0e01\u0e23\u0e30\u0e17\u0e1a\u0e18\u0e23\u0e13\u0e35\u0e1e\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e20\u0e31\u0e22\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u0e18\u0e23\u0e13\u0e35\u0e27\u0e34\u0e17\u0e22\u0e32\u0e01\u0e31\u0e1a\u0e07\u0e32\u0e19\u0e1f\u0e37\u0e49\u0e19\u0e1f\u0e39\u0e43\u0e19\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e1c\u0e25\u0e01\u0e23\u0e30\u0e17\u0e1a\u0e18\u0e23\u0e13\u0e35\u0e1e\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e20\u0e31\u0e22 - \u0e01\u0e23\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e32\u0e01\u0e23\u0e18\u0e23\u0e13\u0e35\" \/>\n<meta property=\"og:description\" content=\"\u0e18\u0e23\u0e13\u0e35\u0e27\u0e34\u0e17\u0e22\u0e32\u0e01\u0e31\u0e1a\u0e07\u0e32\u0e19\u0e1f\u0e37\u0e49\u0e19\u0e1f\u0e39\u0e43\u0e19\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e1c\u0e25\u0e01\u0e23\u0e30\u0e17\u0e1a\u0e18\u0e23\u0e13\u0e35\u0e1e\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e20\u0e31\u0e22 \u0e19\u0e32\u0e22\u0e2d\u0e14\u0e34\u0e0a\u0e32\u0e15\u0e34 \u0e2a\u0e38\u0e23\u0e34\u0e19\u0e17\u0e23\u0e4c\u0e04\u0e33 \u0e1c\u0e39\u0e49\u0e2d\u0e33\u0e19\u0e27\u0e22\u0e01\u0e32\u0e23\u0e01\u0e2d\u0e07\u0e18\u0e23\u0e13\u0e35\u0e27\u0e34\u0e17\u0e22\u0e32\u0e2a\u0e34\u0e48\u0e07\u0e41\u0e27\u0e14\u0e25\u0e49\u0e2d\u0e21 \u0e19\u0e33\u0e2a\u0e37\u0e48\u0e2d\u0e21\u0e27\u0e25\u0e0a\u0e19\u0e25\u0e07\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e17\u0e35\u0e48\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e1c\u0e25\u0e01\u0e23\u0e30\u0e17\u0e1a\u0e08\u0e32\u0e01\u0e40\u0e2b\u0e15\u0e38\u0e18\u0e23\u0e13\u0e35\u0e1e\u0e34\u0e1a\u0e31\u0e15\u0e34 \u0e13 \u0e2d.\u0e1a\u0e48\u0e2d\u0e40\u0e01\u0e25\u0e37\u0e2d \u0e08.\u0e19\u0e48\u0e32\u0e19 \u0e16\u0e48\u0e32\u0e22\u0e17\u0e33\u0e2a\u0e01\u0e39\u0e4a\u0e1b\u0e02\u0e48\u0e32\u0e27\u0e07\u0e32\u0e19\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e41\u0e19\u0e27\u0e1b\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e19\u0e41\u0e25\u0e30\u0e1f\u0e37\u0e49\u0e19\u0e1f\u0e39\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e17\u0e35\u0e48\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e1c\u0e25\u0e01\u0e23\u0e30\u0e17\u0e1a\u0e08\u0e32\u0e01\u0e18\u0e23\u0e13\u0e35\u0e1e\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e20\u0e31\u0e22 \u0e01\u0e32\u0e23\u0e41\u0e01\u0e49\u0e44\u0e02\u0e1b\u0e31\u0e0d\u0e2b\u0e32\u0e08\u0e32\u0e01\u0e1c\u0e25\u0e01\u0e23\u0e30\u0e17\u0e1a\u0e14\u0e49\u0e32\u0e19\u0e18\u0e23\u0e13\u0e35\u0e27\u0e34\u0e17\u0e22\u0e32 \u0e41\u0e25\u0e30\u0e1b\u0e23\u0e30\u0e2a\u0e32\u0e19\u0e1b\u0e23\u0e30\u0e2a\u0e32\u0e19\u0e40\u0e04\u0e23\u0e37\u0e2d\u0e02\u0e48\u0e32\u0e22\u0e40\u0e1d\u0e49\u0e32\u0e23\u0e30\u0e27\u0e31\u0e07\u0e41\u0e08\u0e49\u0e07\u0e40\u0e2b\u0e15\u0e38\u0e18\u0e23\u0e13\u0e35\u0e1e\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e20\u0e31\u0e22 \u0e1c\u0e39\u0e49\u0e19\u0e33\u0e0a\u0e38\u0e21\u0e0a\u0e19 \u0e40\u0e0a\u0e48\u0e19 \u0e19\u0e32\u0e22\u0e01 \u0e2d\u0e1a\u0e15. \u0e2d\u0e1a\u0e15. \u0e1c\u0e39\u0e49\u0e43\u0e2b\u0e0d\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e1c\u0e39\u0e49\u0e0a\u0e48\u0e27\u0e22\u0e1c\u0e39\u0e49\u0e43\u0e2b\u0e0d\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e1c\u0e39\u0e49\u0e21\u0e35\u0e2a\u0e48\u0e27\u0e19\u0e44\u0e14\u0e49\u0e2a\u0e48\u0e27\u0e19\u0e40\u0e2a\u0e35\u0e22\u0e43\u0e19\u0e01\u0e32\u0e23\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e17\u0e33\u0e41\u0e19\u0e27\u0e01\u0e32\u0e23\u0e1b\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e19\u0e41\u0e25\u0e30\u0e1f\u0e37\u0e49\u0e19\u0e1f\u0e39\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e30\u0e2a\u0e1a\u0e20\u0e31\u0e22\u0e14\u0e34\u0e19\u0e16\u0e25\u0e48\u0e21 \u0e43\u0e19\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e20\u0e39\u0e1f\u0e49\u0e32 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e27\u0e32\u0e07\u0e41\u0e1c\u0e19\u0e43\u0e19\u0e01\u0e32\u0e23\u0e40\u0e02\u0e49\u0e32\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e01\u0e32\u0e23\u0e1b\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e19\u0e41\u0e25\u0e30\u0e1f\u0e37\u0e49\u0e19\u0e1f\u0e39\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e30\u0e2a\u0e1a\u0e20\u0e31\u0e22\u0e14\u0e34\u0e19\u0e16\u0e25\u0e48\u0e21 \u0e0b\u0e36\u0e48\u0e07\u0e2a\u0e01\u0e39\u0e4a\u0e1b\u0e02\u0e48\u0e32\u0e27 2 \u0e19\u0e32\u0e17\u0e35 \u0e21\u0e35\u0e17\u0e31\u0e49\u0e07\u0e2b\u0e21\u0e14 4 \u0e15\u0e2d\u0e19 \u0e0b\u0e36\u0e48\u0e07\u0e21\u0e35\u0e01\u0e33\u0e2b\u0e19\u0e14\u0e2d\u0e2d\u0e01\u0e2d\u0e32\u0e01\u0e32\u0e28\u0e17\u0e32\u0e07\u0e2a\u0e16\u0e32\u0e19\u0e35\u0e42\u0e17\u0e23\u0e17\u0e31\u0e28\u0e19\u0e4c\u0e42\u0e21\u0e40\u0e14\u0e34\u0e23\u0e4c\u0e19\u0e44\u0e19\u0e17\u0e4c\u0e17\u0e35\u0e27\u0e35 \u0e40\u0e27\u0e25\u0e32\u0e1b\u0e23\u0e30\u0e21\u0e32\u0e13 19.20-19.40 \u0e19. \u0e14\u0e31\u0e07\u0e19\u0e35\u0e49 1. \u0e27\u0e31\u0e19\u0e1e\u0e24\u0e2b\u0e31\u0e2a\u0e1a\u0e14\u0e35\u0e17\u0e35\u0e48 3 \u0e18\u0e31\u0e19\u0e27\u0e32\u0e04\u0e21 2552 \u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07 \u0e1a\u0e48\u0e2d\u0e40\u0e01\u0e25\u0e37\u0e2d\u0e1a\u0e19\u0e20\u0e39\u0e40\u0e02\u0e32 2. \u0e27\u0e31\u0e19\u0e2d\u0e31\u0e07\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48 8 \u0e18\u0e31\u0e19\u0e27\u0e32\u0e04\u0e21 2552 \u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07 \u0e1b\u0e38\u0e4b\u0e22\u0e2d\u0e34\u0e19\u0e17\u0e23\u0e35\u0e22\u0e4c\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e41\u0e01\u0e49\u0e1b\u0e31\u0e0d\u0e2b\u0e32\u0e14\u0e34\u0e19\u0e16\u0e25\u0e48\u0e21 3. \u0e27\u0e31\u0e19\u0e1e\u0e38\u0e18\u0e17\u0e35\u0e48 9 \u0e18\u0e31\u0e19\u0e27\u0e32\u0e04\u0e21 2552 \u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07 \u0e40\u0e22\u0e32\u0e27\u0e0a\u0e19\u0e23\u0e31\u0e01\u0e29\u0e4c\u0e20\u0e39\u0e1f\u0e49\u0e32\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e23\u0e31\u0e01\u0e29\u0e32\u0e2a\u0e34\u0e48\u0e07\u0e41\u0e27\u0e14\u0e25\u0e49\u0e2d\u0e21 4. \u0e27\u0e31\u0e19\u0e2d\u0e31\u0e07\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.dmr.go.th\/\u0e18\u0e23\u0e13\u0e35\u0e27\u0e34\u0e17\u0e22\u0e32\u0e01\u0e31\u0e1a\u0e07\u0e32\u0e19\u0e1f\u0e37\u0e49\u0e19\u0e1f\u0e39\u0e43\u0e19\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e1c\u0e25\u0e01\u0e23\u0e30\u0e17\u0e1a\u0e18\u0e23\u0e13\u0e35\u0e1e\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e20\u0e31\u0e22\/\" \/>\n<meta property=\"og:site_name\" content=\"\u0e01\u0e23\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e32\u0e01\u0e23\u0e18\u0e23\u0e13\u0e35\" \/>\n<meta property=\"article:published_time\" content=\"2009-12-03T11:10:14+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.dmr.go.th\/wp-content\/uploads\/2022\/10\/default_no_pic-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"341\" \/>\n\t<meta property=\"og:image:height\" content=\"249\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e18\u0e23\u0e13\u0e35\u0e27\u0e34\u0e17\u0e22\u0e32\u0e2a\u0e34\u0e48\u0e07\u0e41\u0e27\u0e14\u0e25\u0e49\u0e2d\u0e21\u0e41\u0e25\u0e30\u0e18\u0e23\u0e13\u0e35\u0e1e\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e20\u0e31\u0e22\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e18\u0e23\u0e13\u0e35\u0e27\u0e34\u0e17\u0e22\u0e32\u0e2a\u0e34\u0e48\u0e07\u0e41\u0e27\u0e14\u0e25\u0e49\u0e2d\u0e21\u0e41\u0e25\u0e30\u0e18\u0e23\u0e13\u0e35\u0e1e\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e20\u0e31\u0e22\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.dmr.go.th\/%e0%b8%98%e0%b8%a3%e0%b8%93%e0%b8%b5%e0%b8%a7%e0%b8%b4%e0%b8%97%e0%b8%a2%e0%b8%b2%e0%b8%81%e0%b8%b1%e0%b8%9a%e0%b8%87%e0%b8%b2%e0%b8%99%e0%b8%9f%e0%b8%b7%e0%b9%89%e0%b8%99%e0%b8%9f%e0%b8%b9%e0%b9%83%e0%b8%99%e0%b8%9e%e0%b8%b7%e0%b9%89%e0%b8%99%e0%b8%97%e0%b8%b5%e0%b9%88%e0%b9%84%e0%b8%94%e0%b9%89%e0%b8%a3%e0%b8%b1%e0%b8%9a%e0%b8%9c%e0%b8%a5%e0%b8%81%e0%b8%a3%e0%b8%b0%e0%b8%97%e0%b8%9a%e0%b8%98%e0%b8%a3%e0%b8%93%e0%b8%b5%e0%b8%9e%e0%b8%b4%e0%b8%9a%e0%b8%b1%e0%b8%95%e0%b8%b4%e0%b8%a0%e0%b8%b1%e0%b8%a2\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.dmr.go.th\/%e0%b8%98%e0%b8%a3%e0%b8%93%e0%b8%b5%e0%b8%a7%e0%b8%b4%e0%b8%97%e0%b8%a2%e0%b8%b2%e0%b8%81%e0%b8%b1%e0%b8%9a%e0%b8%87%e0%b8%b2%e0%b8%99%e0%b8%9f%e0%b8%b7%e0%b9%89%e0%b8%99%e0%b8%9f%e0%b8%b9%e0%b9%83%e0%b8%99%e0%b8%9e%e0%b8%b7%e0%b9%89%e0%b8%99%e0%b8%97%e0%b8%b5%e0%b9%88%e0%b9%84%e0%b8%94%e0%b9%89%e0%b8%a3%e0%b8%b1%e0%b8%9a%e0%b8%9c%e0%b8%a5%e0%b8%81%e0%b8%a3%e0%b8%b0%e0%b8%97%e0%b8%9a%e0%b8%98%e0%b8%a3%e0%b8%93%e0%b8%b5%e0%b8%9e%e0%b8%b4%e0%b8%9a%e0%b8%b1%e0%b8%95%e0%b8%b4%e0%b8%a0%e0%b8%b1%e0%b8%a2\/\"},\"author\":{\"name\":\"\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e18\u0e23\u0e13\u0e35\u0e27\u0e34\u0e17\u0e22\u0e32\u0e2a\u0e34\u0e48\u0e07\u0e41\u0e27\u0e14\u0e25\u0e49\u0e2d\u0e21\u0e41\u0e25\u0e30\u0e18\u0e23\u0e13\u0e35\u0e1e\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e20\u0e31\u0e22\",\"@id\":\"https:\/\/www.dmr.go.th\/#\/schema\/person\/f4bc4dd56ee9041de4a03c606749e2bc\"},\"headline\":\"\u0e18\u0e23\u0e13\u0e35\u0e27\u0e34\u0e17\u0e22\u0e32\u0e01\u0e31\u0e1a\u0e07\u0e32\u0e19\u0e1f\u0e37\u0e49\u0e19\u0e1f\u0e39\u0e43\u0e19\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e1c\u0e25\u0e01\u0e23\u0e30\u0e17\u0e1a\u0e18\u0e23\u0e13\u0e35\u0e1e\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e20\u0e31\u0e22\",\"datePublished\":\"2009-12-03T11:10:14+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.dmr.go.th\/%e0%b8%98%e0%b8%a3%e0%b8%93%e0%b8%b5%e0%b8%a7%e0%b8%b4%e0%b8%97%e0%b8%a2%e0%b8%b2%e0%b8%81%e0%b8%b1%e0%b8%9a%e0%b8%87%e0%b8%b2%e0%b8%99%e0%b8%9f%e0%b8%b7%e0%b9%89%e0%b8%99%e0%b8%9f%e0%b8%b9%e0%b9%83%e0%b8%99%e0%b8%9e%e0%b8%b7%e0%b9%89%e0%b8%99%e0%b8%97%e0%b8%b5%e0%b9%88%e0%b9%84%e0%b8%94%e0%b9%89%e0%b8%a3%e0%b8%b1%e0%b8%9a%e0%b8%9c%e0%b8%a5%e0%b8%81%e0%b8%a3%e0%b8%b0%e0%b8%97%e0%b8%9a%e0%b8%98%e0%b8%a3%e0%b8%93%e0%b8%b5%e0%b8%9e%e0%b8%b4%e0%b8%9a%e0%b8%b1%e0%b8%95%e0%b8%b4%e0%b8%a0%e0%b8%b1%e0%b8%a2\/\"},\"wordCount\":1,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.dmr.go.th\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.dmr.go.th\/%e0%b8%98%e0%b8%a3%e0%b8%93%e0%b8%b5%e0%b8%a7%e0%b8%b4%e0%b8%97%e0%b8%a2%e0%b8%b2%e0%b8%81%e0%b8%b1%e0%b8%9a%e0%b8%87%e0%b8%b2%e0%b8%99%e0%b8%9f%e0%b8%b7%e0%b9%89%e0%b8%99%e0%b8%9f%e0%b8%b9%e0%b9%83%e0%b8%99%e0%b8%9e%e0%b8%b7%e0%b9%89%e0%b8%99%e0%b8%97%e0%b8%b5%e0%b9%88%e0%b9%84%e0%b8%94%e0%b9%89%e0%b8%a3%e0%b8%b1%e0%b8%9a%e0%b8%9c%e0%b8%a5%e0%b8%81%e0%b8%a3%e0%b8%b0%e0%b8%97%e0%b8%9a%e0%b8%98%e0%b8%a3%e0%b8%93%e0%b8%b5%e0%b8%9e%e0%b8%b4%e0%b8%9a%e0%b8%b1%e0%b8%95%e0%b8%b4%e0%b8%a0%e0%b8%b1%e0%b8%a2\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.dmr.go.th\/wp-content\/uploads\/2022\/10\/default_no_pic-1.jpg\",\"articleSection\":[\"\u0e02\u0e48\u0e32\u0e27\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.dmr.go.th\/%e0%b8%98%e0%b8%a3%e0%b8%93%e0%b8%b5%e0%b8%a7%e0%b8%b4%e0%b8%97%e0%b8%a2%e0%b8%b2%e0%b8%81%e0%b8%b1%e0%b8%9a%e0%b8%87%e0%b8%b2%e0%b8%99%e0%b8%9f%e0%b8%b7%e0%b9%89%e0%b8%99%e0%b8%9f%e0%b8%b9%e0%b9%83%e0%b8%99%e0%b8%9e%e0%b8%b7%e0%b9%89%e0%b8%99%e0%b8%97%e0%b8%b5%e0%b9%88%e0%b9%84%e0%b8%94%e0%b9%89%e0%b8%a3%e0%b8%b1%e0%b8%9a%e0%b8%9c%e0%b8%a5%e0%b8%81%e0%b8%a3%e0%b8%b0%e0%b8%97%e0%b8%9a%e0%b8%98%e0%b8%a3%e0%b8%93%e0%b8%b5%e0%b8%9e%e0%b8%b4%e0%b8%9a%e0%b8%b1%e0%b8%95%e0%b8%b4%e0%b8%a0%e0%b8%b1%e0%b8%a2\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.dmr.go.th\/%e0%b8%98%e0%b8%a3%e0%b8%93%e0%b8%b5%e0%b8%a7%e0%b8%b4%e0%b8%97%e0%b8%a2%e0%b8%b2%e0%b8%81%e0%b8%b1%e0%b8%9a%e0%b8%87%e0%b8%b2%e0%b8%99%e0%b8%9f%e0%b8%b7%e0%b9%89%e0%b8%99%e0%b8%9f%e0%b8%b9%e0%b9%83%e0%b8%99%e0%b8%9e%e0%b8%b7%e0%b9%89%e0%b8%99%e0%b8%97%e0%b8%b5%e0%b9%88%e0%b9%84%e0%b8%94%e0%b9%89%e0%b8%a3%e0%b8%b1%e0%b8%9a%e0%b8%9c%e0%b8%a5%e0%b8%81%e0%b8%a3%e0%b8%b0%e0%b8%97%e0%b8%9a%e0%b8%98%e0%b8%a3%e0%b8%93%e0%b8%b5%e0%b8%9e%e0%b8%b4%e0%b8%9a%e0%b8%b1%e0%b8%95%e0%b8%b4%e0%b8%a0%e0%b8%b1%e0%b8%a2\/\",\"url\":\"https:\/\/www.dmr.go.th\/%e0%b8%98%e0%b8%a3%e0%b8%93%e0%b8%b5%e0%b8%a7%e0%b8%b4%e0%b8%97%e0%b8%a2%e0%b8%b2%e0%b8%81%e0%b8%b1%e0%b8%9a%e0%b8%87%e0%b8%b2%e0%b8%99%e0%b8%9f%e0%b8%b7%e0%b9%89%e0%b8%99%e0%b8%9f%e0%b8%b9%e0%b9%83%e0%b8%99%e0%b8%9e%e0%b8%b7%e0%b9%89%e0%b8%99%e0%b8%97%e0%b8%b5%e0%b9%88%e0%b9%84%e0%b8%94%e0%b9%89%e0%b8%a3%e0%b8%b1%e0%b8%9a%e0%b8%9c%e0%b8%a5%e0%b8%81%e0%b8%a3%e0%b8%b0%e0%b8%97%e0%b8%9a%e0%b8%98%e0%b8%a3%e0%b8%93%e0%b8%b5%e0%b8%9e%e0%b8%b4%e0%b8%9a%e0%b8%b1%e0%b8%95%e0%b8%b4%e0%b8%a0%e0%b8%b1%e0%b8%a2\/\",\"name\":\"\u0e18\u0e23\u0e13\u0e35\u0e27\u0e34\u0e17\u0e22\u0e32\u0e01\u0e31\u0e1a\u0e07\u0e32\u0e19\u0e1f\u0e37\u0e49\u0e19\u0e1f\u0e39\u0e43\u0e19\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e1c\u0e25\u0e01\u0e23\u0e30\u0e17\u0e1a\u0e18\u0e23\u0e13\u0e35\u0e1e\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e20\u0e31\u0e22 - \u0e01\u0e23\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e32\u0e01\u0e23\u0e18\u0e23\u0e13\u0e35\",\"isPartOf\":{\"@id\":\"https:\/\/www.dmr.go.th\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.dmr.go.th\/%e0%b8%98%e0%b8%a3%e0%b8%93%e0%b8%b5%e0%b8%a7%e0%b8%b4%e0%b8%97%e0%b8%a2%e0%b8%b2%e0%b8%81%e0%b8%b1%e0%b8%9a%e0%b8%87%e0%b8%b2%e0%b8%99%e0%b8%9f%e0%b8%b7%e0%b9%89%e0%b8%99%e0%b8%9f%e0%b8%b9%e0%b9%83%e0%b8%99%e0%b8%9e%e0%b8%b7%e0%b9%89%e0%b8%99%e0%b8%97%e0%b8%b5%e0%b9%88%e0%b9%84%e0%b8%94%e0%b9%89%e0%b8%a3%e0%b8%b1%e0%b8%9a%e0%b8%9c%e0%b8%a5%e0%b8%81%e0%b8%a3%e0%b8%b0%e0%b8%97%e0%b8%9a%e0%b8%98%e0%b8%a3%e0%b8%93%e0%b8%b5%e0%b8%9e%e0%b8%b4%e0%b8%9a%e0%b8%b1%e0%b8%95%e0%b8%b4%e0%b8%a0%e0%b8%b1%e0%b8%a2\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.dmr.go.th\/%e0%b8%98%e0%b8%a3%e0%b8%93%e0%b8%b5%e0%b8%a7%e0%b8%b4%e0%b8%97%e0%b8%a2%e0%b8%b2%e0%b8%81%e0%b8%b1%e0%b8%9a%e0%b8%87%e0%b8%b2%e0%b8%99%e0%b8%9f%e0%b8%b7%e0%b9%89%e0%b8%99%e0%b8%9f%e0%b8%b9%e0%b9%83%e0%b8%99%e0%b8%9e%e0%b8%b7%e0%b9%89%e0%b8%99%e0%b8%97%e0%b8%b5%e0%b9%88%e0%b9%84%e0%b8%94%e0%b9%89%e0%b8%a3%e0%b8%b1%e0%b8%9a%e0%b8%9c%e0%b8%a5%e0%b8%81%e0%b8%a3%e0%b8%b0%e0%b8%97%e0%b8%9a%e0%b8%98%e0%b8%a3%e0%b8%93%e0%b8%b5%e0%b8%9e%e0%b8%b4%e0%b8%9a%e0%b8%b1%e0%b8%95%e0%b8%b4%e0%b8%a0%e0%b8%b1%e0%b8%a2\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.dmr.go.th\/wp-content\/uploads\/2022\/10\/default_no_pic-1.jpg\",\"datePublished\":\"2009-12-03T11:10:14+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.dmr.go.th\/%e0%b8%98%e0%b8%a3%e0%b8%93%e0%b8%b5%e0%b8%a7%e0%b8%b4%e0%b8%97%e0%b8%a2%e0%b8%b2%e0%b8%81%e0%b8%b1%e0%b8%9a%e0%b8%87%e0%b8%b2%e0%b8%99%e0%b8%9f%e0%b8%b7%e0%b9%89%e0%b8%99%e0%b8%9f%e0%b8%b9%e0%b9%83%e0%b8%99%e0%b8%9e%e0%b8%b7%e0%b9%89%e0%b8%99%e0%b8%97%e0%b8%b5%e0%b9%88%e0%b9%84%e0%b8%94%e0%b9%89%e0%b8%a3%e0%b8%b1%e0%b8%9a%e0%b8%9c%e0%b8%a5%e0%b8%81%e0%b8%a3%e0%b8%b0%e0%b8%97%e0%b8%9a%e0%b8%98%e0%b8%a3%e0%b8%93%e0%b8%b5%e0%b8%9e%e0%b8%b4%e0%b8%9a%e0%b8%b1%e0%b8%95%e0%b8%b4%e0%b8%a0%e0%b8%b1%e0%b8%a2\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.dmr.go.th\/%e0%b8%98%e0%b8%a3%e0%b8%93%e0%b8%b5%e0%b8%a7%e0%b8%b4%e0%b8%97%e0%b8%a2%e0%b8%b2%e0%b8%81%e0%b8%b1%e0%b8%9a%e0%b8%87%e0%b8%b2%e0%b8%99%e0%b8%9f%e0%b8%b7%e0%b9%89%e0%b8%99%e0%b8%9f%e0%b8%b9%e0%b9%83%e0%b8%99%e0%b8%9e%e0%b8%b7%e0%b9%89%e0%b8%99%e0%b8%97%e0%b8%b5%e0%b9%88%e0%b9%84%e0%b8%94%e0%b9%89%e0%b8%a3%e0%b8%b1%e0%b8%9a%e0%b8%9c%e0%b8%a5%e0%b8%81%e0%b8%a3%e0%b8%b0%e0%b8%97%e0%b8%9a%e0%b8%98%e0%b8%a3%e0%b8%93%e0%b8%b5%e0%b8%9e%e0%b8%b4%e0%b8%9a%e0%b8%b1%e0%b8%95%e0%b8%b4%e0%b8%a0%e0%b8%b1%e0%b8%a2\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.dmr.go.th\/%e0%b8%98%e0%b8%a3%e0%b8%93%e0%b8%b5%e0%b8%a7%e0%b8%b4%e0%b8%97%e0%b8%a2%e0%b8%b2%e0%b8%81%e0%b8%b1%e0%b8%9a%e0%b8%87%e0%b8%b2%e0%b8%99%e0%b8%9f%e0%b8%b7%e0%b9%89%e0%b8%99%e0%b8%9f%e0%b8%b9%e0%b9%83%e0%b8%99%e0%b8%9e%e0%b8%b7%e0%b9%89%e0%b8%99%e0%b8%97%e0%b8%b5%e0%b9%88%e0%b9%84%e0%b8%94%e0%b9%89%e0%b8%a3%e0%b8%b1%e0%b8%9a%e0%b8%9c%e0%b8%a5%e0%b8%81%e0%b8%a3%e0%b8%b0%e0%b8%97%e0%b8%9a%e0%b8%98%e0%b8%a3%e0%b8%93%e0%b8%b5%e0%b8%9e%e0%b8%b4%e0%b8%9a%e0%b8%b1%e0%b8%95%e0%b8%b4%e0%b8%a0%e0%b8%b1%e0%b8%a2\/#primaryimage\",\"url\":\"https:\/\/www.dmr.go.th\/wp-content\/uploads\/2022\/10\/default_no_pic-1.jpg\",\"contentUrl\":\"https:\/\/www.dmr.go.th\/wp-content\/uploads\/2022\/10\/default_no_pic-1.jpg\",\"width\":341,\"height\":249,\"caption\":\"\u0e01\u0e23\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e32\u0e01\u0e23\u0e18\u0e23\u0e13\u0e35\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.dmr.go.th\/%e0%b8%98%e0%b8%a3%e0%b8%93%e0%b8%b5%e0%b8%a7%e0%b8%b4%e0%b8%97%e0%b8%a2%e0%b8%b2%e0%b8%81%e0%b8%b1%e0%b8%9a%e0%b8%87%e0%b8%b2%e0%b8%99%e0%b8%9f%e0%b8%b7%e0%b9%89%e0%b8%99%e0%b8%9f%e0%b8%b9%e0%b9%83%e0%b8%99%e0%b8%9e%e0%b8%b7%e0%b9%89%e0%b8%99%e0%b8%97%e0%b8%b5%e0%b9%88%e0%b9%84%e0%b8%94%e0%b9%89%e0%b8%a3%e0%b8%b1%e0%b8%9a%e0%b8%9c%e0%b8%a5%e0%b8%81%e0%b8%a3%e0%b8%b0%e0%b8%97%e0%b8%9a%e0%b8%98%e0%b8%a3%e0%b8%93%e0%b8%b5%e0%b8%9e%e0%b8%b4%e0%b8%9a%e0%b8%b1%e0%b8%95%e0%b8%b4%e0%b8%a0%e0%b8%b1%e0%b8%a2\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.dmr.go.th\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u0e18\u0e23\u0e13\u0e35\u0e27\u0e34\u0e17\u0e22\u0e32\u0e01\u0e31\u0e1a\u0e07\u0e32\u0e19\u0e1f\u0e37\u0e49\u0e19\u0e1f\u0e39\u0e43\u0e19\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e1c\u0e25\u0e01\u0e23\u0e30\u0e17\u0e1a\u0e18\u0e23\u0e13\u0e35\u0e1e\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e20\u0e31\u0e22\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.dmr.go.th\/#website\",\"url\":\"https:\/\/www.dmr.go.th\/\",\"name\":\"\u0e01\u0e23\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e32\u0e01\u0e23\u0e18\u0e23\u0e13\u0e35\",\"description\":\"\u0e01\u0e23\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e32\u0e01\u0e23\u0e18\u0e23\u0e13\u0e35\",\"publisher\":{\"@id\":\"https:\/\/www.dmr.go.th\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.dmr.go.th\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.dmr.go.th\/#organization\",\"name\":\"\u0e01\u0e23\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e32\u0e01\u0e23\u0e18\u0e23\u0e13\u0e35\",\"url\":\"https:\/\/www.dmr.go.th\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.dmr.go.th\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.dmr.go.th\/wp-content\/uploads\/2022\/08\/\u0e15\u0e23\u0e32\u0e01\u0e23\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e32\u0e01\u0e23\u0e18\u0e23\u0e13\u0e35-2.png\",\"contentUrl\":\"https:\/\/www.dmr.go.th\/wp-content\/uploads\/2022\/08\/\u0e15\u0e23\u0e32\u0e01\u0e23\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e32\u0e01\u0e23\u0e18\u0e23\u0e13\u0e35-2.png\",\"width\":400,\"height\":400,\"caption\":\"\u0e01\u0e23\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e32\u0e01\u0e23\u0e18\u0e23\u0e13\u0e35\"},\"image\":{\"@id\":\"https:\/\/www.dmr.go.th\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.dmr.go.th\/#\/schema\/person\/f4bc4dd56ee9041de4a03c606749e2bc\",\"name\":\"\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e18\u0e23\u0e13\u0e35\u0e27\u0e34\u0e17\u0e22\u0e32\u0e2a\u0e34\u0e48\u0e07\u0e41\u0e27\u0e14\u0e25\u0e49\u0e2d\u0e21\u0e41\u0e25\u0e30\u0e18\u0e23\u0e13\u0e35\u0e1e\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e20\u0e31\u0e22\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.dmr.go.th\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/16cd7e279959e64661a4e273e93548cbadc539d0c3f9f0db93f4c4c1c30720c0?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/16cd7e279959e64661a4e273e93548cbadc539d0c3f9f0db93f4c4c1c30720c0?s=96&d=mm&r=g\",\"caption\":\"\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e18\u0e23\u0e13\u0e35\u0e27\u0e34\u0e17\u0e22\u0e32\u0e2a\u0e34\u0e48\u0e07\u0e41\u0e27\u0e14\u0e25\u0e49\u0e2d\u0e21\u0e41\u0e25\u0e30\u0e18\u0e23\u0e13\u0e35\u0e1e\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e20\u0e31\u0e22\"},\"sameAs\":[\"https:\/\/www.dmr.go.th\"],\"url\":\"https:\/\/www.dmr.go.th\/en\/author\/amika-bcipher-co-th\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u0e18\u0e23\u0e13\u0e35\u0e27\u0e34\u0e17\u0e22\u0e32\u0e01\u0e31\u0e1a\u0e07\u0e32\u0e19\u0e1f\u0e37\u0e49\u0e19\u0e1f\u0e39\u0e43\u0e19\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e1c\u0e25\u0e01\u0e23\u0e30\u0e17\u0e1a\u0e18\u0e23\u0e13\u0e35\u0e1e\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e20\u0e31\u0e22 - \u0e01\u0e23\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e32\u0e01\u0e23\u0e18\u0e23\u0e13\u0e35","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.dmr.go.th\/\u0e18\u0e23\u0e13\u0e35\u0e27\u0e34\u0e17\u0e22\u0e32\u0e01\u0e31\u0e1a\u0e07\u0e32\u0e19\u0e1f\u0e37\u0e49\u0e19\u0e1f\u0e39\u0e43\u0e19\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e1c\u0e25\u0e01\u0e23\u0e30\u0e17\u0e1a\u0e18\u0e23\u0e13\u0e35\u0e1e\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e20\u0e31\u0e22\/","og_locale":"en_US","og_type":"article","og_title":"\u0e18\u0e23\u0e13\u0e35\u0e27\u0e34\u0e17\u0e22\u0e32\u0e01\u0e31\u0e1a\u0e07\u0e32\u0e19\u0e1f\u0e37\u0e49\u0e19\u0e1f\u0e39\u0e43\u0e19\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e1c\u0e25\u0e01\u0e23\u0e30\u0e17\u0e1a\u0e18\u0e23\u0e13\u0e35\u0e1e\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e20\u0e31\u0e22 - \u0e01\u0e23\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e32\u0e01\u0e23\u0e18\u0e23\u0e13\u0e35","og_description":"\u0e18\u0e23\u0e13\u0e35\u0e27\u0e34\u0e17\u0e22\u0e32\u0e01\u0e31\u0e1a\u0e07\u0e32\u0e19\u0e1f\u0e37\u0e49\u0e19\u0e1f\u0e39\u0e43\u0e19\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e1c\u0e25\u0e01\u0e23\u0e30\u0e17\u0e1a\u0e18\u0e23\u0e13\u0e35\u0e1e\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e20\u0e31\u0e22 \u0e19\u0e32\u0e22\u0e2d\u0e14\u0e34\u0e0a\u0e32\u0e15\u0e34 \u0e2a\u0e38\u0e23\u0e34\u0e19\u0e17\u0e23\u0e4c\u0e04\u0e33 \u0e1c\u0e39\u0e49\u0e2d\u0e33\u0e19\u0e27\u0e22\u0e01\u0e32\u0e23\u0e01\u0e2d\u0e07\u0e18\u0e23\u0e13\u0e35\u0e27\u0e34\u0e17\u0e22\u0e32\u0e2a\u0e34\u0e48\u0e07\u0e41\u0e27\u0e14\u0e25\u0e49\u0e2d\u0e21 \u0e19\u0e33\u0e2a\u0e37\u0e48\u0e2d\u0e21\u0e27\u0e25\u0e0a\u0e19\u0e25\u0e07\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e17\u0e35\u0e48\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e1c\u0e25\u0e01\u0e23\u0e30\u0e17\u0e1a\u0e08\u0e32\u0e01\u0e40\u0e2b\u0e15\u0e38\u0e18\u0e23\u0e13\u0e35\u0e1e\u0e34\u0e1a\u0e31\u0e15\u0e34 \u0e13 \u0e2d.\u0e1a\u0e48\u0e2d\u0e40\u0e01\u0e25\u0e37\u0e2d \u0e08.\u0e19\u0e48\u0e32\u0e19 \u0e16\u0e48\u0e32\u0e22\u0e17\u0e33\u0e2a\u0e01\u0e39\u0e4a\u0e1b\u0e02\u0e48\u0e32\u0e27\u0e07\u0e32\u0e19\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e41\u0e19\u0e27\u0e1b\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e19\u0e41\u0e25\u0e30\u0e1f\u0e37\u0e49\u0e19\u0e1f\u0e39\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e17\u0e35\u0e48\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e1c\u0e25\u0e01\u0e23\u0e30\u0e17\u0e1a\u0e08\u0e32\u0e01\u0e18\u0e23\u0e13\u0e35\u0e1e\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e20\u0e31\u0e22 \u0e01\u0e32\u0e23\u0e41\u0e01\u0e49\u0e44\u0e02\u0e1b\u0e31\u0e0d\u0e2b\u0e32\u0e08\u0e32\u0e01\u0e1c\u0e25\u0e01\u0e23\u0e30\u0e17\u0e1a\u0e14\u0e49\u0e32\u0e19\u0e18\u0e23\u0e13\u0e35\u0e27\u0e34\u0e17\u0e22\u0e32 \u0e41\u0e25\u0e30\u0e1b\u0e23\u0e30\u0e2a\u0e32\u0e19\u0e1b\u0e23\u0e30\u0e2a\u0e32\u0e19\u0e40\u0e04\u0e23\u0e37\u0e2d\u0e02\u0e48\u0e32\u0e22\u0e40\u0e1d\u0e49\u0e32\u0e23\u0e30\u0e27\u0e31\u0e07\u0e41\u0e08\u0e49\u0e07\u0e40\u0e2b\u0e15\u0e38\u0e18\u0e23\u0e13\u0e35\u0e1e\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e20\u0e31\u0e22 \u0e1c\u0e39\u0e49\u0e19\u0e33\u0e0a\u0e38\u0e21\u0e0a\u0e19 \u0e40\u0e0a\u0e48\u0e19 \u0e19\u0e32\u0e22\u0e01 \u0e2d\u0e1a\u0e15. \u0e2d\u0e1a\u0e15. \u0e1c\u0e39\u0e49\u0e43\u0e2b\u0e0d\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e1c\u0e39\u0e49\u0e0a\u0e48\u0e27\u0e22\u0e1c\u0e39\u0e49\u0e43\u0e2b\u0e0d\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e1c\u0e39\u0e49\u0e21\u0e35\u0e2a\u0e48\u0e27\u0e19\u0e44\u0e14\u0e49\u0e2a\u0e48\u0e27\u0e19\u0e40\u0e2a\u0e35\u0e22\u0e43\u0e19\u0e01\u0e32\u0e23\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e17\u0e33\u0e41\u0e19\u0e27\u0e01\u0e32\u0e23\u0e1b\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e19\u0e41\u0e25\u0e30\u0e1f\u0e37\u0e49\u0e19\u0e1f\u0e39\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e30\u0e2a\u0e1a\u0e20\u0e31\u0e22\u0e14\u0e34\u0e19\u0e16\u0e25\u0e48\u0e21 \u0e43\u0e19\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e20\u0e39\u0e1f\u0e49\u0e32 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e27\u0e32\u0e07\u0e41\u0e1c\u0e19\u0e43\u0e19\u0e01\u0e32\u0e23\u0e40\u0e02\u0e49\u0e32\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e01\u0e32\u0e23\u0e1b\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e19\u0e41\u0e25\u0e30\u0e1f\u0e37\u0e49\u0e19\u0e1f\u0e39\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e30\u0e2a\u0e1a\u0e20\u0e31\u0e22\u0e14\u0e34\u0e19\u0e16\u0e25\u0e48\u0e21 \u0e0b\u0e36\u0e48\u0e07\u0e2a\u0e01\u0e39\u0e4a\u0e1b\u0e02\u0e48\u0e32\u0e27 2 \u0e19\u0e32\u0e17\u0e35 \u0e21\u0e35\u0e17\u0e31\u0e49\u0e07\u0e2b\u0e21\u0e14 4 \u0e15\u0e2d\u0e19 \u0e0b\u0e36\u0e48\u0e07\u0e21\u0e35\u0e01\u0e33\u0e2b\u0e19\u0e14\u0e2d\u0e2d\u0e01\u0e2d\u0e32\u0e01\u0e32\u0e28\u0e17\u0e32\u0e07\u0e2a\u0e16\u0e32\u0e19\u0e35\u0e42\u0e17\u0e23\u0e17\u0e31\u0e28\u0e19\u0e4c\u0e42\u0e21\u0e40\u0e14\u0e34\u0e23\u0e4c\u0e19\u0e44\u0e19\u0e17\u0e4c\u0e17\u0e35\u0e27\u0e35 \u0e40\u0e27\u0e25\u0e32\u0e1b\u0e23\u0e30\u0e21\u0e32\u0e13 19.20-19.40 \u0e19. \u0e14\u0e31\u0e07\u0e19\u0e35\u0e49 1. \u0e27\u0e31\u0e19\u0e1e\u0e24\u0e2b\u0e31\u0e2a\u0e1a\u0e14\u0e35\u0e17\u0e35\u0e48 3 \u0e18\u0e31\u0e19\u0e27\u0e32\u0e04\u0e21 2552 \u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07 \u0e1a\u0e48\u0e2d\u0e40\u0e01\u0e25\u0e37\u0e2d\u0e1a\u0e19\u0e20\u0e39\u0e40\u0e02\u0e32 2. \u0e27\u0e31\u0e19\u0e2d\u0e31\u0e07\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48 8 \u0e18\u0e31\u0e19\u0e27\u0e32\u0e04\u0e21 2552 \u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07 \u0e1b\u0e38\u0e4b\u0e22\u0e2d\u0e34\u0e19\u0e17\u0e23\u0e35\u0e22\u0e4c\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e41\u0e01\u0e49\u0e1b\u0e31\u0e0d\u0e2b\u0e32\u0e14\u0e34\u0e19\u0e16\u0e25\u0e48\u0e21 3. \u0e27\u0e31\u0e19\u0e1e\u0e38\u0e18\u0e17\u0e35\u0e48 9 \u0e18\u0e31\u0e19\u0e27\u0e32\u0e04\u0e21 2552 \u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07 \u0e40\u0e22\u0e32\u0e27\u0e0a\u0e19\u0e23\u0e31\u0e01\u0e29\u0e4c\u0e20\u0e39\u0e1f\u0e49\u0e32\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e23\u0e31\u0e01\u0e29\u0e32\u0e2a\u0e34\u0e48\u0e07\u0e41\u0e27\u0e14\u0e25\u0e49\u0e2d\u0e21 4. \u0e27\u0e31\u0e19\u0e2d\u0e31\u0e07\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48 [&hellip;]","og_url":"https:\/\/www.dmr.go.th\/\u0e18\u0e23\u0e13\u0e35\u0e27\u0e34\u0e17\u0e22\u0e32\u0e01\u0e31\u0e1a\u0e07\u0e32\u0e19\u0e1f\u0e37\u0e49\u0e19\u0e1f\u0e39\u0e43\u0e19\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e1c\u0e25\u0e01\u0e23\u0e30\u0e17\u0e1a\u0e18\u0e23\u0e13\u0e35\u0e1e\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e20\u0e31\u0e22\/","og_site_name":"\u0e01\u0e23\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e32\u0e01\u0e23\u0e18\u0e23\u0e13\u0e35","article_published_time":"2009-12-03T11:10:14+00:00","og_image":[{"width":341,"height":249,"url":"https:\/\/www.dmr.go.th\/wp-content\/uploads\/2022\/10\/default_no_pic-1.jpg","type":"image\/png"}],"author":"\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e18\u0e23\u0e13\u0e35\u0e27\u0e34\u0e17\u0e22\u0e32\u0e2a\u0e34\u0e48\u0e07\u0e41\u0e27\u0e14\u0e25\u0e49\u0e2d\u0e21\u0e41\u0e25\u0e30\u0e18\u0e23\u0e13\u0e35\u0e1e\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e20\u0e31\u0e22","twitter_card":"summary_large_image","twitter_misc":{"Written by":"\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e18\u0e23\u0e13\u0e35\u0e27\u0e34\u0e17\u0e22\u0e32\u0e2a\u0e34\u0e48\u0e07\u0e41\u0e27\u0e14\u0e25\u0e49\u0e2d\u0e21\u0e41\u0e25\u0e30\u0e18\u0e23\u0e13\u0e35\u0e1e\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e20\u0e31\u0e22"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.dmr.go.th\/%e0%b8%98%e0%b8%a3%e0%b8%93%e0%b8%b5%e0%b8%a7%e0%b8%b4%e0%b8%97%e0%b8%a2%e0%b8%b2%e0%b8%81%e0%b8%b1%e0%b8%9a%e0%b8%87%e0%b8%b2%e0%b8%99%e0%b8%9f%e0%b8%b7%e0%b9%89%e0%b8%99%e0%b8%9f%e0%b8%b9%e0%b9%83%e0%b8%99%e0%b8%9e%e0%b8%b7%e0%b9%89%e0%b8%99%e0%b8%97%e0%b8%b5%e0%b9%88%e0%b9%84%e0%b8%94%e0%b9%89%e0%b8%a3%e0%b8%b1%e0%b8%9a%e0%b8%9c%e0%b8%a5%e0%b8%81%e0%b8%a3%e0%b8%b0%e0%b8%97%e0%b8%9a%e0%b8%98%e0%b8%a3%e0%b8%93%e0%b8%b5%e0%b8%9e%e0%b8%b4%e0%b8%9a%e0%b8%b1%e0%b8%95%e0%b8%b4%e0%b8%a0%e0%b8%b1%e0%b8%a2\/#article","isPartOf":{"@id":"https:\/\/www.dmr.go.th\/%e0%b8%98%e0%b8%a3%e0%b8%93%e0%b8%b5%e0%b8%a7%e0%b8%b4%e0%b8%97%e0%b8%a2%e0%b8%b2%e0%b8%81%e0%b8%b1%e0%b8%9a%e0%b8%87%e0%b8%b2%e0%b8%99%e0%b8%9f%e0%b8%b7%e0%b9%89%e0%b8%99%e0%b8%9f%e0%b8%b9%e0%b9%83%e0%b8%99%e0%b8%9e%e0%b8%b7%e0%b9%89%e0%b8%99%e0%b8%97%e0%b8%b5%e0%b9%88%e0%b9%84%e0%b8%94%e0%b9%89%e0%b8%a3%e0%b8%b1%e0%b8%9a%e0%b8%9c%e0%b8%a5%e0%b8%81%e0%b8%a3%e0%b8%b0%e0%b8%97%e0%b8%9a%e0%b8%98%e0%b8%a3%e0%b8%93%e0%b8%b5%e0%b8%9e%e0%b8%b4%e0%b8%9a%e0%b8%b1%e0%b8%95%e0%b8%b4%e0%b8%a0%e0%b8%b1%e0%b8%a2\/"},"author":{"name":"\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e18\u0e23\u0e13\u0e35\u0e27\u0e34\u0e17\u0e22\u0e32\u0e2a\u0e34\u0e48\u0e07\u0e41\u0e27\u0e14\u0e25\u0e49\u0e2d\u0e21\u0e41\u0e25\u0e30\u0e18\u0e23\u0e13\u0e35\u0e1e\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e20\u0e31\u0e22","@id":"https:\/\/www.dmr.go.th\/#\/schema\/person\/f4bc4dd56ee9041de4a03c606749e2bc"},"headline":"\u0e18\u0e23\u0e13\u0e35\u0e27\u0e34\u0e17\u0e22\u0e32\u0e01\u0e31\u0e1a\u0e07\u0e32\u0e19\u0e1f\u0e37\u0e49\u0e19\u0e1f\u0e39\u0e43\u0e19\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e1c\u0e25\u0e01\u0e23\u0e30\u0e17\u0e1a\u0e18\u0e23\u0e13\u0e35\u0e1e\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e20\u0e31\u0e22","datePublished":"2009-12-03T11:10:14+00:00","mainEntityOfPage":{"@id":"https:\/\/www.dmr.go.th\/%e0%b8%98%e0%b8%a3%e0%b8%93%e0%b8%b5%e0%b8%a7%e0%b8%b4%e0%b8%97%e0%b8%a2%e0%b8%b2%e0%b8%81%e0%b8%b1%e0%b8%9a%e0%b8%87%e0%b8%b2%e0%b8%99%e0%b8%9f%e0%b8%b7%e0%b9%89%e0%b8%99%e0%b8%9f%e0%b8%b9%e0%b9%83%e0%b8%99%e0%b8%9e%e0%b8%b7%e0%b9%89%e0%b8%99%e0%b8%97%e0%b8%b5%e0%b9%88%e0%b9%84%e0%b8%94%e0%b9%89%e0%b8%a3%e0%b8%b1%e0%b8%9a%e0%b8%9c%e0%b8%a5%e0%b8%81%e0%b8%a3%e0%b8%b0%e0%b8%97%e0%b8%9a%e0%b8%98%e0%b8%a3%e0%b8%93%e0%b8%b5%e0%b8%9e%e0%b8%b4%e0%b8%9a%e0%b8%b1%e0%b8%95%e0%b8%b4%e0%b8%a0%e0%b8%b1%e0%b8%a2\/"},"wordCount":1,"commentCount":0,"publisher":{"@id":"https:\/\/www.dmr.go.th\/#organization"},"image":{"@id":"https:\/\/www.dmr.go.th\/%e0%b8%98%e0%b8%a3%e0%b8%93%e0%b8%b5%e0%b8%a7%e0%b8%b4%e0%b8%97%e0%b8%a2%e0%b8%b2%e0%b8%81%e0%b8%b1%e0%b8%9a%e0%b8%87%e0%b8%b2%e0%b8%99%e0%b8%9f%e0%b8%b7%e0%b9%89%e0%b8%99%e0%b8%9f%e0%b8%b9%e0%b9%83%e0%b8%99%e0%b8%9e%e0%b8%b7%e0%b9%89%e0%b8%99%e0%b8%97%e0%b8%b5%e0%b9%88%e0%b9%84%e0%b8%94%e0%b9%89%e0%b8%a3%e0%b8%b1%e0%b8%9a%e0%b8%9c%e0%b8%a5%e0%b8%81%e0%b8%a3%e0%b8%b0%e0%b8%97%e0%b8%9a%e0%b8%98%e0%b8%a3%e0%b8%93%e0%b8%b5%e0%b8%9e%e0%b8%b4%e0%b8%9a%e0%b8%b1%e0%b8%95%e0%b8%b4%e0%b8%a0%e0%b8%b1%e0%b8%a2\/#primaryimage"},"thumbnailUrl":"https:\/\/www.dmr.go.th\/wp-content\/uploads\/2022\/10\/default_no_pic-1.jpg","articleSection":["\u0e02\u0e48\u0e32\u0e27\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.dmr.go.th\/%e0%b8%98%e0%b8%a3%e0%b8%93%e0%b8%b5%e0%b8%a7%e0%b8%b4%e0%b8%97%e0%b8%a2%e0%b8%b2%e0%b8%81%e0%b8%b1%e0%b8%9a%e0%b8%87%e0%b8%b2%e0%b8%99%e0%b8%9f%e0%b8%b7%e0%b9%89%e0%b8%99%e0%b8%9f%e0%b8%b9%e0%b9%83%e0%b8%99%e0%b8%9e%e0%b8%b7%e0%b9%89%e0%b8%99%e0%b8%97%e0%b8%b5%e0%b9%88%e0%b9%84%e0%b8%94%e0%b9%89%e0%b8%a3%e0%b8%b1%e0%b8%9a%e0%b8%9c%e0%b8%a5%e0%b8%81%e0%b8%a3%e0%b8%b0%e0%b8%97%e0%b8%9a%e0%b8%98%e0%b8%a3%e0%b8%93%e0%b8%b5%e0%b8%9e%e0%b8%b4%e0%b8%9a%e0%b8%b1%e0%b8%95%e0%b8%b4%e0%b8%a0%e0%b8%b1%e0%b8%a2\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.dmr.go.th\/%e0%b8%98%e0%b8%a3%e0%b8%93%e0%b8%b5%e0%b8%a7%e0%b8%b4%e0%b8%97%e0%b8%a2%e0%b8%b2%e0%b8%81%e0%b8%b1%e0%b8%9a%e0%b8%87%e0%b8%b2%e0%b8%99%e0%b8%9f%e0%b8%b7%e0%b9%89%e0%b8%99%e0%b8%9f%e0%b8%b9%e0%b9%83%e0%b8%99%e0%b8%9e%e0%b8%b7%e0%b9%89%e0%b8%99%e0%b8%97%e0%b8%b5%e0%b9%88%e0%b9%84%e0%b8%94%e0%b9%89%e0%b8%a3%e0%b8%b1%e0%b8%9a%e0%b8%9c%e0%b8%a5%e0%b8%81%e0%b8%a3%e0%b8%b0%e0%b8%97%e0%b8%9a%e0%b8%98%e0%b8%a3%e0%b8%93%e0%b8%b5%e0%b8%9e%e0%b8%b4%e0%b8%9a%e0%b8%b1%e0%b8%95%e0%b8%b4%e0%b8%a0%e0%b8%b1%e0%b8%a2\/","url":"https:\/\/www.dmr.go.th\/%e0%b8%98%e0%b8%a3%e0%b8%93%e0%b8%b5%e0%b8%a7%e0%b8%b4%e0%b8%97%e0%b8%a2%e0%b8%b2%e0%b8%81%e0%b8%b1%e0%b8%9a%e0%b8%87%e0%b8%b2%e0%b8%99%e0%b8%9f%e0%b8%b7%e0%b9%89%e0%b8%99%e0%b8%9f%e0%b8%b9%e0%b9%83%e0%b8%99%e0%b8%9e%e0%b8%b7%e0%b9%89%e0%b8%99%e0%b8%97%e0%b8%b5%e0%b9%88%e0%b9%84%e0%b8%94%e0%b9%89%e0%b8%a3%e0%b8%b1%e0%b8%9a%e0%b8%9c%e0%b8%a5%e0%b8%81%e0%b8%a3%e0%b8%b0%e0%b8%97%e0%b8%9a%e0%b8%98%e0%b8%a3%e0%b8%93%e0%b8%b5%e0%b8%9e%e0%b8%b4%e0%b8%9a%e0%b8%b1%e0%b8%95%e0%b8%b4%e0%b8%a0%e0%b8%b1%e0%b8%a2\/","name":"\u0e18\u0e23\u0e13\u0e35\u0e27\u0e34\u0e17\u0e22\u0e32\u0e01\u0e31\u0e1a\u0e07\u0e32\u0e19\u0e1f\u0e37\u0e49\u0e19\u0e1f\u0e39\u0e43\u0e19\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e1c\u0e25\u0e01\u0e23\u0e30\u0e17\u0e1a\u0e18\u0e23\u0e13\u0e35\u0e1e\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e20\u0e31\u0e22 - \u0e01\u0e23\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e32\u0e01\u0e23\u0e18\u0e23\u0e13\u0e35","isPartOf":{"@id":"https:\/\/www.dmr.go.th\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.dmr.go.th\/%e0%b8%98%e0%b8%a3%e0%b8%93%e0%b8%b5%e0%b8%a7%e0%b8%b4%e0%b8%97%e0%b8%a2%e0%b8%b2%e0%b8%81%e0%b8%b1%e0%b8%9a%e0%b8%87%e0%b8%b2%e0%b8%99%e0%b8%9f%e0%b8%b7%e0%b9%89%e0%b8%99%e0%b8%9f%e0%b8%b9%e0%b9%83%e0%b8%99%e0%b8%9e%e0%b8%b7%e0%b9%89%e0%b8%99%e0%b8%97%e0%b8%b5%e0%b9%88%e0%b9%84%e0%b8%94%e0%b9%89%e0%b8%a3%e0%b8%b1%e0%b8%9a%e0%b8%9c%e0%b8%a5%e0%b8%81%e0%b8%a3%e0%b8%b0%e0%b8%97%e0%b8%9a%e0%b8%98%e0%b8%a3%e0%b8%93%e0%b8%b5%e0%b8%9e%e0%b8%b4%e0%b8%9a%e0%b8%b1%e0%b8%95%e0%b8%b4%e0%b8%a0%e0%b8%b1%e0%b8%a2\/#primaryimage"},"image":{"@id":"https:\/\/www.dmr.go.th\/%e0%b8%98%e0%b8%a3%e0%b8%93%e0%b8%b5%e0%b8%a7%e0%b8%b4%e0%b8%97%e0%b8%a2%e0%b8%b2%e0%b8%81%e0%b8%b1%e0%b8%9a%e0%b8%87%e0%b8%b2%e0%b8%99%e0%b8%9f%e0%b8%b7%e0%b9%89%e0%b8%99%e0%b8%9f%e0%b8%b9%e0%b9%83%e0%b8%99%e0%b8%9e%e0%b8%b7%e0%b9%89%e0%b8%99%e0%b8%97%e0%b8%b5%e0%b9%88%e0%b9%84%e0%b8%94%e0%b9%89%e0%b8%a3%e0%b8%b1%e0%b8%9a%e0%b8%9c%e0%b8%a5%e0%b8%81%e0%b8%a3%e0%b8%b0%e0%b8%97%e0%b8%9a%e0%b8%98%e0%b8%a3%e0%b8%93%e0%b8%b5%e0%b8%9e%e0%b8%b4%e0%b8%9a%e0%b8%b1%e0%b8%95%e0%b8%b4%e0%b8%a0%e0%b8%b1%e0%b8%a2\/#primaryimage"},"thumbnailUrl":"https:\/\/www.dmr.go.th\/wp-content\/uploads\/2022\/10\/default_no_pic-1.jpg","datePublished":"2009-12-03T11:10:14+00:00","breadcrumb":{"@id":"https:\/\/www.dmr.go.th\/%e0%b8%98%e0%b8%a3%e0%b8%93%e0%b8%b5%e0%b8%a7%e0%b8%b4%e0%b8%97%e0%b8%a2%e0%b8%b2%e0%b8%81%e0%b8%b1%e0%b8%9a%e0%b8%87%e0%b8%b2%e0%b8%99%e0%b8%9f%e0%b8%b7%e0%b9%89%e0%b8%99%e0%b8%9f%e0%b8%b9%e0%b9%83%e0%b8%99%e0%b8%9e%e0%b8%b7%e0%b9%89%e0%b8%99%e0%b8%97%e0%b8%b5%e0%b9%88%e0%b9%84%e0%b8%94%e0%b9%89%e0%b8%a3%e0%b8%b1%e0%b8%9a%e0%b8%9c%e0%b8%a5%e0%b8%81%e0%b8%a3%e0%b8%b0%e0%b8%97%e0%b8%9a%e0%b8%98%e0%b8%a3%e0%b8%93%e0%b8%b5%e0%b8%9e%e0%b8%b4%e0%b8%9a%e0%b8%b1%e0%b8%95%e0%b8%b4%e0%b8%a0%e0%b8%b1%e0%b8%a2\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.dmr.go.th\/%e0%b8%98%e0%b8%a3%e0%b8%93%e0%b8%b5%e0%b8%a7%e0%b8%b4%e0%b8%97%e0%b8%a2%e0%b8%b2%e0%b8%81%e0%b8%b1%e0%b8%9a%e0%b8%87%e0%b8%b2%e0%b8%99%e0%b8%9f%e0%b8%b7%e0%b9%89%e0%b8%99%e0%b8%9f%e0%b8%b9%e0%b9%83%e0%b8%99%e0%b8%9e%e0%b8%b7%e0%b9%89%e0%b8%99%e0%b8%97%e0%b8%b5%e0%b9%88%e0%b9%84%e0%b8%94%e0%b9%89%e0%b8%a3%e0%b8%b1%e0%b8%9a%e0%b8%9c%e0%b8%a5%e0%b8%81%e0%b8%a3%e0%b8%b0%e0%b8%97%e0%b8%9a%e0%b8%98%e0%b8%a3%e0%b8%93%e0%b8%b5%e0%b8%9e%e0%b8%b4%e0%b8%9a%e0%b8%b1%e0%b8%95%e0%b8%b4%e0%b8%a0%e0%b8%b1%e0%b8%a2\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.dmr.go.th\/%e0%b8%98%e0%b8%a3%e0%b8%93%e0%b8%b5%e0%b8%a7%e0%b8%b4%e0%b8%97%e0%b8%a2%e0%b8%b2%e0%b8%81%e0%b8%b1%e0%b8%9a%e0%b8%87%e0%b8%b2%e0%b8%99%e0%b8%9f%e0%b8%b7%e0%b9%89%e0%b8%99%e0%b8%9f%e0%b8%b9%e0%b9%83%e0%b8%99%e0%b8%9e%e0%b8%b7%e0%b9%89%e0%b8%99%e0%b8%97%e0%b8%b5%e0%b9%88%e0%b9%84%e0%b8%94%e0%b9%89%e0%b8%a3%e0%b8%b1%e0%b8%9a%e0%b8%9c%e0%b8%a5%e0%b8%81%e0%b8%a3%e0%b8%b0%e0%b8%97%e0%b8%9a%e0%b8%98%e0%b8%a3%e0%b8%93%e0%b8%b5%e0%b8%9e%e0%b8%b4%e0%b8%9a%e0%b8%b1%e0%b8%95%e0%b8%b4%e0%b8%a0%e0%b8%b1%e0%b8%a2\/#primaryimage","url":"https:\/\/www.dmr.go.th\/wp-content\/uploads\/2022\/10\/default_no_pic-1.jpg","contentUrl":"https:\/\/www.dmr.go.th\/wp-content\/uploads\/2022\/10\/default_no_pic-1.jpg","width":341,"height":249,"caption":"\u0e01\u0e23\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e32\u0e01\u0e23\u0e18\u0e23\u0e13\u0e35"},{"@type":"BreadcrumbList","@id":"https:\/\/www.dmr.go.th\/%e0%b8%98%e0%b8%a3%e0%b8%93%e0%b8%b5%e0%b8%a7%e0%b8%b4%e0%b8%97%e0%b8%a2%e0%b8%b2%e0%b8%81%e0%b8%b1%e0%b8%9a%e0%b8%87%e0%b8%b2%e0%b8%99%e0%b8%9f%e0%b8%b7%e0%b9%89%e0%b8%99%e0%b8%9f%e0%b8%b9%e0%b9%83%e0%b8%99%e0%b8%9e%e0%b8%b7%e0%b9%89%e0%b8%99%e0%b8%97%e0%b8%b5%e0%b9%88%e0%b9%84%e0%b8%94%e0%b9%89%e0%b8%a3%e0%b8%b1%e0%b8%9a%e0%b8%9c%e0%b8%a5%e0%b8%81%e0%b8%a3%e0%b8%b0%e0%b8%97%e0%b8%9a%e0%b8%98%e0%b8%a3%e0%b8%93%e0%b8%b5%e0%b8%9e%e0%b8%b4%e0%b8%9a%e0%b8%b1%e0%b8%95%e0%b8%b4%e0%b8%a0%e0%b8%b1%e0%b8%a2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.dmr.go.th\/"},{"@type":"ListItem","position":2,"name":"\u0e18\u0e23\u0e13\u0e35\u0e27\u0e34\u0e17\u0e22\u0e32\u0e01\u0e31\u0e1a\u0e07\u0e32\u0e19\u0e1f\u0e37\u0e49\u0e19\u0e1f\u0e39\u0e43\u0e19\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e1c\u0e25\u0e01\u0e23\u0e30\u0e17\u0e1a\u0e18\u0e23\u0e13\u0e35\u0e1e\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e20\u0e31\u0e22"}]},{"@type":"WebSite","@id":"https:\/\/www.dmr.go.th\/#website","url":"https:\/\/www.dmr.go.th\/","name":"\u0e01\u0e23\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e32\u0e01\u0e23\u0e18\u0e23\u0e13\u0e35","description":"\u0e01\u0e23\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e32\u0e01\u0e23\u0e18\u0e23\u0e13\u0e35","publisher":{"@id":"https:\/\/www.dmr.go.th\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.dmr.go.th\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.dmr.go.th\/#organization","name":"\u0e01\u0e23\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e32\u0e01\u0e23\u0e18\u0e23\u0e13\u0e35","url":"https:\/\/www.dmr.go.th\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.dmr.go.th\/#\/schema\/logo\/image\/","url":"https:\/\/www.dmr.go.th\/wp-content\/uploads\/2022\/08\/\u0e15\u0e23\u0e32\u0e01\u0e23\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e32\u0e01\u0e23\u0e18\u0e23\u0e13\u0e35-2.png","contentUrl":"https:\/\/www.dmr.go.th\/wp-content\/uploads\/2022\/08\/\u0e15\u0e23\u0e32\u0e01\u0e23\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e32\u0e01\u0e23\u0e18\u0e23\u0e13\u0e35-2.png","width":400,"height":400,"caption":"\u0e01\u0e23\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e32\u0e01\u0e23\u0e18\u0e23\u0e13\u0e35"},"image":{"@id":"https:\/\/www.dmr.go.th\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.dmr.go.th\/#\/schema\/person\/f4bc4dd56ee9041de4a03c606749e2bc","name":"\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e18\u0e23\u0e13\u0e35\u0e27\u0e34\u0e17\u0e22\u0e32\u0e2a\u0e34\u0e48\u0e07\u0e41\u0e27\u0e14\u0e25\u0e49\u0e2d\u0e21\u0e41\u0e25\u0e30\u0e18\u0e23\u0e13\u0e35\u0e1e\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e20\u0e31\u0e22","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.dmr.go.th\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/16cd7e279959e64661a4e273e93548cbadc539d0c3f9f0db93f4c4c1c30720c0?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/16cd7e279959e64661a4e273e93548cbadc539d0c3f9f0db93f4c4c1c30720c0?s=96&d=mm&r=g","caption":"\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e18\u0e23\u0e13\u0e35\u0e27\u0e34\u0e17\u0e22\u0e32\u0e2a\u0e34\u0e48\u0e07\u0e41\u0e27\u0e14\u0e25\u0e49\u0e2d\u0e21\u0e41\u0e25\u0e30\u0e18\u0e23\u0e13\u0e35\u0e1e\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e20\u0e31\u0e22"},"sameAs":["https:\/\/www.dmr.go.th"],"url":"https:\/\/www.dmr.go.th\/en\/author\/amika-bcipher-co-th\/"}]}},"_links":{"self":[{"href":"https:\/\/www.dmr.go.th\/en\/wp-json\/wp\/v2\/posts\/172299","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.dmr.go.th\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.dmr.go.th\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.dmr.go.th\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.dmr.go.th\/en\/wp-json\/wp\/v2\/comments?post=172299"}],"version-history":[{"count":0,"href":"https:\/\/www.dmr.go.th\/en\/wp-json\/wp\/v2\/posts\/172299\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.dmr.go.th\/en\/wp-json\/wp\/v2\/media\/165448"}],"wp:attachment":[{"href":"https:\/\/www.dmr.go.th\/en\/wp-json\/wp\/v2\/media?parent=172299"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.dmr.go.th\/en\/wp-json\/wp\/v2\/categories?post=172299"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.dmr.go.th\/en\/wp-json\/wp\/v2\/tags?post=172299"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}