{"id":215846,"date":"2023-08-21T10:47:18","date_gmt":"2023-08-21T03:47:18","guid":{"rendered":"https:\/\/www.dmr.go.th\/?p=215846"},"modified":"2023-08-21T10:47:20","modified_gmt":"2023-08-21T03:47:20","slug":"%e0%b8%9a-%e0%b8%9b%e0%b8%a5%e0%b8%b2%e0%b8%9a%e0%b9%88%e0%b8%b2-%e0%b8%95-%e0%b8%9b%e0%b8%a5%e0%b8%b2%e0%b8%9a%e0%b9%88%e0%b8%b2-%e0%b8%ad-%e0%b8%a0%e0%b8%b9%e0%b9%80%e0%b8%a3%e0%b8%b7%e0%b8%ad-%e0%b8%88-%e0%b9%80%e0%b8%a5%e0%b8%a2_%e0%b8%a7%e0%b8%b1%e0%b8%94%e0%b8%9b%e0%b8%a3%e0%b8%b4%e0%b8%a1%e0%b8%b2%e0%b8%93%e0%b8%99%e0%b9%89%e0%b8%b3%e0%b8%9d%e0%b8%99%e0%b9%84%e0%b8%94%e0%b9%89-30-%e0%b8%a1%e0%b8%a1-%e0%b8%a1%e0%b8%b5%e0%b8%9d%e0%b8%99%e0%b8%95%e0%b8%81%e0%b9%80%e0%b8%a5%e0%b9%87%e0%b8%81%e0%b8%99%e0%b9%89%e0%b8%ad%e0%b8%a2","status":"publish","type":"post","link":"https:\/\/www.dmr.go.th\/en\/%e0%b8%9a-%e0%b8%9b%e0%b8%a5%e0%b8%b2%e0%b8%9a%e0%b9%88%e0%b8%b2-%e0%b8%95-%e0%b8%9b%e0%b8%a5%e0%b8%b2%e0%b8%9a%e0%b9%88%e0%b8%b2-%e0%b8%ad-%e0%b8%a0%e0%b8%b9%e0%b9%80%e0%b8%a3%e0%b8%b7%e0%b8%ad-%e0%b8%88-%e0%b9%80%e0%b8%a5%e0%b8%a2_%e0%b8%a7%e0%b8%b1%e0%b8%94%e0%b8%9b%e0%b8%a3%e0%b8%b4%e0%b8%a1%e0%b8%b2%e0%b8%93%e0%b8%99%e0%b9%89%e0%b8%b3%e0%b8%9d%e0%b8%99%e0%b9%84%e0%b8%94%e0%b9%89-30-%e0%b8%a1%e0%b8%a1-%e0%b8%a1%e0%b8%b5%e0%b8%9d%e0%b8%99%e0%b8%95%e0%b8%81%e0%b9%80%e0%b8%a5%e0%b9%87%e0%b8%81%e0%b8%99%e0%b9%89%e0%b8%ad%e0%b8%a2\/","title":{"rendered":"\u0e1a.\u0e1b\u0e25\u0e32\u0e1a\u0e48\u0e32 \u0e15.\u0e1b\u0e25\u0e32\u0e1a\u0e48\u0e32  \u0e2d.\u0e20\u0e39\u0e40\u0e23\u0e37\u0e2d \u0e08.\u0e40\u0e25\u0e22_\u0e27\u0e31\u0e14\u0e1b\u0e23\u0e34\u0e21\u0e32\u0e13\u0e19\u0e49\u0e33\u0e1d\u0e19\u0e44\u0e14\u0e49 30 \u0e21\u0e21. \u0e21\u0e35\u0e1d\u0e19\u0e15\u0e01\u0e40\u0e25\u0e47\u0e01\u0e19\u0e49\u0e2d\u0e22"},"content":{"rendered":"\n<p>\u0e1a.\u0e1b\u0e25\u0e32\u0e1a\u0e48\u0e32 \u0e15.\u0e1b\u0e25\u0e32\u0e1a\u0e48\u0e32  \u0e2d.\u0e20\u0e39\u0e40\u0e23\u0e37\u0e2d \u0e08.\u0e40\u0e25\u0e22_\u0e27\u0e31\u0e14\u0e1b\u0e23\u0e34\u0e21\u0e32\u0e13\u0e19\u0e49\u0e33\u0e1d\u0e19\u0e44\u0e14\u0e49 30 \u0e21\u0e21. \u0e21\u0e35\u0e1d\u0e19\u0e15\u0e01\u0e40\u0e25\u0e47\u0e01\u0e19\u0e49\u0e2d\u0e22<\/p>\n\n\n\n<p>\u0e17\u0e35\u0e48\u0e21\u0e32 ; \u0e19\u0e32\u0e22\u0e21\u0e19\u0e15\u0e23\u0e35 \u0e28\u0e23\u0e35\u0e1a\u0e38\u0e23\u0e34\u0e19\u0e17\u0e23\u0e4c<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u0e1a.\u0e1b\u0e25\u0e32\u0e1a\u0e48\u0e32 \u0e15.\u0e1b\u0e25\u0e32\u0e1a\u0e48\u0e32 \u0e2d.\u0e20\u0e39\u0e40\u0e23\u0e37\u0e2d \u0e08.\u0e40\u0e25\u0e22_\u0e27\u0e31\u0e14\u0e1b\u0e23\u0e34\u0e21\u0e32\u0e13\u0e19\u0e49\u0e33\u0e1d\u0e19\u0e44\u0e14\u0e49 30 \u0e21\u0e21. \u0e21\u0e35\u0e1d\u0e19\u0e15\u0e01\u0e40\u0e25\u0e47\u0e01\u0e19\u0e49\u0e2d\u0e22 \u0e17\u0e35\u0e48\u0e21\u0e32 ; \u0e19\u0e32\u0e22\u0e21\u0e19\u0e15\u0e23\u0e35 \u0e28\u0e23\u0e35\u0e1a\u0e38\u0e23\u0e34\u0e19\u0e17\u0e23\u0e4c<\/p>\n","protected":false},"author":31,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-215846","post","type-post","status-publish","format-standard","hentry","category-uncategorized-th"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u0e1a.\u0e1b\u0e25\u0e32\u0e1a\u0e48\u0e32 \u0e15.\u0e1b\u0e25\u0e32\u0e1a\u0e48\u0e32 \u0e2d.\u0e20\u0e39\u0e40\u0e23\u0e37\u0e2d \u0e08.\u0e40\u0e25\u0e22_\u0e27\u0e31\u0e14\u0e1b\u0e23\u0e34\u0e21\u0e32\u0e13\u0e19\u0e49\u0e33\u0e1d\u0e19\u0e44\u0e14\u0e49 30 \u0e21\u0e21. \u0e21\u0e35\u0e1d\u0e19\u0e15\u0e01\u0e40\u0e25\u0e47\u0e01\u0e19\u0e49\u0e2d\u0e22 - \u0e01\u0e23\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e32\u0e01\u0e23\u0e18\u0e23\u0e13\u0e35<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.dmr.go.th\/\u0e1a-\u0e1b\u0e25\u0e32\u0e1a\u0e48\u0e32-\u0e15-\u0e1b\u0e25\u0e32\u0e1a\u0e48\u0e32-\u0e2d-\u0e20\u0e39\u0e40\u0e23\u0e37\u0e2d-\u0e08-\u0e40\u0e25\u0e22_\u0e27\u0e31\u0e14\u0e1b\u0e23\u0e34\u0e21\u0e32\u0e13\u0e19\u0e49\u0e33\u0e1d\u0e19\u0e44\u0e14\u0e49-30-\u0e21\u0e21-\u0e21\u0e35\u0e1d\u0e19\u0e15\u0e01\u0e40\u0e25\u0e47\u0e01\u0e19\u0e49\u0e2d\u0e22\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u0e1a.\u0e1b\u0e25\u0e32\u0e1a\u0e48\u0e32 \u0e15.\u0e1b\u0e25\u0e32\u0e1a\u0e48\u0e32 \u0e2d.\u0e20\u0e39\u0e40\u0e23\u0e37\u0e2d \u0e08.\u0e40\u0e25\u0e22_\u0e27\u0e31\u0e14\u0e1b\u0e23\u0e34\u0e21\u0e32\u0e13\u0e19\u0e49\u0e33\u0e1d\u0e19\u0e44\u0e14\u0e49 30 \u0e21\u0e21. \u0e21\u0e35\u0e1d\u0e19\u0e15\u0e01\u0e40\u0e25\u0e47\u0e01\u0e19\u0e49\u0e2d\u0e22 - \u0e01\u0e23\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e32\u0e01\u0e23\u0e18\u0e23\u0e13\u0e35\" \/>\n<meta property=\"og:description\" content=\"\u0e1a.\u0e1b\u0e25\u0e32\u0e1a\u0e48\u0e32 \u0e15.\u0e1b\u0e25\u0e32\u0e1a\u0e48\u0e32 \u0e2d.\u0e20\u0e39\u0e40\u0e23\u0e37\u0e2d \u0e08.\u0e40\u0e25\u0e22_\u0e27\u0e31\u0e14\u0e1b\u0e23\u0e34\u0e21\u0e32\u0e13\u0e19\u0e49\u0e33\u0e1d\u0e19\u0e44\u0e14\u0e49 30 \u0e21\u0e21. \u0e21\u0e35\u0e1d\u0e19\u0e15\u0e01\u0e40\u0e25\u0e47\u0e01\u0e19\u0e49\u0e2d\u0e22 \u0e17\u0e35\u0e48\u0e21\u0e32 ; \u0e19\u0e32\u0e22\u0e21\u0e19\u0e15\u0e23\u0e35 \u0e28\u0e23\u0e35\u0e1a\u0e38\u0e23\u0e34\u0e19\u0e17\u0e23\u0e4c\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.dmr.go.th\/\u0e1a-\u0e1b\u0e25\u0e32\u0e1a\u0e48\u0e32-\u0e15-\u0e1b\u0e25\u0e32\u0e1a\u0e48\u0e32-\u0e2d-\u0e20\u0e39\u0e40\u0e23\u0e37\u0e2d-\u0e08-\u0e40\u0e25\u0e22_\u0e27\u0e31\u0e14\u0e1b\u0e23\u0e34\u0e21\u0e32\u0e13\u0e19\u0e49\u0e33\u0e1d\u0e19\u0e44\u0e14\u0e49-30-\u0e21\u0e21-\u0e21\u0e35\u0e1d\u0e19\u0e15\u0e01\u0e40\u0e25\u0e47\u0e01\u0e19\u0e49\u0e2d\u0e22\/\" \/>\n<meta property=\"og:site_name\" content=\"\u0e01\u0e23\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e32\u0e01\u0e23\u0e18\u0e23\u0e13\u0e35\" \/>\n<meta property=\"article:published_time\" content=\"2023-08-21T03:47:18+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-08-21T03:47:20+00:00\" \/>\n<meta name=\"author\" content=\"\u0e28\u0e39\u0e19\u0e22\u0e4c\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e01\u0e32\u0e23\u0e18\u0e23\u0e13\u0e35\u0e1e\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e20\u0e31\u0e22\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"\u0e28\u0e39\u0e19\u0e22\u0e4c\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e01\u0e32\u0e23\u0e18\u0e23\u0e13\u0e35\u0e1e\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e20\u0e31\u0e22\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.dmr.go.th\/%e0%b8%9a-%e0%b8%9b%e0%b8%a5%e0%b8%b2%e0%b8%9a%e0%b9%88%e0%b8%b2-%e0%b8%95-%e0%b8%9b%e0%b8%a5%e0%b8%b2%e0%b8%9a%e0%b9%88%e0%b8%b2-%e0%b8%ad-%e0%b8%a0%e0%b8%b9%e0%b9%80%e0%b8%a3%e0%b8%b7%e0%b8%ad-%e0%b8%88-%e0%b9%80%e0%b8%a5%e0%b8%a2_%e0%b8%a7%e0%b8%b1%e0%b8%94%e0%b8%9b%e0%b8%a3%e0%b8%b4%e0%b8%a1%e0%b8%b2%e0%b8%93%e0%b8%99%e0%b9%89%e0%b8%b3%e0%b8%9d%e0%b8%99%e0%b9%84%e0%b8%94%e0%b9%89-30-%e0%b8%a1%e0%b8%a1-%e0%b8%a1%e0%b8%b5%e0%b8%9d%e0%b8%99%e0%b8%95%e0%b8%81%e0%b9%80%e0%b8%a5%e0%b9%87%e0%b8%81%e0%b8%99%e0%b9%89%e0%b8%ad%e0%b8%a2\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.dmr.go.th\/%e0%b8%9a-%e0%b8%9b%e0%b8%a5%e0%b8%b2%e0%b8%9a%e0%b9%88%e0%b8%b2-%e0%b8%95-%e0%b8%9b%e0%b8%a5%e0%b8%b2%e0%b8%9a%e0%b9%88%e0%b8%b2-%e0%b8%ad-%e0%b8%a0%e0%b8%b9%e0%b9%80%e0%b8%a3%e0%b8%b7%e0%b8%ad-%e0%b8%88-%e0%b9%80%e0%b8%a5%e0%b8%a2_%e0%b8%a7%e0%b8%b1%e0%b8%94%e0%b8%9b%e0%b8%a3%e0%b8%b4%e0%b8%a1%e0%b8%b2%e0%b8%93%e0%b8%99%e0%b9%89%e0%b8%b3%e0%b8%9d%e0%b8%99%e0%b9%84%e0%b8%94%e0%b9%89-30-%e0%b8%a1%e0%b8%a1-%e0%b8%a1%e0%b8%b5%e0%b8%9d%e0%b8%99%e0%b8%95%e0%b8%81%e0%b9%80%e0%b8%a5%e0%b9%87%e0%b8%81%e0%b8%99%e0%b9%89%e0%b8%ad%e0%b8%a2\/\"},\"author\":{\"name\":\"\u0e28\u0e39\u0e19\u0e22\u0e4c\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e01\u0e32\u0e23\u0e18\u0e23\u0e13\u0e35\u0e1e\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e20\u0e31\u0e22\",\"@id\":\"https:\/\/www.dmr.go.th\/#\/schema\/person\/4f0313ebbcd75dd20a40f88259c955b7\"},\"headline\":\"\u0e1a.\u0e1b\u0e25\u0e32\u0e1a\u0e48\u0e32 \u0e15.\u0e1b\u0e25\u0e32\u0e1a\u0e48\u0e32 \u0e2d.\u0e20\u0e39\u0e40\u0e23\u0e37\u0e2d \u0e08.\u0e40\u0e25\u0e22_\u0e27\u0e31\u0e14\u0e1b\u0e23\u0e34\u0e21\u0e32\u0e13\u0e19\u0e49\u0e33\u0e1d\u0e19\u0e44\u0e14\u0e49 30 \u0e21\u0e21. \u0e21\u0e35\u0e1d\u0e19\u0e15\u0e01\u0e40\u0e25\u0e47\u0e01\u0e19\u0e49\u0e2d\u0e22\",\"datePublished\":\"2023-08-21T03:47:18+00:00\",\"dateModified\":\"2023-08-21T03:47:20+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.dmr.go.th\/%e0%b8%9a-%e0%b8%9b%e0%b8%a5%e0%b8%b2%e0%b8%9a%e0%b9%88%e0%b8%b2-%e0%b8%95-%e0%b8%9b%e0%b8%a5%e0%b8%b2%e0%b8%9a%e0%b9%88%e0%b8%b2-%e0%b8%ad-%e0%b8%a0%e0%b8%b9%e0%b9%80%e0%b8%a3%e0%b8%b7%e0%b8%ad-%e0%b8%88-%e0%b9%80%e0%b8%a5%e0%b8%a2_%e0%b8%a7%e0%b8%b1%e0%b8%94%e0%b8%9b%e0%b8%a3%e0%b8%b4%e0%b8%a1%e0%b8%b2%e0%b8%93%e0%b8%99%e0%b9%89%e0%b8%b3%e0%b8%9d%e0%b8%99%e0%b9%84%e0%b8%94%e0%b9%89-30-%e0%b8%a1%e0%b8%a1-%e0%b8%a1%e0%b8%b5%e0%b8%9d%e0%b8%99%e0%b8%95%e0%b8%81%e0%b9%80%e0%b8%a5%e0%b9%87%e0%b8%81%e0%b8%99%e0%b9%89%e0%b8%ad%e0%b8%a2\/\"},\"wordCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.dmr.go.th\/#organization\"},\"articleSection\":[\"Uncategorized @th\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.dmr.go.th\/%e0%b8%9a-%e0%b8%9b%e0%b8%a5%e0%b8%b2%e0%b8%9a%e0%b9%88%e0%b8%b2-%e0%b8%95-%e0%b8%9b%e0%b8%a5%e0%b8%b2%e0%b8%9a%e0%b9%88%e0%b8%b2-%e0%b8%ad-%e0%b8%a0%e0%b8%b9%e0%b9%80%e0%b8%a3%e0%b8%b7%e0%b8%ad-%e0%b8%88-%e0%b9%80%e0%b8%a5%e0%b8%a2_%e0%b8%a7%e0%b8%b1%e0%b8%94%e0%b8%9b%e0%b8%a3%e0%b8%b4%e0%b8%a1%e0%b8%b2%e0%b8%93%e0%b8%99%e0%b9%89%e0%b8%b3%e0%b8%9d%e0%b8%99%e0%b9%84%e0%b8%94%e0%b9%89-30-%e0%b8%a1%e0%b8%a1-%e0%b8%a1%e0%b8%b5%e0%b8%9d%e0%b8%99%e0%b8%95%e0%b8%81%e0%b9%80%e0%b8%a5%e0%b9%87%e0%b8%81%e0%b8%99%e0%b9%89%e0%b8%ad%e0%b8%a2\/\",\"url\":\"https:\/\/www.dmr.go.th\/%e0%b8%9a-%e0%b8%9b%e0%b8%a5%e0%b8%b2%e0%b8%9a%e0%b9%88%e0%b8%b2-%e0%b8%95-%e0%b8%9b%e0%b8%a5%e0%b8%b2%e0%b8%9a%e0%b9%88%e0%b8%b2-%e0%b8%ad-%e0%b8%a0%e0%b8%b9%e0%b9%80%e0%b8%a3%e0%b8%b7%e0%b8%ad-%e0%b8%88-%e0%b9%80%e0%b8%a5%e0%b8%a2_%e0%b8%a7%e0%b8%b1%e0%b8%94%e0%b8%9b%e0%b8%a3%e0%b8%b4%e0%b8%a1%e0%b8%b2%e0%b8%93%e0%b8%99%e0%b9%89%e0%b8%b3%e0%b8%9d%e0%b8%99%e0%b9%84%e0%b8%94%e0%b9%89-30-%e0%b8%a1%e0%b8%a1-%e0%b8%a1%e0%b8%b5%e0%b8%9d%e0%b8%99%e0%b8%95%e0%b8%81%e0%b9%80%e0%b8%a5%e0%b9%87%e0%b8%81%e0%b8%99%e0%b9%89%e0%b8%ad%e0%b8%a2\/\",\"name\":\"\u0e1a.\u0e1b\u0e25\u0e32\u0e1a\u0e48\u0e32 \u0e15.\u0e1b\u0e25\u0e32\u0e1a\u0e48\u0e32 \u0e2d.\u0e20\u0e39\u0e40\u0e23\u0e37\u0e2d \u0e08.\u0e40\u0e25\u0e22_\u0e27\u0e31\u0e14\u0e1b\u0e23\u0e34\u0e21\u0e32\u0e13\u0e19\u0e49\u0e33\u0e1d\u0e19\u0e44\u0e14\u0e49 30 \u0e21\u0e21. \u0e21\u0e35\u0e1d\u0e19\u0e15\u0e01\u0e40\u0e25\u0e47\u0e01\u0e19\u0e49\u0e2d\u0e22 - \u0e01\u0e23\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e32\u0e01\u0e23\u0e18\u0e23\u0e13\u0e35\",\"isPartOf\":{\"@id\":\"https:\/\/www.dmr.go.th\/#website\"},\"datePublished\":\"2023-08-21T03:47:18+00:00\",\"dateModified\":\"2023-08-21T03:47:20+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.dmr.go.th\/%e0%b8%9a-%e0%b8%9b%e0%b8%a5%e0%b8%b2%e0%b8%9a%e0%b9%88%e0%b8%b2-%e0%b8%95-%e0%b8%9b%e0%b8%a5%e0%b8%b2%e0%b8%9a%e0%b9%88%e0%b8%b2-%e0%b8%ad-%e0%b8%a0%e0%b8%b9%e0%b9%80%e0%b8%a3%e0%b8%b7%e0%b8%ad-%e0%b8%88-%e0%b9%80%e0%b8%a5%e0%b8%a2_%e0%b8%a7%e0%b8%b1%e0%b8%94%e0%b8%9b%e0%b8%a3%e0%b8%b4%e0%b8%a1%e0%b8%b2%e0%b8%93%e0%b8%99%e0%b9%89%e0%b8%b3%e0%b8%9d%e0%b8%99%e0%b9%84%e0%b8%94%e0%b9%89-30-%e0%b8%a1%e0%b8%a1-%e0%b8%a1%e0%b8%b5%e0%b8%9d%e0%b8%99%e0%b8%95%e0%b8%81%e0%b9%80%e0%b8%a5%e0%b9%87%e0%b8%81%e0%b8%99%e0%b9%89%e0%b8%ad%e0%b8%a2\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.dmr.go.th\/%e0%b8%9a-%e0%b8%9b%e0%b8%a5%e0%b8%b2%e0%b8%9a%e0%b9%88%e0%b8%b2-%e0%b8%95-%e0%b8%9b%e0%b8%a5%e0%b8%b2%e0%b8%9a%e0%b9%88%e0%b8%b2-%e0%b8%ad-%e0%b8%a0%e0%b8%b9%e0%b9%80%e0%b8%a3%e0%b8%b7%e0%b8%ad-%e0%b8%88-%e0%b9%80%e0%b8%a5%e0%b8%a2_%e0%b8%a7%e0%b8%b1%e0%b8%94%e0%b8%9b%e0%b8%a3%e0%b8%b4%e0%b8%a1%e0%b8%b2%e0%b8%93%e0%b8%99%e0%b9%89%e0%b8%b3%e0%b8%9d%e0%b8%99%e0%b9%84%e0%b8%94%e0%b9%89-30-%e0%b8%a1%e0%b8%a1-%e0%b8%a1%e0%b8%b5%e0%b8%9d%e0%b8%99%e0%b8%95%e0%b8%81%e0%b9%80%e0%b8%a5%e0%b9%87%e0%b8%81%e0%b8%99%e0%b9%89%e0%b8%ad%e0%b8%a2\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.dmr.go.th\/%e0%b8%9a-%e0%b8%9b%e0%b8%a5%e0%b8%b2%e0%b8%9a%e0%b9%88%e0%b8%b2-%e0%b8%95-%e0%b8%9b%e0%b8%a5%e0%b8%b2%e0%b8%9a%e0%b9%88%e0%b8%b2-%e0%b8%ad-%e0%b8%a0%e0%b8%b9%e0%b9%80%e0%b8%a3%e0%b8%b7%e0%b8%ad-%e0%b8%88-%e0%b9%80%e0%b8%a5%e0%b8%a2_%e0%b8%a7%e0%b8%b1%e0%b8%94%e0%b8%9b%e0%b8%a3%e0%b8%b4%e0%b8%a1%e0%b8%b2%e0%b8%93%e0%b8%99%e0%b9%89%e0%b8%b3%e0%b8%9d%e0%b8%99%e0%b9%84%e0%b8%94%e0%b9%89-30-%e0%b8%a1%e0%b8%a1-%e0%b8%a1%e0%b8%b5%e0%b8%9d%e0%b8%99%e0%b8%95%e0%b8%81%e0%b9%80%e0%b8%a5%e0%b9%87%e0%b8%81%e0%b8%99%e0%b9%89%e0%b8%ad%e0%b8%a2\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.dmr.go.th\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u0e1a.\u0e1b\u0e25\u0e32\u0e1a\u0e48\u0e32 \u0e15.\u0e1b\u0e25\u0e32\u0e1a\u0e48\u0e32 \u0e2d.\u0e20\u0e39\u0e40\u0e23\u0e37\u0e2d \u0e08.\u0e40\u0e25\u0e22_\u0e27\u0e31\u0e14\u0e1b\u0e23\u0e34\u0e21\u0e32\u0e13\u0e19\u0e49\u0e33\u0e1d\u0e19\u0e44\u0e14\u0e49 30 \u0e21\u0e21. \u0e21\u0e35\u0e1d\u0e19\u0e15\u0e01\u0e40\u0e25\u0e47\u0e01\u0e19\u0e49\u0e2d\u0e22\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.dmr.go.th\/#website\",\"url\":\"https:\/\/www.dmr.go.th\/\",\"name\":\"\u0e01\u0e23\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e32\u0e01\u0e23\u0e18\u0e23\u0e13\u0e35\",\"description\":\"\u0e01\u0e23\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e32\u0e01\u0e23\u0e18\u0e23\u0e13\u0e35\",\"publisher\":{\"@id\":\"https:\/\/www.dmr.go.th\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.dmr.go.th\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.dmr.go.th\/#organization\",\"name\":\"\u0e01\u0e23\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e32\u0e01\u0e23\u0e18\u0e23\u0e13\u0e35\",\"url\":\"https:\/\/www.dmr.go.th\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.dmr.go.th\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.dmr.go.th\/wp-content\/uploads\/2022\/08\/\u0e15\u0e23\u0e32\u0e01\u0e23\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e32\u0e01\u0e23\u0e18\u0e23\u0e13\u0e35-2.png\",\"contentUrl\":\"https:\/\/www.dmr.go.th\/wp-content\/uploads\/2022\/08\/\u0e15\u0e23\u0e32\u0e01\u0e23\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e32\u0e01\u0e23\u0e18\u0e23\u0e13\u0e35-2.png\",\"width\":400,\"height\":400,\"caption\":\"\u0e01\u0e23\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e32\u0e01\u0e23\u0e18\u0e23\u0e13\u0e35\"},\"image\":{\"@id\":\"https:\/\/www.dmr.go.th\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.dmr.go.th\/#\/schema\/person\/4f0313ebbcd75dd20a40f88259c955b7\",\"name\":\"\u0e28\u0e39\u0e19\u0e22\u0e4c\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e01\u0e32\u0e23\u0e18\u0e23\u0e13\u0e35\u0e1e\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e20\u0e31\u0e22\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.dmr.go.th\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/4666fbe7f0e846a4db928e3fc4864d73bdd0bbead0c00422a002b3f1a57fcef8?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/4666fbe7f0e846a4db928e3fc4864d73bdd0bbead0c00422a002b3f1a57fcef8?s=96&d=mm&r=g\",\"caption\":\"\u0e28\u0e39\u0e19\u0e22\u0e4c\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e01\u0e32\u0e23\u0e18\u0e23\u0e13\u0e35\u0e1e\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e20\u0e31\u0e22\"},\"url\":\"https:\/\/www.dmr.go.th\/en\/author\/dmr-egd1\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u0e1a.\u0e1b\u0e25\u0e32\u0e1a\u0e48\u0e32 \u0e15.\u0e1b\u0e25\u0e32\u0e1a\u0e48\u0e32 \u0e2d.\u0e20\u0e39\u0e40\u0e23\u0e37\u0e2d \u0e08.\u0e40\u0e25\u0e22_\u0e27\u0e31\u0e14\u0e1b\u0e23\u0e34\u0e21\u0e32\u0e13\u0e19\u0e49\u0e33\u0e1d\u0e19\u0e44\u0e14\u0e49 30 \u0e21\u0e21. \u0e21\u0e35\u0e1d\u0e19\u0e15\u0e01\u0e40\u0e25\u0e47\u0e01\u0e19\u0e49\u0e2d\u0e22 - \u0e01\u0e23\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e32\u0e01\u0e23\u0e18\u0e23\u0e13\u0e35","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.dmr.go.th\/\u0e1a-\u0e1b\u0e25\u0e32\u0e1a\u0e48\u0e32-\u0e15-\u0e1b\u0e25\u0e32\u0e1a\u0e48\u0e32-\u0e2d-\u0e20\u0e39\u0e40\u0e23\u0e37\u0e2d-\u0e08-\u0e40\u0e25\u0e22_\u0e27\u0e31\u0e14\u0e1b\u0e23\u0e34\u0e21\u0e32\u0e13\u0e19\u0e49\u0e33\u0e1d\u0e19\u0e44\u0e14\u0e49-30-\u0e21\u0e21-\u0e21\u0e35\u0e1d\u0e19\u0e15\u0e01\u0e40\u0e25\u0e47\u0e01\u0e19\u0e49\u0e2d\u0e22\/","og_locale":"en_US","og_type":"article","og_title":"\u0e1a.\u0e1b\u0e25\u0e32\u0e1a\u0e48\u0e32 \u0e15.\u0e1b\u0e25\u0e32\u0e1a\u0e48\u0e32 \u0e2d.\u0e20\u0e39\u0e40\u0e23\u0e37\u0e2d \u0e08.\u0e40\u0e25\u0e22_\u0e27\u0e31\u0e14\u0e1b\u0e23\u0e34\u0e21\u0e32\u0e13\u0e19\u0e49\u0e33\u0e1d\u0e19\u0e44\u0e14\u0e49 30 \u0e21\u0e21. \u0e21\u0e35\u0e1d\u0e19\u0e15\u0e01\u0e40\u0e25\u0e47\u0e01\u0e19\u0e49\u0e2d\u0e22 - \u0e01\u0e23\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e32\u0e01\u0e23\u0e18\u0e23\u0e13\u0e35","og_description":"\u0e1a.\u0e1b\u0e25\u0e32\u0e1a\u0e48\u0e32 \u0e15.\u0e1b\u0e25\u0e32\u0e1a\u0e48\u0e32 \u0e2d.\u0e20\u0e39\u0e40\u0e23\u0e37\u0e2d \u0e08.\u0e40\u0e25\u0e22_\u0e27\u0e31\u0e14\u0e1b\u0e23\u0e34\u0e21\u0e32\u0e13\u0e19\u0e49\u0e33\u0e1d\u0e19\u0e44\u0e14\u0e49 30 \u0e21\u0e21. \u0e21\u0e35\u0e1d\u0e19\u0e15\u0e01\u0e40\u0e25\u0e47\u0e01\u0e19\u0e49\u0e2d\u0e22 \u0e17\u0e35\u0e48\u0e21\u0e32 ; \u0e19\u0e32\u0e22\u0e21\u0e19\u0e15\u0e23\u0e35 \u0e28\u0e23\u0e35\u0e1a\u0e38\u0e23\u0e34\u0e19\u0e17\u0e23\u0e4c","og_url":"https:\/\/www.dmr.go.th\/\u0e1a-\u0e1b\u0e25\u0e32\u0e1a\u0e48\u0e32-\u0e15-\u0e1b\u0e25\u0e32\u0e1a\u0e48\u0e32-\u0e2d-\u0e20\u0e39\u0e40\u0e23\u0e37\u0e2d-\u0e08-\u0e40\u0e25\u0e22_\u0e27\u0e31\u0e14\u0e1b\u0e23\u0e34\u0e21\u0e32\u0e13\u0e19\u0e49\u0e33\u0e1d\u0e19\u0e44\u0e14\u0e49-30-\u0e21\u0e21-\u0e21\u0e35\u0e1d\u0e19\u0e15\u0e01\u0e40\u0e25\u0e47\u0e01\u0e19\u0e49\u0e2d\u0e22\/","og_site_name":"\u0e01\u0e23\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e32\u0e01\u0e23\u0e18\u0e23\u0e13\u0e35","article_published_time":"2023-08-21T03:47:18+00:00","article_modified_time":"2023-08-21T03:47:20+00:00","author":"\u0e28\u0e39\u0e19\u0e22\u0e4c\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e01\u0e32\u0e23\u0e18\u0e23\u0e13\u0e35\u0e1e\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e20\u0e31\u0e22","twitter_card":"summary_large_image","twitter_misc":{"Written by":"\u0e28\u0e39\u0e19\u0e22\u0e4c\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e01\u0e32\u0e23\u0e18\u0e23\u0e13\u0e35\u0e1e\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e20\u0e31\u0e22","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.dmr.go.th\/%e0%b8%9a-%e0%b8%9b%e0%b8%a5%e0%b8%b2%e0%b8%9a%e0%b9%88%e0%b8%b2-%e0%b8%95-%e0%b8%9b%e0%b8%a5%e0%b8%b2%e0%b8%9a%e0%b9%88%e0%b8%b2-%e0%b8%ad-%e0%b8%a0%e0%b8%b9%e0%b9%80%e0%b8%a3%e0%b8%b7%e0%b8%ad-%e0%b8%88-%e0%b9%80%e0%b8%a5%e0%b8%a2_%e0%b8%a7%e0%b8%b1%e0%b8%94%e0%b8%9b%e0%b8%a3%e0%b8%b4%e0%b8%a1%e0%b8%b2%e0%b8%93%e0%b8%99%e0%b9%89%e0%b8%b3%e0%b8%9d%e0%b8%99%e0%b9%84%e0%b8%94%e0%b9%89-30-%e0%b8%a1%e0%b8%a1-%e0%b8%a1%e0%b8%b5%e0%b8%9d%e0%b8%99%e0%b8%95%e0%b8%81%e0%b9%80%e0%b8%a5%e0%b9%87%e0%b8%81%e0%b8%99%e0%b9%89%e0%b8%ad%e0%b8%a2\/#article","isPartOf":{"@id":"https:\/\/www.dmr.go.th\/%e0%b8%9a-%e0%b8%9b%e0%b8%a5%e0%b8%b2%e0%b8%9a%e0%b9%88%e0%b8%b2-%e0%b8%95-%e0%b8%9b%e0%b8%a5%e0%b8%b2%e0%b8%9a%e0%b9%88%e0%b8%b2-%e0%b8%ad-%e0%b8%a0%e0%b8%b9%e0%b9%80%e0%b8%a3%e0%b8%b7%e0%b8%ad-%e0%b8%88-%e0%b9%80%e0%b8%a5%e0%b8%a2_%e0%b8%a7%e0%b8%b1%e0%b8%94%e0%b8%9b%e0%b8%a3%e0%b8%b4%e0%b8%a1%e0%b8%b2%e0%b8%93%e0%b8%99%e0%b9%89%e0%b8%b3%e0%b8%9d%e0%b8%99%e0%b9%84%e0%b8%94%e0%b9%89-30-%e0%b8%a1%e0%b8%a1-%e0%b8%a1%e0%b8%b5%e0%b8%9d%e0%b8%99%e0%b8%95%e0%b8%81%e0%b9%80%e0%b8%a5%e0%b9%87%e0%b8%81%e0%b8%99%e0%b9%89%e0%b8%ad%e0%b8%a2\/"},"author":{"name":"\u0e28\u0e39\u0e19\u0e22\u0e4c\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e01\u0e32\u0e23\u0e18\u0e23\u0e13\u0e35\u0e1e\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e20\u0e31\u0e22","@id":"https:\/\/www.dmr.go.th\/#\/schema\/person\/4f0313ebbcd75dd20a40f88259c955b7"},"headline":"\u0e1a.\u0e1b\u0e25\u0e32\u0e1a\u0e48\u0e32 \u0e15.\u0e1b\u0e25\u0e32\u0e1a\u0e48\u0e32 \u0e2d.\u0e20\u0e39\u0e40\u0e23\u0e37\u0e2d \u0e08.\u0e40\u0e25\u0e22_\u0e27\u0e31\u0e14\u0e1b\u0e23\u0e34\u0e21\u0e32\u0e13\u0e19\u0e49\u0e33\u0e1d\u0e19\u0e44\u0e14\u0e49 30 \u0e21\u0e21. \u0e21\u0e35\u0e1d\u0e19\u0e15\u0e01\u0e40\u0e25\u0e47\u0e01\u0e19\u0e49\u0e2d\u0e22","datePublished":"2023-08-21T03:47:18+00:00","dateModified":"2023-08-21T03:47:20+00:00","mainEntityOfPage":{"@id":"https:\/\/www.dmr.go.th\/%e0%b8%9a-%e0%b8%9b%e0%b8%a5%e0%b8%b2%e0%b8%9a%e0%b9%88%e0%b8%b2-%e0%b8%95-%e0%b8%9b%e0%b8%a5%e0%b8%b2%e0%b8%9a%e0%b9%88%e0%b8%b2-%e0%b8%ad-%e0%b8%a0%e0%b8%b9%e0%b9%80%e0%b8%a3%e0%b8%b7%e0%b8%ad-%e0%b8%88-%e0%b9%80%e0%b8%a5%e0%b8%a2_%e0%b8%a7%e0%b8%b1%e0%b8%94%e0%b8%9b%e0%b8%a3%e0%b8%b4%e0%b8%a1%e0%b8%b2%e0%b8%93%e0%b8%99%e0%b9%89%e0%b8%b3%e0%b8%9d%e0%b8%99%e0%b9%84%e0%b8%94%e0%b9%89-30-%e0%b8%a1%e0%b8%a1-%e0%b8%a1%e0%b8%b5%e0%b8%9d%e0%b8%99%e0%b8%95%e0%b8%81%e0%b9%80%e0%b8%a5%e0%b9%87%e0%b8%81%e0%b8%99%e0%b9%89%e0%b8%ad%e0%b8%a2\/"},"wordCount":0,"publisher":{"@id":"https:\/\/www.dmr.go.th\/#organization"},"articleSection":["Uncategorized @th"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/www.dmr.go.th\/%e0%b8%9a-%e0%b8%9b%e0%b8%a5%e0%b8%b2%e0%b8%9a%e0%b9%88%e0%b8%b2-%e0%b8%95-%e0%b8%9b%e0%b8%a5%e0%b8%b2%e0%b8%9a%e0%b9%88%e0%b8%b2-%e0%b8%ad-%e0%b8%a0%e0%b8%b9%e0%b9%80%e0%b8%a3%e0%b8%b7%e0%b8%ad-%e0%b8%88-%e0%b9%80%e0%b8%a5%e0%b8%a2_%e0%b8%a7%e0%b8%b1%e0%b8%94%e0%b8%9b%e0%b8%a3%e0%b8%b4%e0%b8%a1%e0%b8%b2%e0%b8%93%e0%b8%99%e0%b9%89%e0%b8%b3%e0%b8%9d%e0%b8%99%e0%b9%84%e0%b8%94%e0%b9%89-30-%e0%b8%a1%e0%b8%a1-%e0%b8%a1%e0%b8%b5%e0%b8%9d%e0%b8%99%e0%b8%95%e0%b8%81%e0%b9%80%e0%b8%a5%e0%b9%87%e0%b8%81%e0%b8%99%e0%b9%89%e0%b8%ad%e0%b8%a2\/","url":"https:\/\/www.dmr.go.th\/%e0%b8%9a-%e0%b8%9b%e0%b8%a5%e0%b8%b2%e0%b8%9a%e0%b9%88%e0%b8%b2-%e0%b8%95-%e0%b8%9b%e0%b8%a5%e0%b8%b2%e0%b8%9a%e0%b9%88%e0%b8%b2-%e0%b8%ad-%e0%b8%a0%e0%b8%b9%e0%b9%80%e0%b8%a3%e0%b8%b7%e0%b8%ad-%e0%b8%88-%e0%b9%80%e0%b8%a5%e0%b8%a2_%e0%b8%a7%e0%b8%b1%e0%b8%94%e0%b8%9b%e0%b8%a3%e0%b8%b4%e0%b8%a1%e0%b8%b2%e0%b8%93%e0%b8%99%e0%b9%89%e0%b8%b3%e0%b8%9d%e0%b8%99%e0%b9%84%e0%b8%94%e0%b9%89-30-%e0%b8%a1%e0%b8%a1-%e0%b8%a1%e0%b8%b5%e0%b8%9d%e0%b8%99%e0%b8%95%e0%b8%81%e0%b9%80%e0%b8%a5%e0%b9%87%e0%b8%81%e0%b8%99%e0%b9%89%e0%b8%ad%e0%b8%a2\/","name":"\u0e1a.\u0e1b\u0e25\u0e32\u0e1a\u0e48\u0e32 \u0e15.\u0e1b\u0e25\u0e32\u0e1a\u0e48\u0e32 \u0e2d.\u0e20\u0e39\u0e40\u0e23\u0e37\u0e2d \u0e08.\u0e40\u0e25\u0e22_\u0e27\u0e31\u0e14\u0e1b\u0e23\u0e34\u0e21\u0e32\u0e13\u0e19\u0e49\u0e33\u0e1d\u0e19\u0e44\u0e14\u0e49 30 \u0e21\u0e21. \u0e21\u0e35\u0e1d\u0e19\u0e15\u0e01\u0e40\u0e25\u0e47\u0e01\u0e19\u0e49\u0e2d\u0e22 - \u0e01\u0e23\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e32\u0e01\u0e23\u0e18\u0e23\u0e13\u0e35","isPartOf":{"@id":"https:\/\/www.dmr.go.th\/#website"},"datePublished":"2023-08-21T03:47:18+00:00","dateModified":"2023-08-21T03:47:20+00:00","breadcrumb":{"@id":"https:\/\/www.dmr.go.th\/%e0%b8%9a-%e0%b8%9b%e0%b8%a5%e0%b8%b2%e0%b8%9a%e0%b9%88%e0%b8%b2-%e0%b8%95-%e0%b8%9b%e0%b8%a5%e0%b8%b2%e0%b8%9a%e0%b9%88%e0%b8%b2-%e0%b8%ad-%e0%b8%a0%e0%b8%b9%e0%b9%80%e0%b8%a3%e0%b8%b7%e0%b8%ad-%e0%b8%88-%e0%b9%80%e0%b8%a5%e0%b8%a2_%e0%b8%a7%e0%b8%b1%e0%b8%94%e0%b8%9b%e0%b8%a3%e0%b8%b4%e0%b8%a1%e0%b8%b2%e0%b8%93%e0%b8%99%e0%b9%89%e0%b8%b3%e0%b8%9d%e0%b8%99%e0%b9%84%e0%b8%94%e0%b9%89-30-%e0%b8%a1%e0%b8%a1-%e0%b8%a1%e0%b8%b5%e0%b8%9d%e0%b8%99%e0%b8%95%e0%b8%81%e0%b9%80%e0%b8%a5%e0%b9%87%e0%b8%81%e0%b8%99%e0%b9%89%e0%b8%ad%e0%b8%a2\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.dmr.go.th\/%e0%b8%9a-%e0%b8%9b%e0%b8%a5%e0%b8%b2%e0%b8%9a%e0%b9%88%e0%b8%b2-%e0%b8%95-%e0%b8%9b%e0%b8%a5%e0%b8%b2%e0%b8%9a%e0%b9%88%e0%b8%b2-%e0%b8%ad-%e0%b8%a0%e0%b8%b9%e0%b9%80%e0%b8%a3%e0%b8%b7%e0%b8%ad-%e0%b8%88-%e0%b9%80%e0%b8%a5%e0%b8%a2_%e0%b8%a7%e0%b8%b1%e0%b8%94%e0%b8%9b%e0%b8%a3%e0%b8%b4%e0%b8%a1%e0%b8%b2%e0%b8%93%e0%b8%99%e0%b9%89%e0%b8%b3%e0%b8%9d%e0%b8%99%e0%b9%84%e0%b8%94%e0%b9%89-30-%e0%b8%a1%e0%b8%a1-%e0%b8%a1%e0%b8%b5%e0%b8%9d%e0%b8%99%e0%b8%95%e0%b8%81%e0%b9%80%e0%b8%a5%e0%b9%87%e0%b8%81%e0%b8%99%e0%b9%89%e0%b8%ad%e0%b8%a2\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.dmr.go.th\/%e0%b8%9a-%e0%b8%9b%e0%b8%a5%e0%b8%b2%e0%b8%9a%e0%b9%88%e0%b8%b2-%e0%b8%95-%e0%b8%9b%e0%b8%a5%e0%b8%b2%e0%b8%9a%e0%b9%88%e0%b8%b2-%e0%b8%ad-%e0%b8%a0%e0%b8%b9%e0%b9%80%e0%b8%a3%e0%b8%b7%e0%b8%ad-%e0%b8%88-%e0%b9%80%e0%b8%a5%e0%b8%a2_%e0%b8%a7%e0%b8%b1%e0%b8%94%e0%b8%9b%e0%b8%a3%e0%b8%b4%e0%b8%a1%e0%b8%b2%e0%b8%93%e0%b8%99%e0%b9%89%e0%b8%b3%e0%b8%9d%e0%b8%99%e0%b9%84%e0%b8%94%e0%b9%89-30-%e0%b8%a1%e0%b8%a1-%e0%b8%a1%e0%b8%b5%e0%b8%9d%e0%b8%99%e0%b8%95%e0%b8%81%e0%b9%80%e0%b8%a5%e0%b9%87%e0%b8%81%e0%b8%99%e0%b9%89%e0%b8%ad%e0%b8%a2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.dmr.go.th\/"},{"@type":"ListItem","position":2,"name":"\u0e1a.\u0e1b\u0e25\u0e32\u0e1a\u0e48\u0e32 \u0e15.\u0e1b\u0e25\u0e32\u0e1a\u0e48\u0e32 \u0e2d.\u0e20\u0e39\u0e40\u0e23\u0e37\u0e2d \u0e08.\u0e40\u0e25\u0e22_\u0e27\u0e31\u0e14\u0e1b\u0e23\u0e34\u0e21\u0e32\u0e13\u0e19\u0e49\u0e33\u0e1d\u0e19\u0e44\u0e14\u0e49 30 \u0e21\u0e21. \u0e21\u0e35\u0e1d\u0e19\u0e15\u0e01\u0e40\u0e25\u0e47\u0e01\u0e19\u0e49\u0e2d\u0e22"}]},{"@type":"WebSite","@id":"https:\/\/www.dmr.go.th\/#website","url":"https:\/\/www.dmr.go.th\/","name":"\u0e01\u0e23\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e32\u0e01\u0e23\u0e18\u0e23\u0e13\u0e35","description":"\u0e01\u0e23\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e32\u0e01\u0e23\u0e18\u0e23\u0e13\u0e35","publisher":{"@id":"https:\/\/www.dmr.go.th\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.dmr.go.th\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.dmr.go.th\/#organization","name":"\u0e01\u0e23\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e32\u0e01\u0e23\u0e18\u0e23\u0e13\u0e35","url":"https:\/\/www.dmr.go.th\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.dmr.go.th\/#\/schema\/logo\/image\/","url":"https:\/\/www.dmr.go.th\/wp-content\/uploads\/2022\/08\/\u0e15\u0e23\u0e32\u0e01\u0e23\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e32\u0e01\u0e23\u0e18\u0e23\u0e13\u0e35-2.png","contentUrl":"https:\/\/www.dmr.go.th\/wp-content\/uploads\/2022\/08\/\u0e15\u0e23\u0e32\u0e01\u0e23\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e32\u0e01\u0e23\u0e18\u0e23\u0e13\u0e35-2.png","width":400,"height":400,"caption":"\u0e01\u0e23\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e32\u0e01\u0e23\u0e18\u0e23\u0e13\u0e35"},"image":{"@id":"https:\/\/www.dmr.go.th\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.dmr.go.th\/#\/schema\/person\/4f0313ebbcd75dd20a40f88259c955b7","name":"\u0e28\u0e39\u0e19\u0e22\u0e4c\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e01\u0e32\u0e23\u0e18\u0e23\u0e13\u0e35\u0e1e\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e20\u0e31\u0e22","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.dmr.go.th\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/4666fbe7f0e846a4db928e3fc4864d73bdd0bbead0c00422a002b3f1a57fcef8?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4666fbe7f0e846a4db928e3fc4864d73bdd0bbead0c00422a002b3f1a57fcef8?s=96&d=mm&r=g","caption":"\u0e28\u0e39\u0e19\u0e22\u0e4c\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e01\u0e32\u0e23\u0e18\u0e23\u0e13\u0e35\u0e1e\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e20\u0e31\u0e22"},"url":"https:\/\/www.dmr.go.th\/en\/author\/dmr-egd1\/"}]}},"_links":{"self":[{"href":"https:\/\/www.dmr.go.th\/en\/wp-json\/wp\/v2\/posts\/215846","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.dmr.go.th\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.dmr.go.th\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.dmr.go.th\/en\/wp-json\/wp\/v2\/users\/31"}],"replies":[{"embeddable":true,"href":"https:\/\/www.dmr.go.th\/en\/wp-json\/wp\/v2\/comments?post=215846"}],"version-history":[{"count":0,"href":"https:\/\/www.dmr.go.th\/en\/wp-json\/wp\/v2\/posts\/215846\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.dmr.go.th\/en\/wp-json\/wp\/v2\/media?parent=215846"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.dmr.go.th\/en\/wp-json\/wp\/v2\/categories?post=215846"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.dmr.go.th\/en\/wp-json\/wp\/v2\/tags?post=215846"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}